{"id":101825,"date":"2026-09-01T10:37:46","date_gmt":"2026-09-01T08:37:46","guid":{"rendered":"https:\/\/www.univda.it\/?post_type=amm-trasparente&#038;p=101825"},"modified":"2026-09-01T10:37:46","modified_gmt":"2026-09-01T08:37:46","slug":"provvedimenti-di-affidamento-anno-2023","status":"publish","type":"amm-trasparente","link":"https:\/\/www.univda.it\/en\/amm-trasparente\/provvedimenti-di-affidamento-anno-2023\/","title":{"rendered":"Provvedimenti di affidamento anno 2023"},"content":{"rendered":"<div class='table-responsive'><table id=\"tablePreview\" class=\"table table-bordered\"><thead>\n                <tr>\n                <th>Data pubblicazione<\/th>\n                <th>Data protocollo<\/th>\n                <th>Repertorio numero<\/th>\n                <th>Oggetto<\/th>\n                <th>File allegati<\/th>\n                <\/tr>\n            <\/thead><tbody><tr><td>06\/10\/2023<\/td><td>05\/10\/2023<\/td><td>2023-UNVACLE-0016094<\/td><td>Decreto del Direttore GREEN - Affidamento del servizio di coffee break e pranzo nell\u2019ambito dell\u2019evento dal titolo \u201cApproccio al concetto di salute planetaria: il potenziale delle Foreste Valdostane\u201d. Autorizzazione alla spesa. CIG Z803C99A98.<\/td><td><ul><li><a href=\"\/download-titulus?id=J8WLonI3KLpMgAk%2FRthIyA%3D%3D_001121954-FS_FILES-91ff72b4-c311-4e0b-93cd-1dc4bbe83b0a%5B1%5D.pdf\" target=\"_blank\">Decreto_affidamento servizio.pdf<a><\/li><li><a href=\"\/download-titulus?id=Cq6RY%2FpoOaAA9zKLGQDEwQ%3D%3D_001121955-FS_FILES-bc54d1ea-87a8-4afb-bd50-7e5ce6c56900%5B1%5D.pdf\" target=\"_blank\">all. decreto - affidamento servizio - scrittura contabile.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/02\/2023<\/td><td>24\/02\/2023<\/td><td>2023-UNVACLE-0003748<\/td><td>Decreto del Direttore del Dipartimento di Scienze economiche e politiche. Affidamento alla ditta G. Giappichelli Editore srl di Torino, P. IVA 02874520014, della pubblicazione del volume contenente gli Atti del Convegno \u201cSapere e pensiero critico. Per un\u2019idea di universit\u00e0\u201d, tenutosi ad Aosta il 3 novembre 2022, a cura del prof. Roberto Calvo - codice progetto DOTBAS2023DIP.SEP - CIG Z4439A61E9.<\/td><td><ul><li><a href=\"\/download-titulus?id=H6YrJ32LnlPQhSziZU9daA%3D%3D_001075593-FS_FILES-da149c4c-7c45-434b-b21a-3740ce0de86e%5B1%5D.pdf\" target=\"_blank\">Decreto_pubblic_Calvo_Atti_Sapere.pdf<a><\/li><li><a href=\"\/download-titulus?id=2yaUkHadOx9vQmY%2BQauZLA%3D%3D_001075594-FS_FILES-fa9b602b-9f23-4e01-89f0-44c86906c23c%5B1%5D.pdf\" target=\"_blank\">Scrittura_COAN_350.pdf<a><\/li><li><a href=\"\/download-titulus?id=6oWb53YIyZOhm8RA%2BYwyxw%3D%3D_001074769-FS_FILES-81dd9741-fcf7-47eb-9a85-446e84c584d1%5B2%5D.pdf\" target=\"_blank\">Preventivo_Giappichelli_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>09\/03\/2023<\/td><td>08\/03\/2023<\/td><td>2023-UNVACLE-0004526<\/td><td>Decreto del Direttore del Dipartimento di Scienze economiche e politiche - Affidamento alla ditta americana Qualtrics Llc, Federal Tax Id 45-4964116, del rinnovo della licenza del software \u201cQualtrics\u201d necessario alla realizzazione di indagini on-line con finalit\u00e0 di ricerca \u2013 periodo 12 marzo 2023\/11 marzo 2024 (CIG : Z143A47E28).<\/td><td><ul><li><a href=\"\/download-titulus?id=ewOUvuBb2FfjmIzPaQXL6A%3D%3D_001078556-FS_FILES-3ff52d5a-74f6-4705-8c69-9c923c41ea6b%5B1%5D.pdf\" target=\"_blank\">Decreto Dir SEP - Rinnovo Qualtrics 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=hwDfY6zJRE5yXrV%2BVpAARg%3D%3D_001078557-FS_FILES-82b922bb-4608-49d7-af6b-24c872a76c18%5B1%5D.pdf\" target=\"_blank\">Quote-198989.pdf<a><\/li><li><a href=\"\/download-titulus?id=GbuLJMP9hoFhrwiVc0KIVg%3D%3D_001078558-FS_FILES-bccfd7de-d4b7-4687-a134-62e81a9205b0%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-03-08T161105.296.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/11\/2023<\/td><td>24\/11\/2023<\/td><td>2023-UNVACLE-0019185<\/td><td>Decreto del Direttore del Dipartimento di Scienze economiche e politiche - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Edizioni Scientifiche Italiane E.S.I. S.p.A., P.IVA 00289510638, della pubblicazione del volume dal titolo \u201cStudi in onore di Ermanno Vitale\u201d a cura del Prof. Roberto Calvo \u2013 Codice progetto DOTBAS2023DIP.SEP \u2013 CIG Z503D0E14B.<\/td><td><ul><li><a href=\"\/download-titulus?id=jCv7sEGZAAIZJZNlHHnbZw%3D%3D_001135121-FS_FILES-8be8ea87-1b20-47d5-954c-0bb1fa3f6130%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2F9T2JEuCExFDJdbdJyEX3w%3D%3D_001135122-FS_FILES-a7b880a9-6e83-4137-a715-40cba2f85bae%5B1%5D.pdf\" target=\"_blank\">Preventivo Edizioni Scientifiche Italiane.pdf<a><\/li><li><a href=\"\/download-titulus?id=0bQNXvAUJlPH1iFj8d9IKw%3D%3D_001135120-FS_FILES-c266e924-62e1-4a98-994a-21e79ea17284%5B1%5D.pdf\" target=\"_blank\">Decreto - Calvo.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>16\/01\/2023<\/td><td>13\/01\/2023<\/td><td>2023-UNVACLE-0000651<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Partecipazione alle spese (APC - article processing charges) per la pubblicazione dell\u2019articolo \u201cCan dissociation mediate the relationship between emotion dysregulation and intelligence? An empirical study involving adolescents with and without complex trauma histories\u201d, scritto dai docenti Laura Ferro e Stefania Cristofanelli, sulla rivista Open Access \u201c IJERPH \u2013 MDPI (rivista di eccellenza in fascia Q1)\u201d, pubblicata dall\u2019editore MDPI (Multidisciplinary Digital Publishing Institute) AG di Basilea (Svizzera). Codice progetto FER20PRA.SHS - referente scientifico Professoressa Laura Ferro - CIG ZC1397D255.<\/td><td><ul><li><a href=\"\/download-titulus?id=4FM1VmL8Te%2Fe%2BJQ%2Fpv%2F8cA%3D%3D_001064160-FS_FILES-1e6821db-b295-4da5-89f0-6bdbf0296f8e%5B1%5D.pdf\" target=\"_blank\">Decreto_articolo_OA_Ferro-Cristofanelli.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>18\/01\/2023<\/td><td>17\/01\/2023<\/td><td>2023-UNVACLE-0000824<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Pubblicazione dell\u2019articolo \u201cSelf-efficacy, motivation and academic satisfaction: The moderating role of friendship at the university\u201d scritto dai professori Elena Cattelino, Stefano Cacciamani, Vittore Perrucci, Mara Morelli, Roberto Baiocco e Antonio Chirumbolo, sulla rivista Open Access \u201cPsicothema\u201d, pubblicata dal Colegio Oficial de Psicologos del Principado de Asturias c\/o Ildefonso Sanchez del Rio, 4 - 1\u00ba B 33001 Oviedo \u2013 Asturias \u2013 C.I.F. Q3300296E, - CIG Z19397DAFA. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=gRM%2BM2JBVBlgZx13Z6Wm%2Bw%3D%3D_001064857-FS_FILES-6faecf17-e24c-403d-9942-21bddd0c413f%5B1%5D.pdf\" target=\"_blank\">Decreto_articolo_Psicothema.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>28\/02\/2023<\/td><td>27\/02\/2023<\/td><td>2023-UNVACLE-0003838<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento alla ditta Editrice Morcelliana Srl di Brescia, P. IVA 00290950179, della pubblicazione del volume \u201cMedici per l\u2019educazione: contributi per una pedagogia dell\u2019infanzia dagli epigoni montessoriani ai giorni nostri\u201d, del professore Andrea Bobbio - codice progetto PRIN17.BOBBIO.SHS- CIG Z5939AA16B, CUP B68D19000230001.<\/td><td><ul><li><a href=\"\/download-titulus?id=nHIEB%2FschhuzCquwxShseA%3D%3D_001075835-FS_FILES-1ea92f7a-ab8f-45da-a6c7-559b43faa27c%5B1%5D.pdf\" target=\"_blank\">Decreto_pubblicaz_Bobbio.pdf<a><\/li><li><a href=\"\/download-titulus?id=w4pN65EcIQqTE%2FNfcMmC7w%3D%3D_001075836-FS_FILES-36f37f66-0077-4558-89f5-a0c78d46e2cb%5B1%5D.pdf\" target=\"_blank\">Scrittura_COAN_348.pdf<a><\/li><li><a href=\"\/download-titulus?id=7t5A7gJDxtqvp8WmsEKi6Q%3D%3D_001074773-FS_FILES-71f61a43-d1a2-4dca-a76c-3da8448c9d6f%5B3%5D.pdf\" target=\"_blank\">Preventivo_Morcelliana_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>24\/03\/2023<\/td><td>23\/03\/2023<\/td><td>2023-UNVACLE-0005464<\/td><td>Decreto del Direttore del Dipartimento di Scienze Umane e Sociali - Approvazione dello svolgimento di una visita didattica presso l\u2019Universit\u00e9 Savoie Mont Blanc in data 4 aprile 2023. Affidamento del servizio di trasporto per i partecipanti. CIG n. ZA73A476B7<\/td><td><ul><li><a href=\"\/download-titulus?id=%2BLMOpc7JWbttA4Fhi3H2iw%3D%3D_001081624-FS_FILES-4c1a1516-fb42-42f7-b6e4-44169d7e2157%5B1%5D.pdf\" target=\"_blank\">Decreto SHS  - Visite du site.pdf<a><\/li><li><a href=\"\/download-titulus?id=Fns89dis0Bv1E0uDqR1K2g%3D%3D_001081625-FS_FILES-2f4e069f-cd1a-41fe-8a69-b08bebebf493%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>20\/04\/2023<\/td><td>19\/04\/2023<\/td><td>2023-UNVACLE-0006857<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento diretto alla ditta Way2Global S.r.l. S.b., P.IVA 10013290969, del servizio di traduzione e revisione linguistica altamente specializzata di testi di Ecopsicologia e di Ecologia Affettiva, finalizzato allo svolgimento delle attivit\u00e0 inerenti al progetto di ricerca \u201cBiophilia\u201d, il cui Responsabile scientifico \u00e8 il Prof. Giuseppe Barbiero - CIG Z1E3A6B59A.<\/td><td><ul><li><a href=\"\/download-titulus?id=g8L3NGhXiv5P%2BCXumhoiXw%3D%3D_001086746-FS_FILES-073486ca-8cea-4579-bb24-0824b6140d6f%5B1%5D.pdf\" target=\"_blank\">DDSHS_Servizio traduzioni.pdf<a><\/li><li><a href=\"\/download-titulus?id=633eZfyFgttWD39psHWLJg%3D%3D_001086747-FS_FILES-3b5eb9e0-d340-4272-af26-ebd6fa4477ab%5B1%5D.pdf\" target=\"_blank\">COAN - modifica scrittura 906 con nome ditta e importo per affidamento.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>28\/04\/2023<\/td><td>27\/04\/2023<\/td><td>2023-UNVACLE-0007177<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento, tramite Mercato Elettronico della Pubblica Amministrazione (Me.P.A.) con Ordinativo Esecuzione Immediata, alla ditta INFOGRAF SAS di Thomas Anezakis, Via Duca della Verdura n. 23 \u2013 90143 Palermo \u2013 P. Iva 03983130828, della fornitura di un Notebook Zenbook Pro 14 Duo OLED UX8402, nell\u2019ambito del Progetto di Rilevante Interesse Nazionale 2017 (PRIN 2017), dal titolo \u201cCLIMALP \u2013 Corpus Linguistics Meets Alpine Heritage: documenting and safeguarding linguistic minorities in the Alps\u201d approvato nell\u2019anno 2019, di cui \u00e8 Referente Scientifico il Prof. Gianmario Raimondi \u2013 CUP B68D19001590001 (codice progetto PRIN17.RAIMONDI.SHS).  \u2013 CIG ZE73ACE745<\/td><td><ul><li><a href=\"\/download-titulus?id=mb%2FB4BuyuCEl1bv%2Bojgx4Q%3D%3D_001087952-FS_FILES-056bf6a4-50d1-450f-b898-49db7e26bdb5%5B1%5D.pdf\" target=\"_blank\">Decreto SHS Notebook - Infograf.pdf<a><\/li><li><a href=\"\/download-titulus?id=nnAk%2BqML6tQoLDZIrSIZkA%3D%3D_001087954-FS_FILES-339b8901-c60f-4401-b3fd-1506cdd37243%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - Infograf sas.pdf<a><\/li><li><a href=\"\/download-titulus?id=n29wsnEstQqHU0FkqYX8kA%3D%3D_001087942-FS_FILES-8f85f96c-b288-438d-a913-4360fa846f5a%5B2%5D.pdf\" target=\"_blank\">Bozza Ordinativo esec. immediata n. 7233501 - omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>12\/05\/2023<\/td><td>11\/05\/2023<\/td><td>2023-UNVACLE-0008076<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento, tramite Mercato Elettronico della Pubblica Amministrazione (Me.P.A.) con Ordinativo Esecuzione Immediata, alla ditta Ultrapromedia s.r.l. con sede in Via Flaminia 106 -00196 Roma \u2013 C.F. 10324241008 della fornitura di attrezzatura nell\u2019ambito del Progetto di Ricerca di Ateneo (PRA) dal titolo \u201cClassi sotto il cielo. Progetto di Ricerca-Formazione per la costituzione della Rete regionale delle scuole all'aperto\u201d, di cui \u00e8 Referente Scientifico il Dott. Fabrizio Bertolino (codice progetto BER20PRA.SHS). C.I.G. Z403AF7941.<\/td><td><ul><li><a href=\"\/download-titulus?id=Yyjs7JaI%2FUZNOTc7Yxg1AA%3D%3D_001091192-FS_FILES-495edd43-1bea-4dbe-8142-be2472bae28b%5B1%5D.pdf\" target=\"_blank\">Decreto SHS materiale ULTRAPROMEDIA.pdf<a><\/li><li><a href=\"\/download-titulus?id=qCXGX5RNv7UWGYLUMVLbKw%3D%3D_001091193-FS_FILES-ef51d2ff-ddf4-4d4e-b26f-bc4dd07f0b8d%5B1%5D.pdf\" target=\"_blank\">Ordinativo n. 7254237_Ultrapromedia - Omissis.pdf<a><\/li><li><a href=\"\/download-titulus?id=6DmlZJLYSBFPFElscJ5ykQ%3D%3D_001091194-FS_FILES-77dce1bd-736d-4f56-8303-e407cd033552%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-05-11T155359.954.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>12\/05\/2023<\/td><td>11\/05\/2023<\/td><td>2023-UNVACLE-0008077<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento, tramite Mercato Elettronico della Pubblica Amministrazione (Me.P.A.) con Ordinativo Esecuzione Immediata, alla ditta Campustore s.r.l. con sede legale in Via Villaggio Europa 3 \u2013 36061 Bassano del Grappa (VI) \u2013 P.IVA 02409740244 della fornitura di attrezzatura nell\u2019ambito del Progetto di Ricerca di Ateneo (PRA) dal titolo \u201cClassi sotto il cielo. Progetto di Ricerca-Formazione per la costituzione della Rete regionale delle scuole all'aperto\u201d, di cui \u00e8 Referente Scientifico il Dott. Fabrizio Bertolino (codice progetto BER20PRA.SHS). C.I.G. ZC13AF78BA.<\/td><td><ul><li><a href=\"\/download-titulus?id=rJphpPuBKIVltOs1xKrrWw%3D%3D_001091195-FS_FILES-2c7d57c3-c01c-48f7-a5c5-18e25ee41665%5B1%5D.pdf\" target=\"_blank\">Decreto SHS materiale CAMPUSTORE.pdf<a><\/li><li><a href=\"\/download-titulus?id=6zIWQXS89Bx9mgKcsGihjw%3D%3D_001091196-FS_FILES-401e4b14-af56-4a0e-8be6-39d62b0d0f42%5B1%5D.pdf\" target=\"_blank\">Ordinativo n. 7254287_Campustore - Omissis.pdf<a><\/li><li><a href=\"\/download-titulus?id=eDC8tm17tVAPznVYIDATCQ%3D%3D_001091197-FS_FILES-9d458e18-0d65-4e36-aad7-edccdd214376%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-05-11T161944.665.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>15\/05\/2023<\/td><td>12\/05\/2023<\/td><td>2023-UNVACLE-0008142<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento del servizio di pernottamento dei partecipanti all\u2019attivit\u00e0 didattica \u201cstage\u201d prevista nell\u2019ambito del Corso di laurea magistrale in Scienze della formazione primaria dal 22 al 26 maggio 2023. CIG n. Z5F3AEE3C1.<\/td><td><ul><li><a href=\"\/download-titulus?id=OC%2BLiGpRaF1vMp0X6dLxLA%3D%3D_001091420-FS_FILES-0377413d-94e7-4412-a0b1-90020607c041%5B1%5D.pdf\" target=\"_blank\">Decreto SHS - Stage SFP Albergo.pdf<a><\/li><li><a href=\"\/download-titulus?id=OEu97x8A%2BlVHOcOaWqJ7VQ%3D%3D_001091421-FS_FILES-ef66eed8-262a-4616-803a-a7d831bf4b9f%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>15\/05\/2023<\/td><td>12\/05\/2023<\/td><td>2023-UNVACLE-0008143<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento del servizio di trasporto per i partecipanti all\u2019attivit\u00e0 didattica \u201cstage\u201d prevista nell\u2019ambito del Corso di laurea magistrale in Scienze della formazione primaria dal 22 al 26 maggio 2023. CIG n. ZD03AEDDEF.<\/td><td><ul><li><a href=\"\/download-titulus?id=R2LdFcuTbuP%2BeCVd1fwZ1Q%3D%3D_001091422-FS_FILES-dcd0dd3c-4e0f-4d9b-95c8-ed7bc0fb1f36%5B1%5D.pdf\" target=\"_blank\">Decreto SHS - Stage SFP trasporto.pdf<a><\/li><li><a href=\"\/download-titulus?id=s1ylP9Sv8ldVW2M1crQ0%2Fg%3D%3D_001091423-FS_FILES-88d70820-eecd-47b4-affe-4f2a5568e61e%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>22\/05\/2023<\/td><td>19\/05\/2023<\/td><td>2023-UNVACLE-0008591<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento alla ditta Borgione s.r.l. di San Maurizio Canavese (TO), P.IVA 02027040019, della fornitura di materiale didattico, funzionale all\u2019attivit\u00e0 di ricerca all\u2019interno del progetto PRIN2017 denominato \u201cMaria Montessori form the past to the present. Reception and implementation of her educational method in Italy on the 150th anniversary of her birth.\u201d di cui \u00e8 referente scientifico il Professore Andrea Bobbio - codice progetto PRIN17.BOBBIO.SHS- CIG ZBC3AF7A52. CUP B68D19000230001.<\/td><td><ul><li><a href=\"\/download-titulus?id=TyLndcVdiDAw1pSf1SKhwA%3D%3D_001093186-FS_FILES-f0d20892-ea8b-42b2-a720-825456d8ccbd%5B1%5D.pdf\" target=\"_blank\">Decreto SHS_materiale didattico.pdf<a><\/li><li><a href=\"\/download-titulus?id=dHXt5knETqXelIsXmkSVIQ%3D%3D_001093187-FS_FILES-dc8413fd-c8dd-4b93-b287-5a4e7fa5fc0e%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-05-19T153814.321.pdf<a><\/li><li><a href=\"\/download-titulus?id=TU4Pqc4SktR%2B6V4bUaU2RA%3D%3D_001093188-FS_FILES-be514538-d0e6-470f-a053-19081515fe69%5B1%5D.pdf\" target=\"_blank\">Preventivo Borgione.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>23\/05\/2023<\/td><td>22\/05\/2023<\/td><td>2023-UNVACLE-0008666<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento, tramite Mercato Elettronico della Pubblica Amministrazione (Me.P.A.) con Ordinativo Esecuzione Immediata, alla ditta DESIG ITALIA s.r.l di Salerno, P.IVA 05174780659, della fornitura di materiale didattico, funzionale all\u2019attivit\u00e0 di ricerca all\u2019interno del progetto PRIN2017 denominato \u201cMaria Montessori form the past to the present. Reception and implementation of her educational method in Italy on the 150th anniversary of her birth.\u201d di cui \u00e8 referente scientifico il Professore Andrea Bobbio - codice progetto PRIN17.BOBBIO.SHS- CIG : Z683AF7845. CUP B68D19000230001.<\/td><td><ul><li><a href=\"\/download-titulus?id=TQl6Eu2P9Njs5tCNcYB1Pw%3D%3D_001093412-FS_FILES-b152e017-f78b-43b1-8b78-29ce60333b6d%5B1%5D.pdf\" target=\"_blank\">Decreto SHS materiale DESIG.pdf<a><\/li><li><a href=\"\/download-titulus?id=fXs8CQ41rssP8lhgEAHOOg%3D%3D_001093413-FS_FILES-16052d53-569f-44b4-bb46-b48640140561%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7272978 - DESIG - Omissis.pdf<a><\/li><li><a href=\"\/download-titulus?id=lghao8B1i%2FNpiWY9jtJ%2Fxw%3D%3D_001093414-FS_FILES-303e8a0d-4a79-4354-bcd3-aa1d33e2c0c2%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-05-22T120327.040.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>25\/05\/2023<\/td><td>24\/05\/2023<\/td><td>2023-UNVACLE-0008928<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Affidamento, tramite Mercato Elettronico della Pubblica Amministrazione (Me.P.A.) con Ordinativo Esecuzione Immediata, alla ditta Adpartners s.r.l. con sede legale in Via Altea 12\/a\u2013 30015 Chioggia (VE) - P.IVA 03340710270 della fornitura di n.1 Powerbank, richiesto dal Prof. Carlo Maria Bajetta, nell\u2019ambito delle dotazioni di base (codice progetto DOTBAS2023.SHS). C.I.G. Z8C3B3D005.<\/td><td><ul><li><a href=\"\/download-titulus?id=%2Fq7nFcOGhSr5qiFqtNlcIQ%3D%3D_001094297-FS_FILES-18fb11ff-b9e7-4776-83b6-be2c409f8eb4%5B1%5D.pdf\" target=\"_blank\">Decreto SHS Powerbank.pdf<a><\/li><li><a href=\"\/download-titulus?id=wCu%2FqNVlFtG34laoNlrMug%3D%3D_001094298-FS_FILES-87d23805-d427-4704-877b-f0793242c697%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-05-24T124630.574.pdf<a><\/li><li><a href=\"\/download-titulus?id=G96GBqQaAU3V6fSgdxyjmQ%3D%3D_001094299-FS_FILES-8f78d161-8dc4-4d7c-9fbd-924d4197b15d%5B1%5D.pdf\" target=\"_blank\">Ordinativo esecuzione immediata - ADPartners_Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>09\/06\/2023<\/td><td>08\/06\/2023<\/td><td>2023-UNVACLE-0009864<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Acquisto di albi illustrati nell\u2019ambito del Corso di perfezionamento \u201cAlbi illustrati e natura, tra immagini e immaginari. Metodologie e strumenti per la promozione della lettura all\u2019aperto\u201d, anno accademico. 2022\/2023. CIG Z79386EABF (monografie pubblicate da editori italiani), CIG Z9C386EB5B (monografie pubblicate da editori stranieri)<\/td><td><ul><li><a href=\"\/download-titulus?id=arhbPBDijWMwJ8HjdLdGng%3D%3D_001097322-FS_FILES-2049c9cc-7f9a-48fb-9cac-f2a6b7e14409%5B1%5D.pdf\" target=\"_blank\">Decreto SHS - Albi e Natura - Libri.pdf<a><\/li><li><a href=\"\/download-titulus?id=9luie21oYRzqTkxcYaetOg%3D%3D_001097323-FS_FILES-6c93bfcd-7ce1-455b-87c9-6e4dc0826584%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN EBSCO.pdf<a><\/li><li><a href=\"\/download-titulus?id=dGUV%2BuoREgYJYrB%2FgbqTAg%3D%3D_001097324-FS_FILES-c4622d69-9d06-48cf-81e0-0a799216b76c%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN terminal.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>24\/07\/2023<\/td><td>21\/07\/2023<\/td><td>2023-UNVACLE-0012333<\/td><td>Decreto del Direttore di Dipartimento di Scienze umane e sociali - Affidamento alla ditta FrancoAngeli srl. di Milano, P. Iva 04949880159, della pubblicazione del volume contenente gli Atti del Convegno \u201cIn viaggio. Esperienze e racconti dall\u2019Europa alla Valle d\u2019Aosta\u201d tenutosi ad Aosta il 12 e 13 dicembre 2022, a cura delle prof.sse Luisa Giacoma, Raffaella Odicino e Anna Maria Pioletti \u2013 codice progetto BAL20PRA.SHS \u2013 CIG ZCD3BDD7BD<\/td><td><ul><li><a href=\"\/download-titulus?id=eFHUUEgh8rk0xJMk7CUGyg%3D%3D_001106935-FS_FILES-3a46817f-65a6-4a6b-9486-ea187728cc81%5B1%5D.pdf\" target=\"_blank\">Decreto - Pubblicazione volume In viaggio. Esperienze e racconti dall'Europa alla Valle d'Aosta.pdf<a><\/li><li><a href=\"\/download-titulus?id=C0tIb2DvJVOAJuWLp%2FbFKg%3D%3D_001106936-FS_FILES-d116f93e-aad3-461a-b44d-76984feff449%5B1%5D.pdf\" target=\"_blank\">Scrittura contabile.pdf<a><\/li><li><a href=\"\/download-titulus?id=P8%2FEI65SnoXXINtQnChP%2Fg%3D%3D_001106660-FS_FILES-4e9378b0-4fc5-480b-a052-57ad5577aef7%5B3%5D.pdf\" target=\"_blank\">Preventivo_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>01\/08\/2023<\/td><td>31\/07\/2023<\/td><td>2023-UNVACLE-0012649<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Pubblicazione di un articolo relativo ad alcuni risultati della ricerca nell\u2019ambito del progetto denominato \u201cSuccesso accademico e didattica di qualit\u00e0: fattori psicologici, pedagogico-didattici e organizzativi\u201d \u2013 codice: TES20PRA.SHS - sulla rivista Open Access \u201cFrontiers in Education\u201d da parte della Ditta Frontiers Media sa con sede in 1005 Lausanne (Switzerland) \u2013 Avenue du Tribunal Federal 34 - CHE-114.168.540 TVA - CIG Z613C006E9. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=IOvwWbtNP4OCLIbYfLn6Yg%3D%3D_001108346-FS_FILES-c95c5ba4-5dfd-4331-a00f-e13853478f0f%5B1%5D.pdf\" target=\"_blank\">Decreto_articolo_Frontiers.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>05\/09\/2023<\/td><td>04\/09\/2023<\/td><td>2023-UNVACLE-0014372<\/td><td>Decreto del Direttore di Dipartimento di Scienze umane e sociali - Affidamento diretto alla ditta Edizioni Centro Studi Erickson S.p.A, P.IVA 01063120222, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, del servizio di erogazione di n. 3 corsi di formazione in modalit\u00e0 telematica per due docenti dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, nell\u2019ambito del progetto di ricerca di Ateneo \u201cOltre il lockdown - Spazi di ricerca e di intervento per il benessere dei singoli, dei gruppi e della comunit\u00e0\u201d di cui \u00e8 responsabile scientifico la Prof.ssa Laura Ferro (codice: FER20PRA.SHS). CIG ZA03C4AF79.<\/td><td><ul><li><a href=\"\/download-titulus?id=h0TKLlOv%2FIaaVAqgdHKgAQ%3D%3D_001114546-FS_FILES-25eea59a-8ca4-4780-ad91-e942e8d69671%5B1%5D.pdf\" target=\"_blank\">Decreto Corsi Erickson.pdf<a><\/li><li><a href=\"\/download-titulus?id=JJLBMU3sxbjwLryQHtRjHg%3D%3D_001114547-FS_FILES-a6b31a90-ecac-4d92-ad7a-1e675796ec70%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>07\/09\/2023<\/td><td>06\/09\/2023<\/td><td>2023-UNVACLE-0014485<\/td><td>Decreto del Direttore di Dipartimento di Scienze umane e sociali - Affidamento diretto alla ditta Liquid Plan S.r.l., P.IVA 11818651009, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, del servizio di erogazione di n. 2 corsi di formazione in modalit\u00e0 telematica per due docenti dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, nell\u2019ambito del progetto di ricerca di Ateneo \u201cOltre il lockdown \u2013 Spazi di ricerca e di intervento per il benessere dei singoli, dei gruppi e della comunit\u00e0\u201d di cui \u00e8 responsabile scientifico la Prof.ssa Laura Ferro (codice: FER20PRA.SHS). CIG ZDA3C5B920.<\/td><td><ul><li><a href=\"\/download-titulus?id=oVzBU0pBTvZ66bjWXjLBsQ%3D%3D_001114986-FS_FILES-c528a4bd-fc9b-49d6-8a94-e7a018588783%5B1%5D.pdf\" target=\"_blank\">Decreto Corsi FCP.pdf<a><\/li><li><a href=\"\/download-titulus?id=40P1gr5kbF30Q44C1NQR8A%3D%3D_001114987-FS_FILES-378bc030-f61a-4ecb-bc68-36c159ba1e80%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>07\/09\/2023<\/td><td>06\/09\/2023<\/td><td>2023-UNVACLE-0014486<\/td><td>Decreto del Direttore di Dipartimento di Scienze umane e sociali - Affidamento diretto alla ditta Giunti Psicologia.io S.r.l., P.IVA 11854690010, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, del servizio di erogazione di n. 2 corsi di formazione in modalit\u00e0 telematica per due docenti dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, nell\u2019ambito del progetto di ricerca di Ateneo \u201cOltre il lockdown \u2013 Spazi di ricerca e di intervento per il benessere dei singoli, dei gruppi e della comunit\u00e0\u201d di cui \u00e8 responsabile scientifico la Prof.ssa Laura Ferro (codice: FER20PRA.SHS). CIG Z093C5ADE5.<\/td><td><ul><li><a href=\"\/download-titulus?id=y50Z8OGghjBGdVWgWhpemw%3D%3D_001114988-FS_FILES-31651fec-b974-4958-8fdb-41f02ac87c50%5B1%5D.pdf\" target=\"_blank\">Decreto Corsi psicologia.io.pdf<a><\/li><li><a href=\"\/download-titulus?id=sYJKLlK94NKEr1Ajisbacg%3D%3D_001114989-FS_FILES-707ec93f-3982-483e-9f38-2f402519033f%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>06\/10\/2023<\/td><td>05\/10\/2023<\/td><td>2023-UNVACLE-0016116<\/td><td>Decreto del Direttore del Dipartimento di Scienze umane e sociali - Pubblicazione di un articolo relativo ad alcuni risultati della ricerca nell\u2019ambito del progetto denominato \u201cOltre il lockdown \u2013 Spazi di ricerca e di intervento per il benessere dei singoli, dei gruppi e della comunit\u00e0\u201d \u2013 codice FER20PRA.SHS \u2013 sulla rivista Open Access \u201cFrontiers in Education\u201d da parte della Ditta Frontiers Media sa con sede in 1005 Lausanne (Switzerland) \u2013 Avenue du tribunal Federal 34 \u2013 CHE-114.168.540 TVA \u2013 CIG ZCF3CA6E19. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=7JvTUHA77PesKNbgrPqgcg%3D%3D_001122026-FS_FILES-064b86f7-4f0c-4328-a3e6-345b6b4e2d0c%5B1%5D.pdf\" target=\"_blank\">Decreto Pubblicazione Frontiers.pdf<a><\/li><li><a href=\"\/download-titulus?id=j4nNvXRBivn4GNKVbpwIMw%3D%3D_001122027-FS_FILES-fc2bef00-5745-4445-9364-e87e20ed6b99%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN per Decreto.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>13\/11\/2023<\/td><td>10\/11\/2023<\/td><td>2023-UNVACLE-0018179<\/td><td>Decreto del Direttore del Dipartimento di Scienze Umane e Sociali - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Fenice Distribuzione S.r.l., P.IVA 01250400320, della fornitura del servizio di abbonamento alla banca dati online \u201cOxford Reference Premium\u201d \u2013 Codice Progetto DOTBAS2023.SHS - CIG ZF13D2E641. Autorizzazione alla spesa<\/td><td><ul><li><a href=\"\/download-titulus?id=%2BcWvVL%2Fl23hMnBALDFQizA%3D%3D_001130139-FS_FILES-96f198ad-ce0e-4085-8a07-2537455ef2b5%5B1%5D.pdf\" target=\"_blank\">Decreto Fenice.pdf<a><\/li><li><a href=\"\/download-titulus?id=ZWzLVaZQN2MH7Gcb8wH1rg%3D%3D_001130140-FS_FILES-1d3a145d-d54e-4fad-bcae-d3015a10926e%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/11\/2023<\/td><td>24\/11\/2023<\/td><td>2023-UNVACLE-0019191<\/td><td>Decreto del Direttore di Dipartimento di Scienze umane e sociali - Revoca dell\u2019affidamento alla Ditta MIM Edizioni S.r.l., P.IVA 02419370305, per la pubblicazione e la fornitura di copie del volume \u201cIn montagna non ci sono alberi. Esperienze di antropologia alpina\u201d della Professoressa Valentina Porcellana, disposto con Decreto del Direttore del Dipartimento di scienze Umane e sociali n. 225, del 21 ottobre 2022, e relativa decisione di contrarre nonch\u00e9 contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Meltemi Press S.r.l., P. IVA 09706560969. CIG Z5E380DC36.<\/td><td><ul><li><a href=\"\/download-titulus?id=iO5QO1dbegD4EnuapUXwvQ%3D%3D_001135149-FS_FILES-a02ae2f6-0b09-4f7e-8b97-427cdcaa6cc3%5B1%5D.pdf\" target=\"_blank\">Decreto_Meltemi_def.pdf<a><\/li><li><a href=\"\/download-titulus?id=l%2F0WVTjYvJ%2Bgli8TgcvMHg%3D%3D_001135150-FS_FILES-773c5db7-f43e-4b41-a955-6a7c1d983382%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>29\/11\/2023<\/td><td>28\/11\/2023<\/td><td>2023-UNVACLE-0019339<\/td><td>Decreto del Direttore di Dipartimento di Scienze Umane e Sociali - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, all\u2019Associazione Archivio Storico Olivetti, P.IVA 07557530016, del servizio di riproduzione digitale di documentazione conservata presso la sede dell\u2019Archivio Storico Olivetti di Ivrea visionata dal Prof. Fabrizio Bertolino \u2013 Ricercatore dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 Codice Progetto DOTBAS2023.SHS - CIG ZDA3D55F52. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=64m1JF4vJ2VKKt%2FL2Imrtg%3D%3D_001135828-FS_FILES-b55c62c9-a1bf-4096-9eec-c3c6fac8c05f%5B1%5D.pdf\" target=\"_blank\">Decreto - Archivio Storico Olivetti.pdf<a><\/li><li><a href=\"\/download-titulus?id=paC%2BqpZEYPD3QAp%2Bih7HGw%3D%3D_001135829-FS_FILES-262f0f1d-4202-4827-83e7-563d1363d2f3%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>31\/01\/2023<\/td><td>30\/01\/2023<\/td><td>2023-UNVACLE-0001666<\/td><td>Decreto Rettorale - Affidamento alla ditta BeSafe Group Srl a socio unico, P. IVA 01656730056, della predisposizione del Documento Unico di Valutazione dei Rischi Interferenziali (D.U.V.R.I.) per la Cerimonia di apertura dell\u2019anno accademico 2022-2023 del 16\/02\/2023 - Autorizzazione alla spesa \u2013 CIG Z6B39A668A<\/td><td><ul><li><a href=\"\/download-titulus?id=dyeSc8p7%2BTMXP9eTP%2B3ZtQ%3D%3D_001067901-FS_FILES-0171ddba-a398-4e53-93cb-f212a2a2c3f9%5B1%5D.pdf\" target=\"_blank\">Decreto rettorale_BeSafe Group.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2FDPYaJZNepfLAlLXs50tqg%3D%3D_001067902-FS_FILES-7280225a-d00d-48c3-9c4e-0a4161424bf8%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 191.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>06\/02\/2023<\/td><td>03\/02\/2023<\/td><td>2023-UNVACLE-0002187<\/td><td>Decreto rettorale - \nDecreto rettorale - Affidamento alla ditta Dreamlight P. IVA 00669180077, della fornitura di servizi connessi all\u2019utilizzo del Teatro Splendor per la cerimonia di inaugurazione dell\u2019anno accademico 2022-2023 dell\u2019Universit\u00e0 della Valle d\u2019Aosta. Autorizzazione alla spesa - CIG Z1A3970486.<\/td><td><ul><li><a href=\"\/download-titulus?id=a8lyq4ziP%2BaU%2BWysUCV3Zg%3D%3D_001069723-FS_FILES-a49895de-242e-45cb-844f-0be6f804a5ff%5B1%5D.pdf\" target=\"_blank\">Decreto rettorale Dreamlight.pdf<a><\/li><li><a href=\"\/download-titulus?id=yIi3P%2FnThyMaMfLUHDng9g%3D%3D_001069724-FS_FILES-59ea95f8-93f7-424e-b661-78321d7f89a3%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 38.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>02\/08\/2023<\/td><td>01\/08\/2023<\/td><td>2023-UNVACLE-0012719<\/td><td>Evento \u201cPr\u00e9lude aux Plaisirs de Culture. La chapelle Saint-Anselme en musique\u201d organizzato dalla Chaire Senghor de la Francophonie dell\u2019Universit\u00e0 della Valle d\u2019Aosta nell\u2019ambito della manifestazione \u201cPlaisirs de Culture en Vall\u00e9e d\u2019Aoste\u201d in programma dal 16 al 24 settembre 2023. Approvazione dell\u2019evento, conferimento incarichi e autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=A4kk5aixh%2FctjHrkJ7YTpw%3D%3D_001108662-FS_FILES-ce6ab4e5-ef95-4660-99a2-17483bd92277%5B1%5D.pdf\" target=\"_blank\">Decreto rettorale Plaisirs de culture 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=Zytg3KKzBWwV%2BAg5CA4%2FCg%3D%3D_001108663-FS_FILES-800c6c57-2d5f-418f-9d8d-3f4970743218%5B1%5D.pdf\" target=\"_blank\">CV Rivolin Fran\u00e7ais abr\u00e9g\u00e9.pdf<a><\/li><li><a href=\"\/download-titulus?id=yNRc%2BCmjEM3jRoBbsXZ3Eg%3D%3D_001108664-FS_FILES-13563cf5-aa0f-49ba-b1c9-c3d84e5d053b%5B1%5D.pdf\" target=\"_blank\">CV Taccardi.pdf<a><\/li><li><a href=\"\/download-titulus?id=jyBo8ZSB%2BHE%2FCqOf%2FmhccQ%3D%3D_001108665-FS_FILES-768e3d28-823a-4b6f-a641-120acf6b06fb%5B1%5D.pdf\" target=\"_blank\">CV Carazzolo.pdf<a><\/li><li><a href=\"\/download-titulus?id=1oqXSV2WgrYs0JiLc5pTgQ%3D%3D_001108666-FS_FILES-7a9136c5-5e10-454a-8bf4-9a6151732026%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 2309-2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>21\/09\/2023<\/td><td>20\/09\/2023<\/td><td>2023-UNVACLE-0015159<\/td><td>Approvazione dell\u2019adesione dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste alla Convenzione Consip Facility Management 4 \u2013 Convenzione per l\u2019affidamento di servizi integrati, gestionali ed operativi, da eseguirsi negli immobili, adibiti prevalentemente ad uso ufficio, in uso a qualsiasi titolo alle Pubbliche Amministrazioni, nonch\u00e9 negli immobili in uso a qualsiasi titolo alle istituzioni universitarie pubbliche ed agli enti ed istituti di ricerca ubicati nella Regione Valle d\u2019Aosta, nella Regione Liguria, relativamente alle sole province di Savona e Imperia, e nella Regione Piemonte relativamente alle sole province di Cuneo e Torino.<\/td><td><ul><li><a href=\"\/download-titulus?id=NzG76GkvWGv%2Foa8lJOjSZg%3D%3D_001120322-FS_FILES-1e9bf95f-76db-4e56-af71-0041739f53fb%5B1%5D.pdf\" target=\"_blank\">testo_delibera.pdf<a><\/li><li><a href=\"\/download-titulus?id=pV7hSXtyg2D3MQhBBUxfLA%3D%3D_001120323-FS_FILES-0675424b-8b52-48ea-a46d-54f2d2ae4a68%5B1%5D.pdf\" target=\"_blank\">FM4L020017_PDA_Rev01_Universit\u00e0 della Valle D Aosta (1).pdf<a><\/li><\/ul><\/td><\/tr><tr><td>07\/02\/2023<\/td><td>06\/02\/2023<\/td><td>2023-UNVACLE-0002298<\/td><td>Affidamento al Consorzio Interuniversitario Almalaurea, P.IVA 02120391202, della fornitura del servizio di inserimento laureati in banca dati e XXV indagine condizione occupazionale \u2013 CIG Z3E399B5B1.<\/td><td><ul><li><a href=\"\/download-titulus?id=BUcbEqmDPo%2FqQgHl%2BWcblw%3D%3D_001070095-FS_FILES-0d36192c-1536-4dcb-bb21-1a32397b8a5a%5B1%5D.pdf\" target=\"_blank\">PD Area 2 - Almalaurea 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2FjF0y1RdD%2F1cSpeuiKCyKA%3D%3D_001070096-FS_FILES-4ae11108-89ac-46c4-899c-2fc09ca9efae%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN 193 27.1.2023 ALMA Lpdf.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>28\/02\/2023<\/td><td>27\/02\/2023<\/td><td>2023-UNVACLE-0003774<\/td><td>Provvedimento del Dirigente Area Didattica e Servizi agli Studenti - Adesione alla Convenzione di Consip s.p.a. denominata \u201cConvenzione per la prestazione dei servizi relativi alla gestione integrata della salute e sicurezza sui luoghi di lavoro per le pubbliche amministrazioni, ai sensi dell\u2019articolo 26, legge 23 dicembre 1999 n. 488 e s.m.i. e dell\u2019articolo 58, legge 23 Dicembre 2000 n.388\u201d per il servizio di erogazione di un corso di informazione e formazione dei lavoratori sui luoghi di lavoro ai sensi dell\u2019art. 37 del d. lgs. n. 81\/2008 per gli studenti del Corso di laurea magistrale in Scienze della formazione primaria - CIG ZC1374BD3D - Parziale rettifica dell\u2019ODA.<\/td><td><ul><li><a href=\"\/download-titulus?id=qXLFklLJXg%2Bz8eG4q2Kfng%3D%3D_001075666-FS_FILES-d6391da3-9a7e-4ec4-b28f-7c8ec8cc997d%5B1%5D.pdf\" target=\"_blank\">Provvedimento corso sicurezza SFP 22 RETTIFICA.pdf<a><\/li><li><a href=\"\/download-titulus?id=TPfJPqL0JiE3WKkk%2FQ0f6w%3D%3D_001075667-FS_FILES-579db480-95cb-4882-8db7-0c1fc05fdc01%5B1%5D.pdf\" target=\"_blank\">ORDINE_7128115 (3).pdf<a><\/li><\/ul><\/td><\/tr><tr><td>20\/03\/2023<\/td><td>17\/03\/2023<\/td><td>2023-UNVACLE-0005108<\/td><td>Provvedimento del Dirigente dell'Area Didattica e Servizi agli Studenti - Affidamento al Consorzio Interuniversitario Sistemi Integrati per l\u2019Accesso - CISIA della fornitura di servizi per lo svolgimento del test TOLC-PSI per l\u2019ammissione al Corso di laurea in Scienze e tecniche psicologiche per l\u2019anno accademico 2023\/2024. Autorizzazione della spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=77YFk%2FpJBurZQazfZO0Ztg%3D%3D_001080467-FS_FILES-dadf00ec-c001-410c-8fb3-213c258ad8f9%5B1%5D.pdf\" target=\"_blank\">PD affidamento a CISIA.pdf<a><\/li><li><a href=\"\/download-titulus?id=1N4N02IsRpH4OkQtf0vEjQ%3D%3D_001080468-FS_FILES-11a2f1b5-de60-4dd3-a625-a3edf9fecc11%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 876 - CISIA.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>23\/03\/2023<\/td><td>22\/03\/2023<\/td><td>2023-UNVACLE-0005354<\/td><td>Provvedimento del Dirigente dell'Area Didattica e Servizi agli Studenti - Affidamento al Consorzio Interuniversitario sulla Formazione COINFO dell\u2019erogazione di un corso di formazione dal titolo \u201cDoppia iscrizione. Prime esperienze a confronto\u201d, erogato in modalit\u00e0 telematica, rivolto a un dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste. Autorizzazione della spesa.  \u2013 CIG Z563A68CCF.<\/td><td><ul><li><a href=\"\/download-titulus?id=JlVUGtA95y5g3wqIY7bqQw%3D%3D_001081320-FS_FILES-dc54dcab-3514-4dbf-b9bd-593311979780%5B1%5D.pdf\" target=\"_blank\">Provvedimento Dirigenziale affidamento Coinfo.pdf<a><\/li><li><a href=\"\/download-titulus?id=DDGAEbUjSVmHqPtMSQOFUQ%3D%3D_001081321-FS_FILES-da6590a9-0f53-4754-9c81-408f6ecc1d45%5B1%5D.pdf\" target=\"_blank\">Programma del corso.pdf<a><\/li><li><a href=\"\/download-titulus?id=PX4an0jXNUQccOEfWUgeAQ%3D%3D_001081322-FS_FILES-9f717b81-1675-4202-b25e-9a3fc38657e8%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 924 - COINFO.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>25\/05\/2023<\/td><td>24\/05\/2023<\/td><td>2023-UNVACLE-0008771<\/td><td>Provvedimento del Dirigente Area Didattica e Servizi agli Studenti - Affidamento alla ditta LINEATENEI S.a.s di Isaija Patrizia, P.IVA 12398000013, della fornitura del servizio per la partecipazione, in modalit\u00e0 telematica, al \u201c7\u00b0 Coordinamento organizzativo delle Segreterie studenti delle Universit\u00e0 italiane- UNISTUD\u201d di due dipendenti dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste. Autorizzazione della spesa.  \u2013 CIG Z463A68F5C.<\/td><td><ul><li><a href=\"\/download-titulus?id=puxxvP82gO18tbm510dCLA%3D%3D_001093783-FS_FILES-56c65b78-cc49-4906-9f0d-36ba1212a964%5B1%5D.pdf\" target=\"_blank\">Provvedimento Dirigenziale affidamento UNISTUD 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2BZ7l55MsHIJsDp0U3cCdJA%3D%3D_001093784-FS_FILES-51c7575c-fc92-40ad-9f10-6fa824e8ffa7%5B1%5D.pdf\" target=\"_blank\">UniSTUDProgramma2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=lCmvSiQZPde9wt0Hda3uJA%3D%3D_001093785-FS_FILES-8bb1ecca-4182-4fb7-8c84-81388009ea88%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>22\/06\/2023<\/td><td>21\/06\/2023<\/td><td>2023-UNVACLE-0010627<\/td><td>Provvedimento del Dirigente dell'Area Didattica e Servizi agli studenti - Affidamento alla ditta CISES SRL della fornitura di materiali e servizi per lo svolgimento della prova di ammissione al Corso di laurea magistrale a ciclo unico in Scienze della formazione primaria per l\u2019anno accademico 2023\/2024. CIG n. Z8B3B7B2ED<\/td><td><ul><li><a href=\"\/download-titulus?id=IqKS%2F%2FQVPeEgAlpTtvme1Q%3D%3D_001100280-FS_FILES-4fbc4b4c-391e-4de6-9a53-3bb79f265aa7%5B1%5D.pdf\" target=\"_blank\">PD affidamento test sfp.pdf<a><\/li><li><a href=\"\/download-titulus?id=d9pNxraKswcNx61GN7xBWg%3D%3D_001098110-FS_FILES-34ce5d62-c980-419d-af16-1567f7d9f2f8%5B3%5D.pdf\" target=\"_blank\">Condizioni di espletamento della fornitura.pdf<a><\/li><li><a href=\"\/download-titulus?id=xwCEFeOPVGZ0qVunExU0Yw%3D%3D_001100236-FS_FILES-b5d58a5f-4db6-4f3f-ad93-ea31c2012e11%5B1%5D.p7m\" target=\"_blank\">Offerta economia CISES.p7m<a><\/li><li><a href=\"\/download-titulus?id=mLe0PbOyTtA7gcQ7CnqY%2FA%3D%3D_001100279-FS_FILES-43d8cad5-d7f2-4222-9f24-31f1d858b746%5B1%5D.pdf\" target=\"_blank\">Scrittura contabile.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/09\/2023<\/td><td>26\/09\/2023<\/td><td>2023-UNVACLE-0015501<\/td><td>Provvedimento del Dirigente dell'Area Didattica e Servizi agli Studenti - Affidamento diretto alla ditta Aifos Service Societ\u00e0 Cooperativa, P.IVA 03129720987, del servizio di erogazione di un corso di informazione e formazione dei lavoratori sui luoghi di lavoro ai sensi dell\u2019art. 37 del D.lgs. n. 81\/2008, per gli studenti del Corso di laurea magistrale in Scienze della formazione primaria. CIG Z4C3C3515B.<\/td><td><ul><li><a href=\"\/download-titulus?id=1y71r3tnpEDtBg%2FE9C8l6w%3D%3D_001119370-FS_FILES-e214883e-ac35-4ea7-998c-7a299f0afc27%5B1%5D.pdf\" target=\"_blank\">PD Corso studenti.pdf<a><\/li><li><a href=\"\/download-titulus?id=bmgCN31x1NNqdpVzuJSMWA%3D%3D_001114591-FS_FILES-1e54f9bc-8b61-4592-924c-8ef31b45ad21%5B2%5D.pdf.p7m\" target=\"_blank\">TD Corso.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=EKiH9pEzt6E3Byr7eZxCUw%3D%3D_001114590-FS_FILES-771059a1-5123-43f9-b1fd-0de20c136d5f%5B2%5D.pdf.p7m\" target=\"_blank\">OE_NG3713923_L0_NP837553 _1_.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=XuOxHRP52tOs%2F%2BrQxYnSpg%3D%3D_001119304-FS_FILES-83f80dec-804b-41b0-bde6-18c2e2025d25%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>09\/10\/2023<\/td><td>06\/10\/2023<\/td><td>2023-UNVACLE-0016173<\/td><td>Provvedimento del Dirigente dell'Area Didattica e Servizi agli Studenti - Affidamento diretto alla ditta LineAtenei s.a.s. di Patrizia Isaija, P.IVA 12398000013, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, della fornitura del servizio per la partecipazione di due dipendenti dell\u2019Ufficio Offerta formativa e Qualit\u00e0 dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, in modalit\u00e0 online, al 2\u00b0 Forum nazionale Comenio Didattica & Management e al 2\u00b0 Seminario nazionale Punto Organi - CIG Z303CA93A4<\/td><td><ul><li><a href=\"\/download-titulus?id=G7Jq69xGYSLLPdM5PJXwmg%3D%3D_001122261-FS_FILES-e5109eec-b3d0-44f4-8df0-2e7c490a510b%5B1%5D.pdf\" target=\"_blank\">PD_Partecipazione Forum DEF.pdf<a><\/li><li><a href=\"\/download-titulus?id=S9H7%2BzUmhKZOXAkobeS5EQ%3D%3D_001122248-FS_FILES-3ee7b3e8-50c8-4d23-991d-c36d7bfbfabf%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=0Qyy4%2FLrHo7DhVs4jLDy9Q%3D%3D_001122180-FS_FILES-d05dc1de-377a-4499-b5d4-7253ec58cf7c%5B1%5D.pdf\" target=\"_blank\">Programma Forum Urbino - 20.10.pdf<a><\/li><li><a href=\"\/download-titulus?id=D7iQ6c5yXbIOdvbKHlUhDA%3D%3D_001122181-FS_FILES-f13cb205-0b17-4f55-a17b-f3dda1c41c7e%5B1%5D.pdf\" target=\"_blank\">Programma Forum Roma - 10.11.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>24\/10\/2023<\/td><td>23\/10\/2023<\/td><td>2023-UNVACLE-0017076<\/td><td>Provvedimento del Dirigente dell'Area Didattica e Servizi agli Studenti - Affidamento diretto alla ditta LineAtenei s.a.s. di Patrizia Isaija, P.IVA 12398000013, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, del servizio di erogazione di un corso formazione dal titolo \u201cRiesame Ciclico dei corsi di studio: il Rapporto secondo AVA3\u201d, erogato in modalit\u00e0 telematica, rivolto a due dipendenti dell\u2019Ufficio Offerta formativa e Qualit\u00e0 dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste - CIG ZB73CE8C7F<\/td><td><ul><li><a href=\"\/download-titulus?id=Sr1zaod4uQaG1cR%2B9HvzDg%3D%3D_001125924-FS_FILES-9b93e324-2433-4d5f-acc9-c1891fb3daca%5B1%5D.pdf\" target=\"_blank\">PD_Corso 09.11.pdf<a><\/li><li><a href=\"\/download-titulus?id=Sfdc4GmXtwmBgjxoRDMXfQ%3D%3D_001125925-FS_FILES-725e0c0d-5bc2-42a1-9345-6d26a6cd47ca%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2F6yggoZ0I%2FV0BdCKzN%2BN2g%3D%3D_001125926-FS_FILES-a712f3a9-a1a8-442a-9306-da0b91de8a8d%5B1%5D.pdf\" target=\"_blank\">Programma corso 09.11.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/11\/2023<\/td><td>13\/11\/2023<\/td><td>2023-UNVACLE-0018234<\/td><td>Provvedimento del Dirigente dell'Area Didattica e Servizi agli Studenti - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla Societ\u00e0 Consorzio Interuniversitario sulla Formazione (Co.In.Fo), P.IVA 06764560014, di un servizio per l\u2019erogazione di un corso di formazione dal titolo \u201cAspetti giudici dell\u2019uso delle tecnologie digitali e dell\u2019intelligenza artificiale nei procedimenti amministrativi delle segreterie universitarie\u201d, destinato a due dipendenti dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG ZBB3D1ED5E. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=avLxdsa%2F4bYfhrm%2B7MzHrw%3D%3D_001130373-FS_FILES-81bb7cdb-c5db-4038-8d8f-d5d77980bab0%5B1%5D.pdf\" target=\"_blank\">Provvedimento - Co.In.Fo.pdf<a><\/li><li><a href=\"\/download-titulus?id=FhNWU%2BjNFtlDAPgycfWuuw%3D%3D_001130374-FS_FILES-4ab35cd3-29c4-4ef0-a82f-4fde9bc91f39%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=JPknk201GGRSFpS20okOdQ%3D%3D_001130375-FS_FILES-0054cb3f-546f-4ba0-bebf-7998916b7e63%5B1%5D.pdf\" target=\"_blank\">Programma corso.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>17\/11\/2023<\/td><td>16\/11\/2023<\/td><td>2023-UNVACLE-0018574<\/td><td>Provvedimento Dirigente Area Didattica e Servizi agli Studenti - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla Societ\u00e0 Cooperativa sociale L\u2019Esprit \u00e0 l\u2019Envers della fornitura del servizio finalizzato al tutorato didattico e socio-educativo rivolto a studenti con disabilit\u00e0 iscritti all\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste nell\u2019anno accademico 2023\/2024 \u2013 CIG Z843D104E1. Autorizzazione della spesa<\/td><td><ul><li><a href=\"\/download-titulus?id=MRK6cHZUr%2B%2F35RwtVm0%2Faw%3D%3D_001131811-FS_FILES-465cb110-308b-4da3-93aa-60a9b6545379%5B1%5D.pdf\" target=\"_blank\">PD_tutorato.pdf<a><\/li><li><a href=\"\/download-titulus?id=xcC5guaCHtkRT7hESIYNXQ%3D%3D_001131812-FS_FILES-d25977ee-3a78-4863-8d9c-83c09b0aea99%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=Ws35%2BV1wpFEIRUb6pflTlA%3D%3D_001131813-FS_FILES-154f89ba-4199-4e3e-8fae-7e524f438985%5B1%5D.pdf\" target=\"_blank\">Progetto di tutorato didattico e socio-educativo 23.24.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>07\/04\/2023<\/td><td>06\/04\/2023<\/td><td>2023-UNVACLE-0006266<\/td><td>Provvedimento del Dirigente dell'Area Affari generali e Risorse Umane - Affidamento al Consorzio Interuniversitario sulla Formazione (CO.IN.FO), P.IVA 06764560014 dell\u2019erogazione di un corso di formazione denominato \u201cDal cedolino alla certificazione della posizione assicurativa INPS\u201d, erogato in modalit\u00e0 telematica, rivolto a una dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, ai sensi dell\u2019articolo 1, comma 2, lettera a), del Decreto-legge 16 luglio 2020, n. 76, convertito, con modificazioni, dalla Legge 11 settembre 2020, n. 120, come modificato dal Decreto-legge 31 maggio 2021, n. 77. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=ysZYwMifICQCNm2YzMGtpQ%3D%3D_001084597-FS_FILES-e928b81e-0012-4cb1-a4c6-6fd78d27bc9b%5B1%5D.pdf\" target=\"_blank\">PD Corso Dal cedolino alla certificazione della posizione INPS.pdf<a><\/li><li><a href=\"\/download-titulus?id=54XBi8o5cUIb%2FP8NSiZc3g%3D%3D_001084598-FS_FILES-ca77edad-f4c7-42b4-8641-88b43f77e460%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 1085 - COINFO.pdf<a><\/li><li><a href=\"\/download-titulus?id=Fm6H5WpbMwdo9r5o97FBHw%3D%3D_001084599-FS_FILES-d0a98dd5-b140-4ac0-bf0e-784e4ae18d3e%5B1%5D.pdf\" target=\"_blank\">Programma del corso.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>21\/04\/2023<\/td><td>20\/04\/2023<\/td><td>2023-UNVACLE-0006916<\/td><td>Provvedimento del Dirigente Area Affari generali e Risorse Umane - Affidamento alla Ditta Accademia Europea Societ\u00e0 Cooperativa, P. Iva 04533430403, dell\u2019erogazione del corso di formazione denominato \u201cIl nuovo diritto d\u2019autore negli istituti di tutela del patrimonio culturale e negli organismi di ricerca\u201d, erogato in modalit\u00e0 telematica, rivolto a una dipendente dell\u2019Ufficio Biblioteca e Coordinamento linguistico dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vallee d\u2019Aoste. - CIG n. Z893AD5929. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=E7MDnh0ZnKbQp5ekasuCog%3D%3D_001086968-FS_FILES-cc4079c3-b8b2-4e54-a396-54d814b131e7%5B1%5D.pdf\" target=\"_blank\">Provv_formaz_dir_autore.pdf<a><\/li><li><a href=\"\/download-titulus?id=gHh0YRPijOkrxdNfnv55aw%3D%3D_001086969-FS_FILES-99cf1ae9-8870-47ab-9d5a-b86dfd7c339b%5B1%5D.pdf\" target=\"_blank\">Corso_Nuovo_Diritto_Autore.pdf<a><\/li><li><a href=\"\/download-titulus?id=eit4OvxhGBB0O8kPqR8eDA%3D%3D_001086970-FS_FILES-33c8bac0-726b-473b-a14e-b0e80ce7f6dd%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 1242 Accademia europea.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>03\/05\/2023<\/td><td>02\/05\/2023<\/td><td>2023-UNVACLE-0007359<\/td><td>Provvedimento del Dirigente dell'Area Affari generali e Risorse Umane - Affidamento al Consorzio Interuniversitario Cineca, P.IVA 00502591209, dell\u2019erogazione di un corso di formazione denominato \u201cI congedi parentali in CSA\u201d, erogato in modalit\u00e0 conf-call, rivolto ad un dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, ai sensi dell\u2019articolo 1, comma 2, lettera a), del Decreto-legge 16 luglio 2020, n. 76, convertito, con modificazioni, dalla Legge 11 settembre 2020, n. 120, come modificato dal Decreto-legge 31 maggio 2021, n. 77. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=V7h202jC9zmq9pTKWwM28A%3D%3D_001088660-FS_FILES-18b6a3ae-c9de-4d5a-89b1-0e148ab03d1f%5B1%5D.pdf\" target=\"_blank\">PD Corso Cineca congedi parentali.pdf<a><\/li><li><a href=\"\/download-titulus?id=2wzVEyz4ArgYy4ftYhDp%2FA%3D%3D_001088661-FS_FILES-fccfc2bd-4e5f-4128-9cfb-40eb1c928143%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN 1319 - Corso Cineca Maggio 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=gPuTvDv93cP4E3p5uM2V%2Bg%3D%3D_001088662-FS_FILES-fc55d1b6-64d7-48c9-822d-c85560f8cbd6%5B1%5D.pdf\" target=\"_blank\">I congedi parentali in CSA _ Cineca Events.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>30\/06\/2023<\/td><td>29\/06\/2023<\/td><td>2023-UNVACLE-0011128<\/td><td>Provvedimento del Dirigente dell'Area Affari generali e Risorse umane - Affidamento alla Societ\u00e0 SOI srl dell\u2019erogazione di un corso di formazione dal titolo \u201cPensioni 2023 e incentivo in busta paga per il posticipo (dm 21\/3\/2023)\u201d, erogato in diretta streaming, rivolto ad una dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste tramite ordine diretto di acquisto nell\u2019ambito del MePA, ai sensi dell\u2019articolo 1, comma 2, lettera a), del Decreto legge 16 luglio 2020, n. 76, convertito, con modificazioni, dalla Legge 11 settembre 2020, n. 120, come modificato dal Decreto legge 31 maggio 2021, n. 77, nel testo vigente. CIG Z043BB07D3. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=N9bw%2FskeUVrPm3sH0Kk1Kw%3D%3D_001101978-FS_FILES-e72f497a-1c70-427f-92fe-a5dade679fd8%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=ZddocuwGt8tpSKSdLVJ0MA%3D%3D_001101977-FS_FILES-ea269791-dc46-42e3-9b7d-2bae67cd1a6e%5B1%5D.pdf\" target=\"_blank\">PD Corso Soi srl 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=7ca%2FkrIOYOsomtGZuVWqOw%3D%3D_001101653-FS_FILES-f894b0fb-f571-4bd9-a4ce-883b715fadf9%5B3%5D.pdf\" target=\"_blank\">Bozza Ordinativo n. 7319776 - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/10\/2023<\/td><td>26\/10\/2023<\/td><td>2023-UNVACLE-0017330<\/td><td>Provvedimento Dirigente Area Affari generali e Risorse Umane - Affidamento diretto alla ditta Opera S.r.l., P.IVA 05994580727, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, dell\u2019erogazione di un corso di formazione dal titolo \u201cLa nuova anagrafe delle prestazioni ADP 2.0 - 2023\u201d, erogato in modalit\u00e0 telematica, rivolto ad una dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG Z1C3CDCFA6<\/td><td><ul><li><a href=\"\/download-titulus?id=TKoWfkJChzXSBf7r%2Bn3shQ%3D%3D_001126995-FS_FILES-cc4adc7b-9706-4637-b74a-ac9765f795dd%5B1%5D.pdf\" target=\"_blank\">PD_Corso 27.10 DEF.pdf<a><\/li><li><a href=\"\/download-titulus?id=Tlq40FBxx9h91iOQaVN31g%3D%3D_001126996-FS_FILES-2934112b-a4bd-4328-96e5-5e995acdf506%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=L%2FNym4qC%2F%2FCZSQXIr80GpA%3D%3D_001126997-FS_FILES-0b8d706d-3b1a-482d-8228-446d1762fcba%5B1%5D.pdf\" target=\"_blank\">Programma corso 27.10.2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>15\/11\/2023<\/td><td>14\/11\/2023<\/td><td>2023-UNVACLE-0018474<\/td><td>Provvedimento Dirigente Area Affari generali e Risorse Umane - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 7, 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, al Consorzio Interuniversitario Cineca, P.IVA 00502591209, di un servizio per l\u2019erogazione di un corso di formazione denominato \u201cCSA Conguaglio fiscale e previdenziale Corso Base\u201d, destinato ad una dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=Hz8mFavV%2FzAxDG36QLg8Og%3D%3D_001131161-FS_FILES-ff06a256-dbca-4d82-98aa-ddb5b6eb68a9%5B1%5D.pdf\" target=\"_blank\">PD Corso CSA Conguaglio fiscale e previdenziale.pdf<a><\/li><li><a href=\"\/download-titulus?id=Pu%2FBztZ8mcacJod%2B5k4nTA%3D%3D_001131162-FS_FILES-84ccbdb7-0457-49bf-ae96-0e956f64ea97%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=iWg5WKaCD38pq6i%2Bo9Ni3Q%3D%3D_001131163-FS_FILES-3176e1ce-04da-4ede-991b-5b340ebbc027%5B1%5D.pdf\" target=\"_blank\">Programma.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>15\/11\/2023<\/td><td>14\/11\/2023<\/td><td>2023-UNVACLE-0018476<\/td><td>Provvedimento Dirigente Area Affari generali e Risorse Umane - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 7, 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, al Consorzio Interuniversitario Cineca, P.IVA 00502591209, di un servizio per l\u2019erogazione di un corso formazione denominato \u201cIl conguaglio di fine anno 2023\u201d, destinato ad una dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste. Autorizzazione alla spesa<\/td><td><ul><li><a href=\"\/download-titulus?id=XsjXwl5ctRXc3mIrUEHDWg%3D%3D_001131167-FS_FILES-5fb056c4-8708-4438-830e-0aa99ca4c48a%5B1%5D.pdf\" target=\"_blank\">PD Seminario Conguaglio.pdf<a><\/li><li><a href=\"\/download-titulus?id=i4JPsP%2BEShrnnaYDw8auIQ%3D%3D_001131168-FS_FILES-19e78812-9f9b-4d52-bb31-358f65c90dd1%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=lMD7bQGPXWT6%2FZsLKE4rZA%3D%3D_001131169-FS_FILES-66f08445-820c-45f2-8125-9e77c4dfcf1a%5B1%5D.pdf\" target=\"_blank\">Programma.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>03\/02\/2023<\/td><td>02\/02\/2023<\/td><td>2023-UNVACLE-0002048<\/td><td>Provvedimento Dirigente Area Finanza e Patrimonio - Affidamento alla ditta GIFRAN S.R.L., P. Iva 02369570987, della fornitura di materiale di primo soccorso, di cancelleria e carta per l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Trattativa Diretta (TD) nell\u2019ambito del Mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 CIG Z7D39A762D.<\/td><td><ul><li><a href=\"\/download-titulus?id=YNSYAgnbH4BLsRrh3itT2A%3D%3D_001069173-FS_FILES-c4c5544c-8e1a-41b6-80f4-4e60ef97194c%5B1%5D.pdf\" target=\"_blank\">PD_Reintegro cassette PS e cancelleria.pdf<a><\/li><li><a href=\"\/download-titulus?id=ba5TJGVv8m8usq2iuBdabg%3D%3D_001069168-FS_FILES-d95f5fda-cd7d-426f-8e65-b87ca2924970%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=jgO0a3sYV0YsECEWeTHq%2BQ%3D%3D_001069113-FS_FILES-bec931ca-bd56-4211-bc09-97ec3324c097%5B1%5D.pdf\" target=\"_blank\">Offerta economica n. 3408321.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>22\/02\/2023<\/td><td>21\/02\/2023<\/td><td>2023-UNVACLE-0003456<\/td><td>Provvedimenti Dirigente Area Finanza e Patrimonio - Affidamento al Gruppo Maggioli S.p.A., P. Iva 02066400405, dell\u2019erogazione di un corso di formazione online in materia di contratti pubblici denominato \u201cVerso il nuovo Codice dei contratti pubblici \u2013 Primo inquadramento generale e sintesi delle principali novit\u00e0\u201d rivolto al personale dell\u2019Ufficio Acquisti e Patrimonio dell\u2019Universit\u00e0 della Valle d\u2019Aosta - Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG Z873A01447.<\/td><td><ul><li><a href=\"\/download-titulus?id=Vuj0wKn31d934i%2FkQa%2FzbA%3D%3D_001074663-FS_FILES-4fa32cc5-5841-4547-a978-a1001916f651%5B1%5D.pdf\" target=\"_blank\">PD_Corso.pdf<a><\/li><li><a href=\"\/download-titulus?id=VNdINWRsEZuTqfQ2t8%2FMsw%3D%3D_001074470-FS_FILES-38d606d7-759c-4d90-881e-534bc2b90e38%5B1%5D.pdf\" target=\"_blank\">Programma Corso 28.02.2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=I2StJZuXEa7uDkzDFrGFgg%3D%3D_001074656-FS_FILES-1bfac1d8-9b21-452d-8cba-e49924293423%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>22\/02\/2023<\/td><td>21\/02\/2023<\/td><td>2023-UNVACLE-0003461<\/td><td>Rinnovo dell\u2019affidamento alla ditta Centro della Sicurezza s.n.c., P.IVA 01185560073, del servizio di gestione e manutenzione degli impianti antintrusione installati presso gli edifici utilizzati dall\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, per il periodo 1\u00b0 marzo 2023 \u2013 29 febbraio 2024 - CIG n. Z1639DC9E5<\/td><td><ul><li><a href=\"\/download-titulus?id=wrgv2cklVpAZ81HAVlQxkw%3D%3D_001074684-FS_FILES-b4a87ed7-2d81-4d6e-be08-16dcd82ad131%5B1%5D.pdf\" target=\"_blank\">PD Rinnovo Centro della Sicurezza.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2FtX5J5%2BmFJ%2BFt0wu14R7ow%3D%3D_001074682-FS_FILES-aae7076a-d5a9-4b0e-9fd1-0c2118afa6ea%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN N. 516.pdf<a><\/li><li><a href=\"\/download-titulus?id=61UVKIGuWuGI91sbm%2BNVEg%3D%3D_001074683-FS_FILES-dce1241a-31a5-43be-be89-7dced4313444%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN N. 517.pdf<a><\/li><li><a href=\"\/download-titulus?id=NWp4h7HAQyb5FmSBuuNEgg%3D%3D_000910298-FS_FILES-8fd0af0d-a33b-4a7e-953e-7d8fc6f19b33%5B5%5D.pdf\" target=\"_blank\">Condizioni particolari contratto.pdf<a><\/li><li><a href=\"\/download-titulus?id=zyQ5PV47vHM64kmtR9sEGA%3D%3D_000910299-FS_FILES-15cf9f2f-767d-4af6-ae36-15c2b1535e41%5B5%5D.pdf\" target=\"_blank\">Capitolato tecnico.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>08\/03\/2023<\/td><td>07\/03\/2023<\/td><td>2023-UNVACLE-0004425<\/td><td>Affidamento alla ditta Scotta S.r.l., P.IVA 02584100040, della fornitura e posa in opera di testine termostatiche finalizzate alla regolazione della temperatura presso la sede di Strada Cappuccini 2\/A dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG n. Z8B39FA981<\/td><td><ul><li><a href=\"\/download-titulus?id=SmthdnhiUvTZ9WviTfJTRg%3D%3D_001078108-FS_FILES-3cc90e24-7cea-4b08-a62a-5ba4bbef0c07%5B1%5D.pdf\" target=\"_blank\">PD Scotta - Testine termostatiche.pdf<a><\/li><li><a href=\"\/download-titulus?id=ilnl6ROmlMR0vhqw3Mtf6g%3D%3D_001078103-FS_FILES-eccdf208-8418-4061-8b72-b377d5abc0a2%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/03\/2023<\/td><td>13\/03\/2023<\/td><td>2023-UNVACLE-0004771<\/td><td>Provvedimento Dirigente Area Finanza e Patrimonio - Affidamento alla ditta Ingroscart S.r.l., P. IVA 01469840662, della fornitura di materiale igienico-sanitario, di carta per stampanti e di cancelleria per l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Trattativa Diretta (TD) nell\u2019ambito del Mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 CIG Z263A330BF<\/td><td><ul><li><a href=\"\/download-titulus?id=VkcZicx%2Fc9OFyjo7eCUYmw%3D%3D_001079277-FS_FILES-c817fd79-d5c0-4820-a0a8-c391a0c0bd71%5B1%5D.pdf\" target=\"_blank\">PD_Cancelleria+igienico.pdf<a><\/li><li><a href=\"\/download-titulus?id=z5vm3eXMgdzZq8ct%2Fa%2FrGw%3D%3D_001079278-FS_FILES-2ea05281-d46d-4b49-8d77-fadf5b29119f%5B1%5D.pdf\" target=\"_blank\">Lettera TD n. 3469515.pdf<a><\/li><li><a href=\"\/download-titulus?id=kdoQSO3BbyzEo0TeEtZKcQ%3D%3D_001079279-FS_FILES-2ae2c9cc-92f8-4b1a-b735-aab031820598%5B1%5D.pdf.p7m.p7m\" target=\"_blank\">OE_NG3469515_L0_NP509693.pdf.p7m.p7m<a><\/li><li><a href=\"\/download-titulus?id=tB%2BmI1K86wfqtKA4RRJq6Q%3D%3D_001078884-FS_FILES-b6fc4a83-71dc-445c-bae5-6f32cdd1e6d9%5B2%5D.p7m\" target=\"_blank\">Dettaglio prezzi.p7m<a><\/li><li><a href=\"\/download-titulus?id=wdWz%2FtM5yP4zhZ46SB3C3w%3D%3D_001079273-FS_FILES-d4dce274-35de-4b6a-a287-f2363f5f8ea7%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>28\/03\/2023<\/td><td>27\/03\/2023<\/td><td>2023-UNVACLE-0005589<\/td><td>Provvedimento Dirigente Area Finanza e Patrimonio - Affidamento alla Fondazione CRUI per le Universit\u00e0 italiane, Codice Fiscale 97240790580, dell\u2019erogazione di un corso avanzato di formazione in presenza in materia di contratti pubblici denominato \u201cNuovo Codice degli Appalti: servizi e forniture\u201d rivolto a un dipendente dell\u2019Ufficio Acquisti e Patrimonio dell\u2019Universit\u00e0 della Valle d\u2019Aosta - Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG Z3B3A7F43A<\/td><td><ul><li><a href=\"\/download-titulus?id=I%2FnZnI0B8XlPmPGgi92Zkg%3D%3D_001082136-FS_FILES-60743d11-e126-4dc6-bb2e-4e8b1e89517e%5B1%5D.pdf\" target=\"_blank\">PD_Corso Tr\u00e8ves.pdf<a><\/li><li><a href=\"\/download-titulus?id=o4GEt7uqm2kMZBy7Bv9%2Byg%3D%3D_001082080-FS_FILES-f81e01ef-df5c-454e-8f98-40052afe555f%5B1%5D.pdf\" target=\"_blank\">Programma corso_17 e 18 aprile 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=hKhYG593R2l3IRfCtOogCQ%3D%3D_001082081-FS_FILES-b0dcdbcd-8218-44f5-8a66-7ffe0ce8b1fb%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>30\/03\/2023<\/td><td>29\/03\/2023<\/td><td>2023-UNVACLE-0005771<\/td><td>Rinnovo dell\u2019affidamento alla Ditta Miorelli Service S.P.A. a Socio Unico, P.IVA 00505590224, dei servizi di pulizia, disinfezione e sanificazione degli edifici in uso all\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste per la durata di sei mesi, per il periodo 1\u00b0 aprile 2023 \u2013 30 settembre 2023 \u2013 CIG n. Z1F3A7A907<\/td><td><ul><li><a href=\"\/download-titulus?id=XPh5tg5u9aZBoT6CjEHRKg%3D%3D_001082814-FS_FILES-33e4ad04-b5a9-43f7-be92-1e645016e8e7%5B1%5D.pdf\" target=\"_blank\">PD rinnovo Miorelli.pdf<a><\/li><li><a href=\"\/download-titulus?id=Vp%2BfzUAuQ%2BPQv0XEHS3hrA%3D%3D_001082798-FS_FILES-881a05db-b6ad-4ce8-bb14-192884a69f9d%5B1%5D.pdf\" target=\"_blank\">Capitolato tecnico e planimetrie_aprile settembre 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=7dpDNtytfyo34xREvkbeAw%3D%3D_001082812-FS_FILES-7ace6667-dd62-48ab-a408-6bc798836c6d%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN_Sedi di Ateneo.pdf<a><\/li><li><a href=\"\/download-titulus?id=UO5XZjoae8BvGmph8uNrtA%3D%3D_001082813-FS_FILES-efbeff8c-f97c-4616-8785-2d280c362e69%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN_Prestazioni su richiesta.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>17\/04\/2023<\/td><td>14\/04\/2023<\/td><td>2023-UNVACLE-0006669<\/td><td>Provvedimento Dirigente Area Finanza e Patrimonio - Affidamento alla Societ\u00e0 PI\u00d9 S.r.l., P.IVA 08857861002, dell\u2019erogazione di un corso avanzato di formazione in presenza in materia di contratti pubblici denominato \u201cNuovo Codice degli Appalti: servizi e forniture\u201d rivolto a un dipendente dell\u2019Ufficio Acquisti e Patrimonio dell\u2019Universit\u00e0 della Valle d\u2019Aosta - Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG Z3B3A7F43A \u2013 RETTIFICA PROVVEDIMENTO DIRIGENTE AREA FINANZA E PATRIMONIO N. 9, DEL 27 MARZO 2023<\/td><td><ul><li><a href=\"\/download-titulus?id=%2B4dADoqSWby3A4UsO4THtQ%3D%3D_001086058-FS_FILES-da6580e4-db24-45a0-812e-c1be56a7dc32%5B1%5D.pdf\" target=\"_blank\">PD_Corso Codice Appalti.pdf<a><\/li><li><a href=\"\/download-titulus?id=TszfTz1pX4jVgZ%2Fuhl04lQ%3D%3D_001086008-FS_FILES-e7845f50-5652-4df6-9fda-c6c3c26ed71a%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>20\/04\/2023<\/td><td>19\/04\/2023<\/td><td>2023-UNVACLE-0006853<\/td><td>Provvedimenti Dirigente Area Finanza e Patrimonio - Affidamento alla ditta Energy Salento Impianti s.r.l., P.IVA 08193950964, della fornitura e sostituzione di alcune componenti relative all\u2019impianto antincendio, presso la sede di Strada Cappuccini dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG n. Z1A3AC7B12<\/td><td><ul><li><a href=\"\/download-titulus?id=bx3ZKNHVw7GFwsiBV8uTgw%3D%3D_001086724-FS_FILES-112a928f-8b4d-4d71-9b37-42b973ddc560%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=qBzm8BCVxPq3cBoWRNQxMg%3D%3D_001086725-FS_FILES-43b0b322-91a5-4149-8126-79ceecfb48e4%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - extra franchigia.pdf<a><\/li><li><a href=\"\/download-titulus?id=FJ%2FwztVtuinmIw00kK1W%2FQ%3D%3D_001086726-FS_FILES-94f7dd02-2c38-4f5d-a29a-b973d818db58%5B1%5D.pdf\" target=\"_blank\">PD Energy Salento2.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/04\/2023<\/td><td>26\/04\/2023<\/td><td>2023-UNVACLE-0007135<\/td><td>Provvedimenti Dirigente Area Finanza e Patrimonio - Affidamento alla ITA S.R.L., P.IVA 01593590605, dell\u2019erogazione di un corso di formazione in diretta streaming denominato \u201cL\u2019aggiornamento del regolamento di Cassa Economale\u201d rivolto a un dipendente dell\u2019Ufficio Acquisti e Patrimonio dell\u2019Universit\u00e0 della Valle d\u2019Aosta - Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG ZED3AE77F0<\/td><td><ul><li><a href=\"\/download-titulus?id=3ZZ%2FakRs4ldGCoMJEJYxFg%3D%3D_001087800-FS_FILES-44bb08cf-ff64-4501-b343-ab1bc37b8168%5B1%5D.pdf\" target=\"_blank\">PD_Corso Tr\u00e8ves.pdf<a><\/li><li><a href=\"\/download-titulus?id=vcdJ2rbBIdn6Wrhx94yBRQ%3D%3D_001087688-FS_FILES-93db9d10-b5e3-487e-ae8d-200cf25c3aae%5B1%5D.pdf\" target=\"_blank\">Programma corso.pdf<a><\/li><li><a href=\"\/download-titulus?id=0qAJENa0rYtZbog6ZMwSyg%3D%3D_001087694-FS_FILES-196d2cfa-8926-4140-b3a6-ca57131403c6%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>03\/05\/2023<\/td><td>02\/05\/2023<\/td><td>2023-UNVACLE-0007357<\/td><td>Provvedimenti Dirigente Area Finanza e Patrimonio - Proroga tecnica dell\u2019affidamento alla ditta Scotta s.r.l. P.IVA 02584100040, dei servizi di conduzione e manutenzione degli impianti idricosanitari, dei boiler, delle apparecchiature di raffrescamento ad espansione diretta (split), degli impianti di condizionamento estivo e delle unit\u00e0 termoventilanti presso gli edifici utilizzati dall\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, per la durata di sei mesi, per il periodo 1\u00b0 maggio 2023 \u2013 31 ottobre 2023 \u2013 CIG n. Z5A280B853<\/td><td><ul><li><a href=\"\/download-titulus?id=gnJB1KWzkhrAy0oHE2lGNQ%3D%3D_001088558-FS_FILES-ac6ff6fe-3f26-4a0f-bc26-15da34143b55%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=S0RwvN6v6c3M6dMQAstNKQ%3D%3D_001088654-FS_FILES-dbe2735e-00c1-49d9-8a3c-f4afb2a59ade%5B1%5D.pdf\" target=\"_blank\">PD Proroga tecnica.pdf<a><\/li><li><a href=\"\/download-titulus?id=V%2B2pJsA77t%2BRsFS9ahO2Iw%3D%3D_001088559-FS_FILES-cb71a98c-baa3-4ba6-88f9-a4e03335fefb%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN_importo extra-franchigia.pdf<a><\/li><li><a href=\"\/download-titulus?id=BirEvuHxP5l7bA%2BY3Pg81Q%3D%3D_001088560-FS_FILES-80138b1c-35be-4a83-a67f-f5b767bb97c4%5B1%5D.pdf\" target=\"_blank\">Condiz. partic. contratto.pdf<a><\/li><li><a href=\"\/download-titulus?id=Vg7OEQ%2FMlg9O2PL%2BWrIGRQ%3D%3D_001088561-FS_FILES-bf68a54e-9297-4db5-a022-912e9e3577c8%5B1%5D.pdf\" target=\"_blank\">Capitolato tecnico.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>05\/05\/2023<\/td><td>04\/05\/2023<\/td><td>2023-UNVACLE-0007495<\/td><td>ProvvedimentO Dirigente Area Finanza e Patrimonio - Affidamento al Consorzio Interuniversitario Cineca, P.IVA 00502591209 e C.F. 00317740371, dell\u2019erogazione di un corso di formazione denominato \u201cFinance - Allocazione Stipendi in CoGe e CoAn\u201d, erogato in modalit\u00e0 telematica, rivolto a un dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste. Autorizzazione alla spesa<\/td><td><ul><li><a href=\"\/download-titulus?id=yrVFCNBGb4v7z5AvaD70Fg%3D%3D_001089130-FS_FILES-59b22d22-19c8-450f-acaa-a462472f44e6%5B1%5D.pdf\" target=\"_blank\">PD affidamento CINECA AC Stipendi.pdf<a><\/li><li><a href=\"\/download-titulus?id=eJgXQ6mf26JIkImmFm9rHQ%3D%3D_001089061-FS_FILES-59262af3-aec2-421b-9414-ee1182965f6b%5B1%5D.pdf\" target=\"_blank\">Programma corso Allocazione costi stipendi.pdf<a><\/li><li><a href=\"\/download-titulus?id=MDExHkmhyOWdMeKJCDIkhw%3D%3D_001089126-FS_FILES-d7836e44-6bed-4747-85ab-8d91fb44ecfe%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>20\/06\/2023<\/td><td>19\/06\/2023<\/td><td>2023-UNVACLE-0010313<\/td><td>Affidamento alla ditta Bunder Company s.r.l. di Bari, P.IVA e C.F. 07734810729, della fornitura e consegna di n. 7 dissuasori di sosta ripiegabili, con serratura, da installare presso la sede ex hotel Ambassador, in Aosta - CIG N. Z293B7B201<\/td><td><ul><li><a href=\"\/download-titulus?id=7snH0zBcPLGSpcUgVEa7Jg%3D%3D_001099215-FS_FILES-fc3afb3b-e95a-4df2-a5ff-d792b1948699%5B1%5D.pdf\" target=\"_blank\">PD dissuasori di sosta.pdf<a><\/li><li><a href=\"\/download-titulus?id=7J7L40LKJ6xpm0AkxQawPw%3D%3D_001099193-FS_FILES-4af5b01c-5800-480c-8b88-019d39b94cd9%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 2291.pdf<a><\/li><li><a href=\"\/download-titulus?id=Kv0lH6SW66UOyB9eBDXT5Q%3D%3D_001099185-FS_FILES-e407832e-d661-4c7f-ac08-3792f0c56f0e%5B2%5D.pdf\" target=\"_blank\">Ordine n. 7301397 omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>21\/06\/2023<\/td><td>20\/06\/2023<\/td><td>2023-UNVACLE-0010355<\/td><td>Integrazione all\u2019autorizzazione alla spesa per la fornitura di gas naturale da riscaldamento per la sede dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, sita in Saint-Christophe, per il periodo 1\u00b0 febbraio 2023 \u2013 28 febbraio 2023, a seguito di ingresso nel \u201cservizio di ultima istanza\u201d, gestito dalla ditta Hera Comm s.p.a., P.IVA 02221101203 \u2013 CIG ZCA3B5F039<\/td><td><ul><li><a href=\"\/download-titulus?id=qS2nfRBf0LYEbCVhiXf2%2Fw%3D%3D_001099459-FS_FILES-52bb385c-23ee-4a3c-910a-9b202d6c9443%5B1%5D.pdf\" target=\"_blank\">PD integrazione gas.pdf<a><\/li><li><a href=\"\/download-titulus?id=wwnuUo%2B0182NOBV6%2BRsplQ%3D%3D_001099444-FS_FILES-507e1705-ece4-4c12-b3e2-f0fd40ec76e5%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 2306.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>18\/07\/2023<\/td><td>17\/07\/2023<\/td><td>2023-UNVACLE-0011963<\/td><td>Affidamento alla ditta Bunder Company s.r.l. di Bari., P. IVA 07734810729, della fornitura e consegna di n. 30 chiavi triangolari per dissuasori di sosta da installare presso la sede ex hotel Ambassador, in Aosta - CIG ZC93BDEC3B.<\/td><td><ul><li><a href=\"\/download-titulus?id=cdeC25GbbQKA3te5o7k3aA%3D%3D_001105314-FS_FILES-04562918-3533-483c-8cdb-347f12b4bb7c%5B1%5D.pdf\" target=\"_blank\">PD Chiavi triangolari dissuasori.pdf<a><\/li><li><a href=\"\/download-titulus?id=BsT4HiW%2BmPrNq14fBmLWhg%3D%3D_001105277-FS_FILES-8709aba5-575a-423a-8525-9fab7df83b38%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=XB1LJwVh5cxotIxYIOo9qQ%3D%3D_001105057-FS_FILES-84a3402b-f750-4a0d-b3ed-b45cf90d4258%5B3%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7343646_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>24\/07\/2023<\/td><td>21\/07\/2023<\/td><td>2023-UNVACLE-0012335<\/td><td>Provvedimento Dirigente Area Finanza e Patrimonio - Affidamento diretto alla ditta Blo Italia S.r.l., P. Iva 12758180157, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, della fornitura di materiale di cancelleria e di primo soccorso per l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Trattativa Diretta (TD) nell\u2019ambito del Mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A\u2013 CIG ZAC3BE523A<\/td><td><ul><li><a href=\"\/download-titulus?id=ospr2Ez%2FUSmGLOm5f3AbVA%3D%3D_001106950-FS_FILES-4998108f-d461-48a4-bc09-c31f1ec7e8b5%5B1%5D.pdf\" target=\"_blank\">PD_Cancelleria.pdf<a><\/li><li><a href=\"\/download-titulus?id=vRpJgfCEGcKDFzBZPKoxxQ%3D%3D_001106931-FS_FILES-7b00fab0-0e3e-4a21-98b5-d35f7248ed1c%5B1%5D.pdf.p7m\" target=\"_blank\">Lettera invito Cancelleria e PS.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=WCawNOmIttJ3dxJ9uqiWjQ%3D%3D_001106932-FS_FILES-959b862d-7598-4735-88d2-abc9738d5ae2%5B1%5D.pdf.p7m\" target=\"_blank\">OE_NG3671607_L0_NP788714.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=Uc2n76zRF0aGN4gSZqdwew%3D%3D_001106934-FS_FILES-2c190d69-fc7d-4a9e-8ab3-8f8e1fa7de6d%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=DJXCgjzkipPsAyD5ybiqMQ%3D%3D_001107030-FS_FILES-aca6e159-039e-4d4d-8439-aa8df57bc19b%5B2%5D.pdf\" target=\"_blank\">PV 1324 17-07-2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>08\/08\/2023<\/td><td>07\/08\/2023<\/td><td>2023-UNVACLE-0013085<\/td><td>Affidamento diretto alla ditta Valmatic S.R.L., P. IVA 00611860073, della fornitura ed installazione di n. 3 refrigeratori d\u2019acqua a rete idrica, in noleggio per 12 mesi e di n. 3 bombole di CO2 da 10 kg. presso le sedi dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aosta, rinnovabile di ulteriori 12 mesi. CIG ZE93BD7179<\/td><td><ul><li><a href=\"\/download-titulus?id=JhU0q%2Be18TenBolTvBxY9Q%3D%3D_001110067-FS_FILES-46ce0b09-a608-4c60-9256-cf708a94d427%5B1%5D.pdf\" target=\"_blank\">PD refrigeratori acqua a rete idrica.pdf<a><\/li><li><a href=\"\/download-titulus?id=kD8YK86Ff8kwTyUjyrPwrg%3D%3D_001110065-FS_FILES-b8be9be6-c521-4704-9c83-6a293773cf70%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 2774.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>18\/09\/2023<\/td><td>15\/09\/2023<\/td><td>2023-UNVACLE-0014997<\/td><td>Proroga tecnica dell\u2019affidamento alla ditta CBT s.n.c., P.IVA 01084170073, del servizio di manutenzione ordinaria e assistenza tecnica per l\u2019impianto di rilevazione fumi ubicato presso la sede dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste di Saint-Christophe (AO), dal 15 settembre 2023 al 31 dicembre 2023, nelle more dell\u2019adesione alla Convenzione Consip del Facility Management 4 \u2013 Lotto 2. CIG ZAA37B6DCD<\/td><td><ul><li><a href=\"\/download-titulus?id=j7f8kEJrqU6lK9%2BWzzB%2F4A%3D%3D_001116905-FS_FILES-fb577ab3-d27c-4949-8b2d-8eb2aaff9f26%5B1%5D.pdf\" target=\"_blank\">PD Cbt.pdf<a><\/li><li><a href=\"\/download-titulus?id=WvNusHOLxM72p1LDEI%2FUIw%3D%3D_001116877-FS_FILES-6c183461-8655-4de7-a358-a671f53b4065%5B1%5D.pdf\" target=\"_blank\">Scrittura contabile.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>25\/09\/2023<\/td><td>22\/09\/2023<\/td><td>2023-UNVACLE-0015365<\/td><td>Affidamento diretto alla ditta ITA S.r.l., P. Iva 01593590605, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, dell\u2019erogazione di un corso di formazione dal titolo \u201cGli stati delle fatture in PCC: automatismi, allineamenti con il gestionale contabile e interventi specifici degli Enti\u201d, erogato in diretta streaming, rivolto alla dipendente Alessia Silvetti dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Ordinativo di Esecuzione Immediata nell\u2019ambito del mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 CIG Z633C5BB5E.<\/td><td><ul><li><a href=\"\/download-titulus?id=jtUpA%2FbQhbVHgXiviQRV8A%3D%3D_001119212-FS_FILES-81b73d36-9a83-4a8e-aef2-aa487e5ec18b%5B1%5D.pdf\" target=\"_blank\">PD Corso di formazione.pdf<a><\/li><li><a href=\"\/download-titulus?id=XyUhzK5%2BnfBlBlOpRZI0UQ%3D%3D_001119213-FS_FILES-8cbde7c0-7626-491e-bf44-f5109ff3606c%5B1%5D.pdf\" target=\"_blank\">Programma corso di formazione.pdf<a><\/li><li><a href=\"\/download-titulus?id=8P5XHg%2FltonSIakMbUVluw%3D%3D_001119214-FS_FILES-673aeb6a-20a1-40d8-b6a9-010560b9c154%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=eZM76tSmMTGSN5SFLcX13w%3D%3D_001119215-FS_FILES-e921377e-a1f6-4ced-8178-8d54ce2b691a%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7395274.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>02\/10\/2023<\/td><td>29\/09\/2023<\/td><td>2023-UNVACLE-0015806<\/td><td>Affidamento alla ditta Scotta s.r.l., P.IVA 02584100040, della fornitura e sostituzione di alcune componenti relative agli impianti idricosanitari non funzionanti presso gli edifici utilizzati dall\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG ZF43C4E482.<\/td><td><ul><li><a href=\"\/download-titulus?id=tQp3CeFOfwngvnkMWWJXpg%3D%3D_001120365-FS_FILES-70c5ebd0-bb58-4d83-b12d-51c67874dedc%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=im6J8is%2BfNxez0pU1XeAVw%3D%3D_001120366-FS_FILES-30b5a3d1-d527-4a17-b1a0-4d8b517f6dbd%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - Extra franchigia.pdf<a><\/li><li><a href=\"\/download-titulus?id=lGp4PlxEAE5pBdcljLPH3Q%3D%3D_001120572-FS_FILES-9a933ca5-9b82-4f51-9e86-8c141d3f1c9d%5B1%5D.pdf\" target=\"_blank\">PD Scotta.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>11\/10\/2023<\/td><td>10\/10\/2023<\/td><td>2023-UNVACLE-0016307<\/td><td>Adesione alla Convenzione di Consip s.p.a. denominata \u201cGas Naturale 15 bis\u201d per il servizio di fornitura di gas naturale per il riscaldamento della sede dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, sita in Saint-Christophe, per il periodo 1\u00b0 gennaio 2024 \u2013 31 dicembre 2024. CIG convenzione Lotto 1: 96772249DE - CIG derivato: A01899C1E8<\/td><td><ul><li><a href=\"\/download-titulus?id=WpW25orx5P3xBM3JJ%2F%2B10Q%3D%3D_001122844-FS_FILES-61190f00-982b-467c-86e7-4bb6f25af4f4%5B1%5D.pdf\" target=\"_blank\">PD_conv gas naturale 15bis.pdf<a><\/li><li><a href=\"\/download-titulus?id=2vG18jBTLROsKcP9ApCWTQ%3D%3D_001122845-FS_FILES-59885f86-94f2-4a0e-9bbf-347b7b226479%5B1%5D.pdf\" target=\"_blank\">ORDINE_7431527.pdf<a><\/li><li><a href=\"\/download-titulus?id=mviYq9fECSmnK1rg7sYxkw%3D%3D_001122580-FS_FILES-38f478aa-3224-4799-9793-b0a0194e9490%5B1%5D.pdf\" target=\"_blank\">GN15 BIS - Allegato 1 - Elenco dei punti di prelievo r0.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>03\/11\/2023<\/td><td>02\/11\/2023<\/td><td>2023-UNVACLE-0017686<\/td><td>Provvedimento del Dirigente Area Finanza e Patrimonio - Affidamento alla ditta Energy Salento Impianti s.r.l., P.IVA 08193950964, della manutenzione all\u2019impianto antincendio, presso la sede di Strada Cappuccini 2\/A, finalizzata al ripristino del corretto funzionamento \u2013 CIG Z1F3CDD075<\/td><td><ul><li><a href=\"\/download-titulus?id=GV0w6OxIyHxlG%2F9B7IA%2Bzg%3D%3D_001128133-FS_FILES-228a1905-5cd2-4bc6-9e58-947018163e73%5B1%5D.pdf\" target=\"_blank\">PD Energy Salento.pdf<a><\/li><li><a href=\"\/download-titulus?id=Jw6FLcyTkZRuG8uuIe%2BoFQ%3D%3D_001127140-FS_FILES-f98da572-85ca-4ab5-a58e-6304915a9023%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>08\/11\/2023<\/td><td>07\/11\/2023<\/td><td>2023-UNVACLE-0017993<\/td><td>Provvedimento del Dirigente Area Finanza e Patrimonio - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Mediaconsult S.r.l., P.IVA 07189200723, di un servizio per l\u2019erogazione di un corso di formazione dal titolo \u201cGli Affidamenti sotto soglia tra procedura, documentazione, MePa e il nuovo Codice dei Contratti \u2013 II Edizione\u201d, destinato ad un dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG ZB13D0F58E<\/td><td><ul><li><a href=\"\/download-titulus?id=KNBMcvgXwjIVGSGy0eihWQ%3D%3D_001129304-FS_FILES-f3669a63-4546-4f88-9d97-7b3b2d42cb4c%5B1%5D.pdf\" target=\"_blank\">PD_Corso appalti 9.11.pdf<a><\/li><li><a href=\"\/download-titulus?id=Nlv2uLyAC1tCJ0AwtgVOpg%3D%3D_001129128-FS_FILES-008272c7-51ee-4a34-85d1-e9f9d9fafc26%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=MMRRdEuU%2FCWwP6ym2XAXpA%3D%3D_001129129-FS_FILES-2b5862bd-9342-4fbc-beb1-192db0af4fb4%5B1%5D.pdf\" target=\"_blank\">Programma corso - MePa e nuovo Codice.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>08\/11\/2023<\/td><td>07\/11\/2023<\/td><td>2023-UNVACLE-0017994<\/td><td>Provvedimento del Dirigente Area Finanza e Patrimonio - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta La Clavalit\u00e9 di Bottel & C. S.n.c., P. IVA 00374990075, per la fornitura di bandiere per l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG ZB73A8A3D1<\/td><td><ul><li><a href=\"\/download-titulus?id=jG1rNH9RlNK7G3JaQsGX4Q%3D%3D_001129305-FS_FILES-89a294fe-a4c4-400e-b33a-b301c678d98c%5B1%5D.pdf\" target=\"_blank\">PD Bandiere DEF.pdf<a><\/li><li><a href=\"\/download-titulus?id=lDg%2BmX%2By6YPytZMjz0bx5w%3D%3D_001129306-FS_FILES-7b24daee-4826-44ea-a4c6-15cb9b820bd3%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/11\/2023<\/td><td>13\/11\/2023<\/td><td>2023-UNVACLE-0018230<\/td><td>Provvedimento del Dirigente Area Finanza e Patrimonio - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b), del D.lgs. n. 36\/2023, alla ditta Tipografia Pesando Snc di Pesando-Gamacchio & Macr\u00ec, P. Iva 00466260072, ai sensi dell\u2019art. 120, comma 1, lettera a), del D.lgs. n. 36\/2023, della fornitura di biglietti da visita e timbro personalizzati \u2013 CIG Z023BE5182<\/td><td><ul><li><a href=\"\/download-titulus?id=7ajIRc19jE%2BNMOe57EBZjQ%3D%3D_001130368-FS_FILES-c3dac8b3-4d78-4ee2-bd32-b91cdf75c404%5B1%5D.pdf\" target=\"_blank\">PD_Biglietti da visita Rettrice.pdf<a><\/li><li><a href=\"\/download-titulus?id=R0SzcIN9idgvy68wi8lccA%3D%3D_001130369-FS_FILES-d03718c0-023f-49d2-83ad-ad5d07939b3f%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>23\/11\/2023<\/td><td>22\/11\/2023<\/td><td>2023-UNVACLE-0018905<\/td><td>Provvedimento Dirigente Area Finanza e Patrimonio - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Barbero Pietro S.p.A., P. IVA 02073350015, della fornitura di carta per stampanti, materiale di cancelleria e primo soccorso per l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste\u2013 CIG ZCB3CF2DC8<\/td><td><ul><li><a href=\"\/download-titulus?id=E%2FhaBFqhYvP8tpt7QnNivw%3D%3D_001133586-FS_FILES-49735a5a-6fd9-4e79-8224-049f30a7eba8%5B1%5D.pdf\" target=\"_blank\">PD_Cancelleria.pdf<a><\/li><li><a href=\"\/download-titulus?id=vF%2Focgqwko1u7RzBeTTixw%3D%3D_001133587-FS_FILES-99aa3836-cfd4-4a61-93f0-0636c8af0b2b%5B1%5D.pdf.p7m.p7m\" target=\"_blank\">OE_NG3832558_L0_NP969622.pdf.p7m.p7m<a><\/li><li><a href=\"\/download-titulus?id=qoeeXHNlo2lQZeL1jqaAog%3D%3D_001133588-FS_FILES-039029d8-ac74-402f-ae49-9b205de2da44%5B1%5D.pdf.p7m.p7m\" target=\"_blank\">offerta.pdf.p7m.p7m<a><\/li><li><a href=\"\/download-titulus?id=hCCNob9Pqxoo08pMU0t69g%3D%3D_001133589-FS_FILES-5385005d-9355-4dc7-bfcc-835785299b9c%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/12\/2023<\/td><td>13\/12\/2023<\/td><td>2023-UNVACLE-0020288<\/td><td>Provvedimento Dirigente Area Finanza e Patrimonio - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Maggioli S.p.A., P. IVA 02066400405, della fornitura del servizio internet \u201cAppalti e Contratti\u201d, per il periodo 16 dicembre 2023 \u2013 15 dicembre 2026 \u2013 CIG Z703D56802. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=zzvYnkrIKiOkkWqhE41RuA%3D%3D_001139871-FS_FILES-5410ffdb-8255-4591-94c8-cc1e2626bbca%5B1%5D.pdf\" target=\"_blank\">PD abbonamento AppltieContratti.pdf<a><\/li><li><a href=\"\/download-titulus?id=G%2B2SIfbXiXjIjczXhntwEg%3D%3D_001139872-FS_FILES-cc48f276-10cb-4bb6-a68a-0af06d3dccf1%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/12\/2023<\/td><td>13\/12\/2023<\/td><td>2023-UNVACLE-0020291<\/td><td>Provvedimenti Dirigente Area Finanza e Patrimonio - Integrazione all\u2019affidamento del servizio di reception\/portierato e di accoglienza da effettuarsi presso gli edifici in uso all\u2019Universit\u00e0 della Valle d\u2019Aosta - Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, per il periodo 1\u00b0 gennaio 2023 \u2013 31 dicembre 2023. Applicazione entro il quinto d\u2019obbligo del contratto. CIG n. ZA3392822E.<\/td><td><ul><li><a href=\"\/download-titulus?id=iaLMuNx6HEBuCiLJH9uA4Q%3D%3D_001139876-FS_FILES-93b10f9b-ae6f-4716-9bec-c8e9359593f4%5B1%5D.pdf\" target=\"_blank\">PD estensione quinto ditta Elite Security.pdf<a><\/li><li><a href=\"\/download-titulus?id=1iep9KbpgK8MFFcoZZHbyQ%3D%3D_001139877-FS_FILES-47715ca9-9b0d-4f03-84e7-9a96bcb29974%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>25\/12\/2023<\/td><td>22\/12\/2023<\/td><td>2023-UNVACLE-0021119<\/td><td>Adesione alla Convenzione della Centrale Unica di Committenza di IN.VA. s.p.a. denominata \u201cServizio di vigilanza armata comprensivo di servizi di vigilanza fissa, vigilanza ispettiva, teleallarme (antintrusione\/antincendio), televigilanza e relativi servizi accessori rivolti alla Regione Autonoma Valle d\u2019Aosta, agli Enti Locali e tutti gli Enti aderenti alla Centrale Unica di Committenza per servizi e forniture, ad eccezione dell\u2019Azienda USL della Valle d\u2019Aosta - Edizione 1 - LOTTO 1\u201d, per il per il periodo 1\u00b0 gennaio 2024 \u2013 31 dicembre 2027. CIG master 99066076B6 - CIG derivato n. A0436BE59C.<\/td><td><ul><li><a href=\"\/download-titulus?id=ldNtYrZJxYy2%2B0uPK5QlSw%3D%3D_001142961-FS_FILES-0fe8ea66-02ef-44a6-9f4d-df2ea8a73d63%5B1%5D.pdf\" target=\"_blank\">PD convenzione vigilanza2.pdf<a><\/li><li><a href=\"\/download-titulus?id=tQ15RVQsEoLXScHkOx%2BBmg%3D%3D_001142889-FS_FILES-f6bfec61-f4a5-4d29-ae19-7e55420f81d7%5B2%5D.pdf\" target=\"_blank\">Ordinativo_di_Fornitura - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>25\/12\/2023<\/td><td>22\/12\/2023<\/td><td>2023-UNVACLE-0021120<\/td><td>Provvedimento Dirigente Area Finanza e Patrimonio - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta TACCONI & DESIGN  SRL, P.IVA 02015810126, della fornitura di n. 100 sedie da ufficio da destinare al personale tecnico-amministrativo e docente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste - CIG Z083DE1045. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=aBm%2BNA%2F3GZVwFiUv0CqeIg%3D%3D_001142966-FS_FILES-c044fa0e-80c2-4a37-8f81-c731f07ba7fe%5B1%5D.pdf\" target=\"_blank\">PD Sedie dipendenti-docenti.pdf<a><\/li><li><a href=\"\/download-titulus?id=yScb6VTv9St%2BGzMBseY%2B0A%3D%3D_001142898-FS_FILES-8c6a815f-d4d0-4b55-b730-bf99147f34ad%5B1%5D.pdf\" target=\"_blank\">Scrittura contabile.pdf<a><\/li><li><a href=\"\/download-titulus?id=LvAlM2xnpaaPHAWilAT5vQ%3D%3D_001142897-FS_FILES-e1e0d049-5e2b-4278-8202-968c6bb947ec%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7564572 - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>13\/01\/2023<\/td><td>12\/01\/2023<\/td><td>2023-UNVACLE-0000604<\/td><td>Provvedimento del Direttore Generale - Affidamento al Consorzio Interuniversitario Cineca, P.IVA 00502591209, dell\u2019erogazione di un corso di formazione denominato \u201cI controlli di fine anno e le chiusure contabili\u201d, erogato in modalit\u00e0 conf-call, rivolto ad una dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, ai sensi dell\u2019articolo 1, comma 2, lettera a), del Decreto-legge 16 luglio 2020, n. 76, convertito, con modificazioni, dalla Legge 11 settembre 2020, n. 120, come modificato dal Decreto-legge 31 maggio 2021, n. 77. Autorizzazione alla spesa<\/td><td><ul><li><a href=\"\/download-titulus?id=63gHkirJtWNpSqFdNjGUCQ%3D%3D_001063929-FS_FILES-950abbdd-245b-49f8-8e88-841d33a629d8%5B1%5D.pdf\" target=\"_blank\">Provvedimento Corso Cineca - Chiusure contabili.pdf<a><\/li><li><a href=\"\/download-titulus?id=4jdwatrXBirrHiDAG6%2BUmA%3D%3D_001063837-FS_FILES-70355646-59d5-4e8d-89c0-3804b73ad97a%5B1%5D.pdf\" target=\"_blank\">Scrittura contabile.pdf<a><\/li><li><a href=\"\/download-titulus?id=KTXpmWZ0ErawQBDQXOGH8Q%3D%3D_001063832-FS_FILES-df463dbc-e54f-4051-b5cc-d959265f6851%5B1%5D.pdf\" target=\"_blank\">Programma Corso I controlli di fine anno e le Chiusure contabili.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>17\/01\/2023<\/td><td>16\/01\/2023<\/td><td>2023-UNVACLE-0000741<\/td><td>Affidamento diretto alla ditta Boschis Lab, P.IVA 12403390011, per la fornitura e la posa di parete arredata su misura, in legno, nell\u2019ambito del progetto \u201cRiqualificazione Biofila dell\u2019Aula C3 Univda\u201d \u2013 CIG Z1638D0D3F<\/td><td><ul><li><a href=\"\/download-titulus?id=SPb8WyXbXALV2uViAWgHZA%3D%3D_001064486-FS_FILES-dc0481ad-a6c0-4cf9-bd73-6eceefef762d%5B1%5D.pdf\" target=\"_blank\">Provvedimento Boschis Lab.pdf<a><\/li><li><a href=\"\/download-titulus?id=sIeRqtQPPnvtVM2vma6xAA%3D%3D_001064008-FS_FILES-50867470-3eb8-49c0-b9c1-7070498fbedd%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 10.pdf<a><\/li><li><a href=\"\/download-titulus?id=CYj2ohziC4L3cT4VqNHewQ%3D%3D_001064009-FS_FILES-e2c9f7ca-c318-4807-ac6c-27ba986bfc64%5B1%5D.pdf\" target=\"_blank\">Offerta BOSCHIS LAB n. 217 - 02 - Universit\u00e0 di Aosta - 23 Novembre 2022.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>17\/01\/2023<\/td><td>16\/01\/2023<\/td><td>2023-UNVACLE-0000743<\/td><td>Provvedimento del Direttore generale - Affidamento alla ditta Officine Zoum Societ\u00e0 consortile a responsabilit\u00e0 limitata, P. IVA IT01252160070, della realizzazione di servizi di comunicazione per l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste per gli anni 2023-2025. Autorizzazione alla spesa - CIG Z2538D0972.<\/td><td><ul><li><a href=\"\/download-titulus?id=6c6MaprzvVSUkS8bgMLM2Q%3D%3D_001064488-FS_FILES-044f3f02-d1ac-4c66-8c38-a38f367bd657%5B1%5D.pdf\" target=\"_blank\">01_Provvedimento Zoum.pdf<a><\/li><li><a href=\"\/download-titulus?id=iB4g%2B%2FzbG4Apd4cq7XBmjg%3D%3D_001061206-FS_FILES-79e880cc-50e1-4639-90e3-a0c8a6a782b9%5B1%5D.pdf\" target=\"_blank\">BustaEconomica.pdf<a><\/li><li><a href=\"\/download-titulus?id=Cj9vqiJA9ITrcDWSEuFp1Q%3D%3D_001063902-FS_FILES-f393ed77-5376-4af3-b51d-9fb26a0a7110%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 3 - ZOUM.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>19\/01\/2023<\/td><td>18\/01\/2023<\/td><td>2023-UNVACLE-0000913<\/td><td>Acquisizione di ulteriori corsi di formazione in modalit\u00e0 e-learning, per lavoratori a rischio basso della durata di 4 ore, rivolto al personale dell\u2019Universit\u00e0 della Valle d\u2019Aosta Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, in adesione alla convenzione di Consip s.p.a. denominata \u201cConvenzione per la prestazione dei servizi relativi alla gestione integrata della salute e sicurezza sui luoghi di lavoro per le pubbliche amministrazioni, ai sensi dell\u2019articolo 26, legge 23 dicembre 1999 n. 488 e s.m.i. e dell\u2019articolo 58, legge 23 Dicembre 2000 n. 388, ed. 4\u201d CIG Convenzione ed. 4 Lotto 1 6522411FD0 - Affidamento alla ditta Sintesi S.P.A., in R.T.I., con sede legale in Roma, Via Lima n. 41 - 00198, P. IVA 03533961003, - CIG n. Z2839751D5<\/td><td><ul><li><a href=\"\/download-titulus?id=n%2B76SqgykNm%2FaT%2BxYFtt7g%3D%3D_001065245-FS_FILES-71dba2d9-86e4-4f23-a47a-c97cf9fcbdba%5B1%5D.pdf\" target=\"_blank\">Provvedimento corsi specifici sicurezza CONSIP.pdf<a><\/li><li><a href=\"\/download-titulus?id=QM3tZ%2F8iu%2FAwadi0l%2BABMQ%3D%3D_001065119-FS_FILES-1391897b-f6c6-47e2-a493-a9d13f62b7fc%5B1%5D.pdf\" target=\"_blank\">ORDINE_7105671.pdf<a><\/li><li><a href=\"\/download-titulus?id=lq5tMzs%2BaXICtMpgub0HFg%3D%3D_001065235-FS_FILES-156a57d2-7bba-4fdc-b3a5-5b4da440ce30%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 81- Corsi Sintesi SpA.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>19\/01\/2023<\/td><td>18\/01\/2023<\/td><td>2023-UNVACLE-0000914<\/td><td>Affidamento alla societ\u00e0 Telecom Italia S.p.A. di Milano (MI), mediante adesione alla convenzione Consip Telefonia mobile 8, Lotto 1, dei servizi di telefonia mobile e noleggio apparati \u2013 CIG Z9D353C286 - Autorizzazione spesa per l\u2019anno 2023<\/td><td><ul><li><a href=\"\/download-titulus?id=p%2FKlfBwslSjrT1gKDWyLqA%3D%3D_001065246-FS_FILES-2d160202-22a9-4f06-842a-634e2e18a723%5B1%5D.pdf\" target=\"_blank\">PD-TelefoniaMobile-Autorizzazione2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=Blrc92s3T6cxksrRUihDWQ%3D%3D_001065233-FS_FILES-467d9b36-da1e-44b5-a5b6-c01c188d33d1%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 80 - Telecom.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>24\/01\/2023<\/td><td>23\/01\/2023<\/td><td>2023-UNVACLE-0001126<\/td><td>Provvedimento del Direttore generale - Rettifica dei Provvedimenti del Direttore generale n. 93, del 21 giugno 2022, e n. 206, del 23 dicembre 2022 concernenti il conferimento degli incarichi di Particolare Posizione Organizzativa, nell\u2019ambito dei Servizi della Direzione generale dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste<\/td><td><ul><li><a href=\"\/download-titulus?id=bOy0yYLCDMKhNdMQTChylA%3D%3D_001066084-FS_FILES-685657f8-d663-4876-a175-762dbf27f715%5B1%5D.pdf\" target=\"_blank\">Provvedimento revoca autorizzazione alla spesa ppo 2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>24\/01\/2023<\/td><td>23\/01\/2023<\/td><td>2023-UNVACLE-0001164<\/td><td>Affidamento alla ditta Fastweb S.p.a. della fornitura dei servizi di telefonia alle condizioni previste dalla convenzione Consip \u201cTelefonia fissa e connettivit\u00e0 IP 5\u201d - CIG ZE8265DE4B - Autorizzazione spesa per l\u2019anno 2023<\/td><td><ul><li><a href=\"\/download-titulus?id=Uh5nha%2FsfKomi4fuRMPXpg%3D%3D_001066215-FS_FILES-55eec923-2b02-4d71-8808-69c2391cbc02%5B1%5D.pdf\" target=\"_blank\">PD - AutorizzazioneFastweb2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=iowFrYCZ8EWnivCU8dsYSw%3D%3D_001066189-FS_FILES-528c5a79-e2a4-4068-a9d4-b4a5de240e85%5B1%5D.pdf\" target=\"_blank\">Scrittura Coan.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>26\/01\/2023<\/td><td>25\/01\/2023<\/td><td>2023-UNVACLE-0001454<\/td><td>Affidamento alla ditta Ultrapromedia S.r.l., P. Iva 10324241008, della fornitura di un carrello pieghevole per l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Ordinativo di Esecuzione Immediata di acquisto nell\u2019ambito del mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 CIG Z78399915C.<\/td><td><ul><li><a href=\"\/download-titulus?id=AZiplCvpU%2BYVcWuFu3qPJw%3D%3D_001067047-FS_FILES-a846632e-1f11-43d5-9bd4-5eb8dadc0f5a%5B1%5D.pdf\" target=\"_blank\">PD Carrello.pdf<a><\/li><li><a href=\"\/download-titulus?id=ED3%2FoYUSHylNpz5Z%2BJZMuA%3D%3D_001066848-FS_FILES-94606dab-fa69-4fa5-baf8-79f98cb1d8a3%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN (2).pdf<a><\/li><li><a href=\"\/download-titulus?id=rg%2FbEgnvUGlV7xvuuyrlsA%3D%3D_001066729-FS_FILES-4f16f2d1-5e8e-48c8-aaa1-b56c0646d841%5B2%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7121892 omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/01\/2023<\/td><td>26\/01\/2023<\/td><td>2023-UNVACLE-0001511<\/td><td>Affidamento al Consorzio Interuniversitario sulla Formazione (CO.IN.FO) \u2013 P.IVA 06764560014 dell\u2019erogazione di un corso di formazione, dal titolo \u201cCome districarsi nella gestione dei progetti senza essere project manager professionali: una guida snella per la gestione dei progetti interni nelle Amministrazioni degli Atenei\u201d. Autorizzazione alla spesa. CIG Z1E39A3364.<\/td><td><ul><li><a href=\"\/download-titulus?id=teEWlheV3At3ZxwKc0nNjg%3D%3D_001067331-FS_FILES-4cecc5e0-8ba1-4123-af9a-a299a618ced0%5B1%5D.pdf\" target=\"_blank\">provv DG CO.IN.FO.pdf<a><\/li><li><a href=\"\/download-titulus?id=Zt%2BBh%2BBSbSql4AZI%2FsXxJg%3D%3D_001067165-FS_FILES-056f8c83-e9c9-4db2-b111-522317f4d73d%5B1%5D.pdf\" target=\"_blank\">programma corso.pdf<a><\/li><li><a href=\"\/download-titulus?id=oDpisPvHVX4NdGVWM1uiyw%3D%3D_001067166-FS_FILES-2a035d8f-df94-43a5-86cf-30c81c28492b%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-01-26T083651.673.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>31\/01\/2023<\/td><td>30\/01\/2023<\/td><td>2023-UNVACLE-0001689<\/td><td>Provvedimento del Direttore generale - Affidamento alle Ditte Terminal Video Italia Srl, P.IVA 03641340371, ed EBSCO Information Services Srl, P. IVA 11164410018, della fornitura di monografie italiane (Lotto 1) e straniere (Lotto 2) all\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste per il periodo 01\/01\/2023-31\/12\/2024. CIG Z79386EABF (Lotto 1 \u2013 monografie pubblicate da editori italiani), CIG Z9C386EB5B (Lotto 2 \u2013 monografie pubblicate da editori stranieri)<\/td><td><ul><li><a href=\"\/download-titulus?id=qEFLEIDMh3rRjHahbmdH9Q%3D%3D_001067989-FS_FILES-289270cd-4114-4c44-814c-790c2dfcce52%5B1%5D.pdf\" target=\"_blank\">Provv_affidamento_libri_2023-24.pdf<a><\/li><li><a href=\"\/download-titulus?id=LdxsmbNCoIshNcsA6qD0zQ%3D%3D_001067752-FS_FILES-dc8c1eae-63dd-4cd9-8ed9-c8c78a052f24%5B1%5D.pdf\" target=\"_blank\">Offerta_Terminal_Video_omissis.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2BwxpwrBDG7C2XOPZLbZp%2FQ%3D%3D_001067755-FS_FILES-3656bf22-ff94-46b3-90e1-6d3f5e7b722e%5B1%5D.pdf\" target=\"_blank\">Offerta_EBSCO_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>02\/02\/2023<\/td><td>01\/02\/2023<\/td><td>2023-UNVACLE-0001949<\/td><td>Provvedimento del Direttore generale - Affidamento alla Societ\u00e0 ITA srl dell\u2019erogazione di un corso di formazione dal titolo \u201cLa gestione del rapporto di lavoro dei docenti universitari\u201d, erogato in diretta streaming, rivolto ad una dirigente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste tramite ordine diretto di acquisto nell\u2019ambito del MePA, ai sensi dell\u2019articolo 1, comma 2, lettera a), del Decreto legge 16 luglio 2020, n. 76, convertito, con modificazioni, dalla Legge 11 settembre 2020, n. 120, come modificato dal Decreto legge 31 maggio 2021, n. 77, nel testo vigente. CIG Z2E39A2BF0. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=TnuOx3ibNriB1QEsmOWPGw%3D%3D_001068981-FS_FILES-7d38d00e-730f-4cba-8251-01dd3b256349%5B1%5D.pdf\" target=\"_blank\">PD Corso ITA 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=GfODYoUvvuprsQR1%2B%2B5XhQ%3D%3D_001068916-FS_FILES-24beaa48-551c-4e38-b544-fb6da6375a56%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 175 - Corso ITA.pdf<a><\/li><li><a href=\"\/download-titulus?id=g%2FiMBD1kfbIcXaEk9tPk0g%3D%3D_001068559-FS_FILES-b84a89b3-62c8-4ab6-b037-040113824e9b%5B1%5D.pdf\" target=\"_blank\">Bozza Oda omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>09\/02\/2023<\/td><td>08\/02\/2023<\/td><td>2023-UNVACLE-0002508<\/td><td>Provvedimento del Direttore generale - Affidamento diretto al Consorzio Interuniversitario Cineca, P.IVA 00502591209 e C.F.00317740371, dell\u2019erogazione di un corso di formazione denominato \u201cESSE3 Anagrafe Nazionale Studenti - Aggiornamenti\u201d  erogato in modalit\u00e0 e-learning blended, rivolto al personale dell\u2019Ufficio Sistemi informatici e Statistica dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste - Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=Jk6vat2bqLDTk6ZQUY5B6A%3D%3D_001070916-FS_FILES-6c63e49b-2884-48e3-8f0d-fcddc7af77e6%5B1%5D.pdf\" target=\"_blank\">Provv_corso_Cineca_ANS_Aggiornamenti_02 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=WM%2Bu4JFNifGGotDxLfGCNA%3D%3D_001070830-FS_FILES-48c11044-d4cc-4912-88d7-a77277c6fe49%5B1%5D.pdf\" target=\"_blank\">Prog_corso Cineca ANS -Aggiornamenti_02-23.pdf<a><\/li><li><a href=\"\/download-titulus?id=NFOO6RzFHFGP8Y871c6d1g%3D%3D_001070831-FS_FILES-3df7c1ce-1e3e-4b97-9b28-771350c23766%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 197.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>15\/02\/2023<\/td><td>14\/02\/2023<\/td><td>2023-UNVACLE-0002999<\/td><td>Affidamento alla ditta Crayon Software Experts Spain SL, P.Iva ESB87135968, della somministrazione di n. 50 licenze Authorised del pacchetto Premium di IBM SPSS e n. 50 licenze Authorised AMOS per il periodo 01 marzo 2023 \u2013 28 febbraio 2024 \u2013 CIG Z3F39D9A1E<\/td><td><ul><li><a href=\"\/download-titulus?id=3G6ASkJAamwsWfn8ji5h8A%3D%3D_001072960-FS_FILES-fd8d080d-0e10-4951-8188-8e902100eb76%5B1%5D.pdf\" target=\"_blank\">PD-SomministrazioneLicenzeSPSS-AMOS_Anno2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=OjpViAgOXahynsvgjA7mdg%3D%3D_001072865-FS_FILES-3e350fd0-4fdf-4f92-8b62-4664dd009f3b%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=Y9K8skvaNyLeT2CH7lBGqg%3D%3D_001072839-FS_FILES-f16f128c-2942-45ca-9cb2-667fcef5486a%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_ODA_7151962.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>02\/03\/2023<\/td><td>01\/03\/2023<\/td><td>2023-UNVACLE-0004021<\/td><td>Affidamento alla Ditta A.S.S.O. S.r.l. di Torino C.F. e P.IVA 01804310017 della fornitura della manutenzione annuale 2023 del software Net Time Evo dell\u2019Universit\u00e0 della Valle d\u2019Aosta - Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, tramite ordine diretto di acquisto nell\u2019ambito del MePa. CIG N. Z923A0D865. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=l9IZwS%2B%2FnMNVx%2F28rHjvig%3D%3D_001076622-FS_FILES-1b9d2473-3517-47f2-b3d6-aea98050f43f%5B1%5D.pdf\" target=\"_blank\">Provv.to Net Time canone annuale assistenza software 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=SDhjAWBfqYqejw3Eh359dw%3D%3D_001076186-FS_FILES-f9d61343-8b18-4d1f-a9c5-a4eab69498d1%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 533 - ASSO srl.pdf<a><\/li><li><a href=\"\/download-titulus?id=eqig58MbhKdsrBXQbjUdIw%3D%3D_001076082-FS_FILES-2b3ad4af-d6da-41b8-b834-fa91a8c44481%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7164633.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>07\/03\/2023<\/td><td>06\/03\/2023<\/td><td>2023-UNVACLE-0004366<\/td><td>Provvedimento del Direttore generale - Affidamento diretto alla ditta Baranzelli NaTur S.r.l., P. IVA 00434360038, del servizio di organizzazione trasporto studenti per la giornata di orientamento \"UNIversoVda 2023\u201d del 10 marzo 2023. \u2013 CIG n. Z443A143D0.<\/td><td><ul><li><a href=\"\/download-titulus?id=q8x0s2ky0GUQTRyx%2BJJtyg%3D%3D_001077901-FS_FILES-1cde5ebf-9721-4429-868d-01d0b25ebd68%5B1%5D.pdf\" target=\"_blank\">PD_Affidamento diretto_Baranzelli.pdf<a><\/li><li><a href=\"\/download-titulus?id=JmbhooDhEeQs5uMJWKehBQ%3D%3D_001077116-FS_FILES-244b0410-6409-456b-aae8-d0fd7c0a03c7%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 680_Noleggio pullman.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>08\/03\/2023<\/td><td>07\/03\/2023<\/td><td>2023-UNVACLE-0004453<\/td><td>Affidamento diretto ai sensi dell\u2019art. 1, comma 2, lettera a) della Legge n. 120\/2020 e ss.mm.ii. (Conversione in legge, con modificazioni, del Decreto-legge 16 luglio 2020, n. 76, recante \u00abMisure urgenti per la semplificazione e l\u2019innovazione digitale\u00bb), del servizio di Controllo di Primo Livello (First Level Control - FLC) del progetto \u201cAlpSatellites. Managing the transition to hybrid work and satellite offices to revitalize remote mountain areas\u201d, in risposta al bando \u201cInterreg \u2013 Alpine Space 2021\/2027\u201d - CUP B67G22000380007 \u2013 CIG ZDC39C4DE5<\/td><td><ul><li><a href=\"\/download-titulus?id=%2FPi4OZqPTKLRlGI1cc%2BXOg%3D%3D_001077624-FS_FILES-c5034705-43a3-4061-afe5-782d95eb6923%5B3%5D.pdf\" target=\"_blank\">Provvedimento affidamento FLC - Omissis.pdf<a><\/li><li><a href=\"\/download-titulus?id=idPvxwzArYU96fR2FgSBTQ%3D%3D_001077626-FS_FILES-ee05902f-f75d-4154-9f07-d0ebad651642%5B2%5D.pdf\" target=\"_blank\">Schema di contratto - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>10\/03\/2023<\/td><td>09\/03\/2023<\/td><td>2023-UNVACLE-0004554<\/td><td>Affidamento alla ditta ITD SOLUTIONS S.P.A., di Milano (MI), mediante adesione alla convenzione Consip Apparecchiature Multifunzione in noleggio 1 \u2013 Lotto 2, della fornitura a noleggio di n. 3 multifunzione A3 monocromatiche per un periodo di 48 mesi da destinarsi alle sedi di Loc. Le Grand Chemin 181, in Saint Christophe, e Via Duca degli Abruzzi 4, in Aosta \u2013 CIG ZBD3A3D9E3<\/td><td><ul><li><a href=\"\/download-titulus?id=byfJQPukbLjC8xEf%2F6%2B0%2FQ%3D%3D_001078666-FS_FILES-92e2a6e9-efc8-4be2-8ce1-8dfc61256c05%5B1%5D.pdf\" target=\"_blank\">PD-Noleggio_Fotocopiatori_2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=1KQP1NndA%2BYAfScSSB%2B%2F1A%3D%3D_001078513-FS_FILES-c6d20973-2af2-4216-831f-c52cb62d6617%5B2%5D.pdf\" target=\"_blank\">Bozza ODA_7178926.pdf<a><\/li><li><a href=\"\/download-titulus?id=UqZQfM0omQlxth8bY%2BdvzA%3D%3D_001078527-FS_FILES-f082cbfc-dc20-4fa6-8be8-007efe6e8768%5B1%5D.pdf\" target=\"_blank\">ScritturaCoan.pdf<a><\/li><li><a href=\"\/download-titulus?id=elglus1ntKD4fUuWEj7bnQ%3D%3D_001078519-FS_FILES-c212a94a-6bd4-4478-a80c-2f3f80e77fc2%5B3%5D.pdf\" target=\"_blank\">Corrispettivi_Lotto_2.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>10\/03\/2023<\/td><td>09\/03\/2023<\/td><td>2023-UNVACLE-0004555<\/td><td>Affidamento diretto alla ditta Boschis Lab, P.IVA 12403390011, per la fornitura e la posa di parete arredata su misura, in legno, nell\u2019ambito del progetto \u201cRiqualificazione Biofila dell\u2019Aula C3 Univda\u201d \u2013 CIG Z1638D0D3F \u2013 Integrazione IVA per passaggio da regime forfettario a regime ordinario<\/td><td><ul><li><a href=\"\/download-titulus?id=V4nwluLxBdzcapxY0P94ww%3D%3D_001078667-FS_FILES-b3a9217f-eb0f-4a01-b349-75e033626ba0%5B1%5D.pdf\" target=\"_blank\">PD integrazione IVA Boschis.pdf<a><\/li><li><a href=\"\/download-titulus?id=SVobf4kR%2F78AyUbmTlSUZQ%3D%3D_001078510-FS_FILES-829e28b0-a49a-417d-8eed-e473a3e675bc%5B1%5D.pdf\" target=\"_blank\">Cambio ragione sociale BOSCHIS LAB1.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>20\/03\/2023<\/td><td>17\/03\/2023<\/td><td>2023-UNVACLE-0005101<\/td><td>Adesione istituzionale dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste all\u2019AICUN - Associazione Italiana Comunicatori d\u2019Universit\u00e0 per l\u2019anno 2023. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=k3ix1ex5t4tJT1o72XpKUg%3D%3D_001080428-FS_FILES-42eb7bdf-0918-4a8a-ade2-25a836677d7a%5B1%5D.pdf\" target=\"_blank\">00_PD Rinnovo iscrizione AICUN 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=mRFDhmMW9Xn1ojgWv1pQlQ%3D%3D_001080376-FS_FILES-ff1e1a9e-45c0-48e0-bebd-0fe9792c7120%5B2%5D.pdf\" target=\"_blank\">Richiesta pagamento quota associativa 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=9pW08C7WSGsw7Frc7%2BfEWw%3D%3D_001080397-FS_FILES-0924623b-47b3-4c40-9c38-c4a4fac6f780%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 900 - GU n. 52_AICUN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>20\/03\/2023<\/td><td>17\/03\/2023<\/td><td>2023-UNVACLE-0005102<\/td><td>Provvedimento del Direttore Generale - Affidamento diretto alla ditta Bleka s.r.l. Unipersonale, P. Iva 01499130332, della fornitura di un Notebook e un Mouse, finalizzati allo svolgimento delle attivit\u00e0 inerenti al progetto \u201cMEDIA (Museo Emozionale DIgitale multimediale Avanzato)\u201d, in risposta al Bando \u201cAggregazioni R&S\u201d, promosso dall\u2019Assessorato Sviluppo economico, formazione e lavoro della Regione Autonoma Valle d\u2019Aosta - CUP B19J22001510007 - CIG Z3D3A5A781.<\/td><td><ul><li><a href=\"\/download-titulus?id=PR5OPsju5P%2BcOpKlzw5LjQ%3D%3D_001080429-FS_FILES-7192d3d9-5f67-4468-acb1-faf33c96f900%5B1%5D.pdf\" target=\"_blank\">PD_Notebook+Mouse.pdf<a><\/li><li><a href=\"\/download-titulus?id=tKzsOG%2FeyFjECDEbJoUFPA%3D%3D_001080322-FS_FILES-57bd31b4-895f-4d0e-ac03-4773b01c1ecd%5B1%5D.pdf\" target=\"_blank\">Ordinativo esecuzione immediata n. 7193475 - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>20\/03\/2023<\/td><td>17\/03\/2023<\/td><td>2023-UNVACLE-0005103<\/td><td>Provvedimento del Direttore Generale - Affidamento diretto alla ditta ESRI ITALIA S.p.A  P. IVA 03837421001 della fornitura di un pacchetto di n. 5 licenze annuali del software \u201cArcGIS\u201d finalizzato allo svolgimento delle attivit\u00e0 inerenti il progetto MEDIA (Museo Emozionale DIgitale multimediale Avanzato) presentato dall\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, di cui al Bando \u201cAggregazioni R&S\u201d approvato con la deliberazione della Giunta della Regione Valle d\u2019Aosta n. 890 in data 19 luglio 2021, di cui \u00e8 Responsabile scientifico la Prof.ssa Anna Maria Pioletti - codice: MEDIA2022 - CUP B19J22001510007 CIG Z0939F13C0.<\/td><td><ul><li><a href=\"\/download-titulus?id=aqSjj5Wo2Po9w0lF9s6mlg%3D%3D_001080430-FS_FILES-dbd37907-ad50-47c5-817e-cdf03b3928d2%5B1%5D.pdf\" target=\"_blank\">Provvedimento DG - software.pdf<a><\/li><li><a href=\"\/download-titulus?id=a%2BUJDvzoOFOBidoWc7493Q%3D%3D_001080314-FS_FILES-175f4f36-f9c0-4ad2-8d23-91deac8c6a3b%5B1%5D.pdf\" target=\"_blank\">Ordinativo esecuzione immediata n. 7193011 Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>21\/03\/2023<\/td><td>20\/03\/2023<\/td><td>2023-UNVACLE-0005199<\/td><td>Provvedimento del Direttore Generale - Affidamento alla ditta Canva Pty Ltd (\u201cCanva\u201d), 110 Kippax St, Surry Hills, NSW 2010, Australia, del rinnovo dell\u2019iscrizione alla piattaforma di progettazione grafica \u201cCanva per i team\u201d per la promozione istituzionale dell\u2019Universit\u00e0 della Valle d\u2019Aosta - Universit\u00e9 de la Vall\u00e9e d\u2019Aoste. CIG: Z513A5FA5A. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=W9Pu1WMexh4VboCaqVG0Eg%3D%3D_001080771-FS_FILES-2b6b956f-3621-4d0e-a60d-039908439931%5B1%5D.pdf\" target=\"_blank\">PD Promozione - Acquisto Canva 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=a5c7Z8iCkQshRBuHkC1kAA%3D%3D_001080767-FS_FILES-7a2dc682-5eef-45e4-9b5b-8dba22340e81%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 911_CANVA.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>24\/03\/2023<\/td><td>23\/03\/2023<\/td><td>2023-UNVACLE-0005433<\/td><td>Fornitura \u201cchiavi in mano\u201d delle dotazioni tecnologico\/informatiche necessarie per l\u2019entrata in funzione del Nuovo Polo Universitario ex Testafochi: riammissione del primo escluso a seguito di rinuncia<\/td><td><ul><li><a href=\"\/download-titulus?id=k4QpUEKZH0DSNFIukJZR6Q%3D%3D_001081528-FS_FILES-2c33fe8f-0a7b-4da9-8b86-aa536556a086%5B1%5D.pdf\" target=\"_blank\">Atto riammissione Durante.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>04\/04\/2023<\/td><td>03\/04\/2023<\/td><td>2023-UNVACLE-0006016<\/td><td>Provvedimento del Direttore Generale - Affidamento diretto ai sensi dell\u2019art. 1, comma 2, lettera a) della Legge n. 120\/2020 e ss.mm.ii. (Conversione in legge, con modificazioni, del Decreto-legge 16 luglio 2020, n. 76, recante \u00abMisure urgenti per la semplificazione e l\u2019innovazione digitale\u00bb), del servizio di revisione testi dall\u2019inglese per progetto \u201cAlpSatellites. Managing the transition to hybrid work and satellite offices to revitalize remote mountain areas\u201d, in risposta al bando \u201cInterreg \u2013 Alpine Space 2021\/2027\u201d - CUP B67G22000380007 \u2013 CIG ZEC3A55445. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=LFI%2B%2BaGZNht4QD1pzfUwYw%3D%3D_001083636-FS_FILES-8c0203a8-1c41-4e68-b32f-193750c93bbf%5B1%5D.pdf\" target=\"_blank\">PD revisione testi_def.pdf<a><\/li><li><a href=\"\/download-titulus?id=vLGRElis90IHYpmlkHY6mQ%3D%3D_001083585-FS_FILES-d53041ac-d55e-4994-891c-103877b561c8%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-04-03T093700.189.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>05\/04\/2023<\/td><td>04\/04\/2023<\/td><td>2023-UNVACLE-0006136<\/td><td>Provvedimento del Direttore generale - Affidamento diretto al Consorzio Interuniversitario Cineca, P.IVA 00502591209, dell\u2019erogazione di un corso di formazione denominato \u201cVERSO LA TRANSIZIONE DIGITALE - STRUMENTI E METODI\u201d erogato in modalit\u00e0 \u201cConf-call\u201d rivolto al personale dell\u2019Ufficio Sistemi informatici e Statistica dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste - Autorizzazione alla spesa<\/td><td><ul><li><a href=\"\/download-titulus?id=HSzkRocGSJaLiC1%2FeeMjfQ%3D%3D_001084162-FS_FILES-8b9750a3-38c3-4c82-b5ab-9140082d2ed6%5B1%5D.pdf\" target=\"_blank\">Provv_seminario_VERSO LA TRANSIZIONE DIGITALE - STRUMENTI E METODI_4_ aprile_2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=ow5LEekytQeKHuIPDYto3A%3D%3D_001083877-FS_FILES-30180ee6-a0fd-411e-9ead-6d424fc4e0cc%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 1804 - Corso Cineca.pdf<a><\/li><li><a href=\"\/download-titulus?id=3%2FS%2F%2FJ0EAsB5qN0w6HcLyQ%3D%3D_001083860-FS_FILES-cd89bcb4-d4d8-4722-b6aa-6004392ba9d5%5B1%5D.pdf\" target=\"_blank\">programma_seminario_CINECA_4_aprile_TRANSIZIONE_DIGITALE.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>10\/04\/2023<\/td><td>07\/04\/2023<\/td><td>2023-UNVACLE-0006371<\/td><td>Affidamento alla ditta A. Manzoni & C., P.IVA 04705810150, della campagna di promozione istituzionale e orientamento universitario per l\u2019anno accademico 2023\/2024 su \u201cGuida Universit\u00e0\u201d \u2013 CIG Z423A5953E. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=W%2F71gLgDydbqT1PrKr2Rvg%3D%3D_001085002-FS_FILES-2f674b40-6a0f-4647-86a3-936a12c35bc1%5B1%5D.pdf\" target=\"_blank\">PD promozione istituzionale 2023 - SCENARI Guida Universit\u00e0.pdf<a><\/li><li><a href=\"\/download-titulus?id=G5BTgMz1%2B7mOFQ%2FA%2BKsQ6w%3D%3D_001084380-FS_FILES-537c7bd1-4d1f-47e3-9d78-480fb2c25e66%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 840-2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>20\/04\/2023<\/td><td>19\/04\/2023<\/td><td>2023-UNVACLE-0006855<\/td><td>Provvedimento del Direttore Generale - Proroga dell\u2019adesione alla Centrale Unica di Committenza (CUC) della Societ\u00e0 IN.VA S.p.A. ed ai relativi servizi di acquisizione di beni e servizi per il periodo 01\/01\/2023 \u2013 31\/12\/2023<\/td><td><ul><li><a href=\"\/download-titulus?id=SNCBiaMhNUjpVXUPK8Xx7g%3D%3D_001086731-FS_FILES-f1927db9-b45a-4640-ab64-47a268131a19%5B1%5D.pdf\" target=\"_blank\">Provvedimento proroga Conv. CUC-Univda_2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=btkkAHsoMA%2BM6jGN%2BCUVDA%3D%3D_001086712-FS_FILES-3ee8d7d0-12c0-450e-ac3a-3555149d1e4e%5B1%5D.pdf\" target=\"_blank\">Scrittura contabile.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>21\/04\/2023<\/td><td>20\/04\/2023<\/td><td>2023-UNVACLE-0006924<\/td><td>Provvedimento del Direttore generale - Affidamento alla societ\u00e0 Paradigma srl dell\u2019erogazione di un corso di formazione dal titolo \u201cIl monitoraggio del RPCT sull\u2019attuazione delle misure anticorruzione e trasparenza\u201d, erogato in videoconferenza, rivolto al Direttore generale dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste mediante Trattativa Diretta (TD) nell\u2019ambito del MePA, ai sensi dell\u2019articolo 1, comma 2, lettera a), del Decreto legge 16 luglio 2020, n. 76, convertito, con modificazioni, dalla Legge 11 settembre 2020, n. 120, come modificato dal Decreto legge 31 maggio 2021, n. 77, nel testo vigente. CIG ZF63A73474. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=ExLoJ%2BDi7N%2FDlReYREkP3Q%3D%3D_001087005-FS_FILES-e5876628-c56f-4a73-96d8-64707b39c0f9%5B1%5D.pdf\" target=\"_blank\">PD RPCT Ravagli.pdf<a><\/li><li><a href=\"\/download-titulus?id=O1oCwj1vL265fL233xzwrQ%3D%3D_001086845-FS_FILES-cb1daf78-05f1-4b9c-bf79-c211e9e384ae%5B1%5D.pdf\" target=\"_blank\">Scrittura n. 1028_PARADIGMA SRL.pdf<a><\/li><li><a href=\"\/download-titulus?id=x9dtdaKNHG7btw6xFGR6BA%3D%3D_001086804-FS_FILES-cb1113ce-2105-4d11-b2a9-ac4416c2b8bd%5B1%5D.pdf.p7m\" target=\"_blank\">OE_NG3523891_L0_NP600645.pdf.p7m<a><\/li><\/ul><\/td><\/tr><tr><td>18\/05\/2023<\/td><td>17\/05\/2023<\/td><td>2023-UNVACLE-0008389<\/td><td>Provvedimento del Direttore generale - Avviso di istruttoria per il conferimento di un incarico di prestazione d\u2019opera autonoma per il supporto alle attivit\u00e0 di comunicazione digitale dell\u2019ufficio comunicazione e orientamento dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste (CODICE DIRAMM\/01\/2023). Approvazione degli atti della commissione esaminatrice e conferimento dell\u2019incarico<\/td><td><ul><li><a href=\"\/download-titulus?id=CNwJ9a1onbe9Af2lIYFgQA%3D%3D_001092592-FS_FILES-255785b2-87d3-4821-a1a0-34d34e579a57%5B1%5D.pdf\" target=\"_blank\">2023_Provvedimento Direttore generale - conferimento incarico collaboratore comunicazione.pdf<a><\/li><li><a href=\"\/download-titulus?id=s%2FEQ%2BNc%2B3B%2Fc6t%2FdEUUnJQ%3D%3D_001091756-FS_FILES-f02bf4da-c288-4269-8534-62805b6ebe87%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN 1241-2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>29\/05\/2023<\/td><td>26\/05\/2023<\/td><td>2023-UNVACLE-0009226<\/td><td>Provvedimento del Direttore Generale - Acquisizione e rinnovo di pacchetti di licenze software Microsoft e servizi collegati attraverso l\u2019accordo in essere tra CRUI - Conferenza dei Rettori delle Universit\u00e0 Italiane e Microsoft. Anno 2023. Autorizzazione alla spesa. CIG: ZD43B52505<\/td><td><ul><li><a href=\"\/download-titulus?id=j%2FEtJt%2BcwYbegGl4nd4qxA%3D%3D_001094884-FS_FILES-181c8f9c-cc12-4633-aec8-53898252777b%5B1%5D.pdf\" target=\"_blank\">PD rinnovo licenze microsoft 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=4pMcTPtGPIO0SF1TZCOLzQ%3D%3D_001094885-FS_FILES-600b8fca-5b40-4b56-9c5e-51b8b60fa9ab%5B1%5D.pdf\" target=\"_blank\">MQO_230522132527_10340_72573768.pdf<a><\/li><li><a href=\"\/download-titulus?id=HuWfT5i8vEhmS1MiYS292A%3D%3D_001094828-FS_FILES-7525d299-9906-4aea-b90c-883bbdb1cebd%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN 2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>29\/05\/2023<\/td><td>26\/05\/2023<\/td><td>2023-UNVACLE-0009227<\/td><td>Affidamento alla ditta Weisoft s.r.l. di Torino, P.IVA e C.F. 10917740010, del rinnovo triennale del contratto di assistenza e aggiornamento della licenza del software Archicad. - CIG N. ZAC3B36AD5<\/td><td><ul><li><a href=\"\/download-titulus?id=6%2Bu0hRRQdkHhM1fibjq9VQ%3D%3D_001094886-FS_FILES-7fc5c073-0359-427e-bc4a-49d46d5e1739%5B1%5D.pdf\" target=\"_blank\">PD rinnovo Archicad.pdf<a><\/li><li><a href=\"\/download-titulus?id=y9Xr1DI9mm%2FAd7QD2wG6xg%3D%3D_001094832-FS_FILES-c86bf45c-cd34-42e9-a750-981c0f5d59b7%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN n. 1741.pdf<a><\/li><li><a href=\"\/download-titulus?id=XJt5g3u9cXPWJrbpPFwDsA%3D%3D_001094798-FS_FILES-62c8c51b-a5ca-44be-a76d-ff7481e4af40%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7281050.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>29\/05\/2023<\/td><td>26\/05\/2023<\/td><td>2023-UNVACLE-0009229<\/td><td>Provvedimento del Direttore generale - Affidamento alla ditta LG Presse s.r.l., P. IVA 01141020071 del servizio di sponsorizzazione dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, in occasione della partecipazione alla manifestazione \u201cLa Piazza Saint-Vincent 2023\u201d nei giorni 16, 17 e 18 giugno 2023 e della campagna di promozione istituzionale e orientamento universitario per l\u2019anno accademico 2023\/2024 su \u201cGazzetta Matin\u201d e \u201cWEEKEND\u201d - CIG Z703B05FDB e Z473B2F75E. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=gzIf0utbD3%2F8zEoubHTMCA%3D%3D_001094889-FS_FILES-19545d45-ef97-4a3c-bcb5-b4aaa79e1837%5B1%5D.pdf\" target=\"_blank\">PD_LG_Presse_Trofeo_La_Piazza_Gazzetta Matin_2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=u1uQortaKN0hsQMurmYgUg%3D%3D_001094400-FS_FILES-4106b5f6-f980-46bf-a61a-ac061d8613b8%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN Trofeo La piazza.pdf<a><\/li><li><a href=\"\/download-titulus?id=3fqMDNyCweV%2FMIx2eY8JFg%3D%3D_001094401-FS_FILES-b704d078-ef40-43f8-b15d-463893d610d5%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN_Gazzetta matin.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>31\/05\/2023<\/td><td>30\/05\/2023<\/td><td>2023-UNVACLE-0009356<\/td><td>Provvedimento del Direttore generale - Affidamento alla ditta Tipografia Valdostana di Aosta, P. Iva 00035150077, della fornitura di n. 100 copie del volume D\u2019Oberteilera ch\u00e9emen \u00e9nger o arrivurun d\u2019greschuneiara? Patrimonio idiomatico titsch e t\u00f6itschu, al\u2019interno del progetto \u201cFAR 3 \u2013 Formazione alla ricerca 3\u201d (PAC.01104.20AC.0.0001.PCE) finanziato dal Fondo Sociale Europeo, nell\u2019ambito del piano giovani \u2013 avviso 20AC (codice SISPOR 2020\/02), CUP B69C20000380006. C.I.G. Z953B5336A.<\/td><td><ul><li><a href=\"\/download-titulus?id=sxXQjowL1MPtIJRxcvLOnw%3D%3D_001095382-FS_FILES-c7ad5898-e803-4742-a0f2-55c3d51f0a1f%5B1%5D.pdf\" target=\"_blank\">PD_Tipografia Valdostana.pdf<a><\/li><li><a href=\"\/download-titulus?id=oJT6rxIU%2FL1%2BHvXIXnYiFw%3D%3D_001095267-FS_FILES-91214720-5ff5-4f31-81a6-2eb56f54078d%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-05-30T112601.021.pdf<a><\/li><li><a href=\"\/download-titulus?id=kwMElbnL09UyqT7602xMig%3D%3D_001095268-FS_FILES-515855b1-9e65-4072-b6d1-3fc7e27740c2%5B1%5D.pdf\" target=\"_blank\">PREV_0876_23_privacy.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>06\/06\/2023<\/td><td>05\/06\/2023<\/td><td>2023-UNVACLE-0009612<\/td><td>Provvedimento del Direttore generale - AAffidamento all\u2019ASSOCIAZIONE ASTER, P.IVA 05360960826, per la locazione di spazi e per la fornitura di servizi connessi alla partecipazione alla V Edizione della manifestazione di orientamento \u201cOrientaLombardia \u2013 ASTERLombardia\u201d \u2013 12, 13 e 14 dicembre 2023, mediante Trattativa Diretta nell\u2019ambito del Mercato Elettronico della Pubblica Amministrazione \u2013 CIG Z9A3A69650.<\/td><td><ul><li><a href=\"\/download-titulus?id=e1lp8Q7q%2FY11S9oWUGDWcA%3D%3D_001096330-FS_FILES-00e784a2-fa3f-4949-acb0-8b64773ecafc%5B1%5D.pdf\" target=\"_blank\">PD ASTER Orienta.pdf<a><\/li><li><a href=\"\/download-titulus?id=9D0Ufwo6a4kE%2FXuA9sUFNw%3D%3D_001094856-FS_FILES-23a312de-443c-4080-a763-565c8bc1ee06%5B2%5D.pdf.p7m\" target=\"_blank\">OE_NG3554680_L0_NP663650.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=1jHlvWO4%2B5X94adR9YlfLg%3D%3D_001095715-FS_FILES-d66a85dd-c1e6-4421-b1aa-5b87d9511775%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>06\/06\/2023<\/td><td>05\/06\/2023<\/td><td>2023-UNVACLE-0009674<\/td><td>Provvedimento del Direttore generale - Affidamento diretto alla ditta TECHNE s.r.l., con sede legale a Cecina (LI), P. IVA 01121580490 della fornitura di una licenza in abbonamento annuale Sketch up Pro 2023 con un anno di M&S incluso, finalizzato allo svolgimento delle attivit\u00e0 inerenti il progetto MEDIA (Museo Emozionale DIgitale multimediale Avanzato) presentato dall\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, di cui al Bando \u201cAggregazioni R&S\u201d approvato con la deliberazione della Giunta della Regione Valle d\u2019Aosta n. 890 in data 19 luglio 2021, di cui \u00e8 Responsabile scientifico la Prof.ssa Anna Maria Pioletti - codice: MEDIA2022 - CUP B19J22001510007 CIG Z683B55F2C.<\/td><td><ul><li><a href=\"\/download-titulus?id=mE3RGVAm6IZcS4%2Ftrnw7Jw%3D%3D_001096624-FS_FILES-b1126d17-b3f4-4b50-acdb-7d929e83e87f%5B1%5D.pdf\" target=\"_blank\">Provvedimento DG - software.pdf<a><\/li><li><a href=\"\/download-titulus?id=pme9w2Sjabd4rPwyW5%2BWrQ%3D%3D_001096622-FS_FILES-cc66510e-6bac-4a48-8f1c-51f1c45f2ac1%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7284923 - Omissis.pdf<a><\/li><li><a href=\"\/download-titulus?id=H1nakONo4o%2FKMwfLfrdFUw%3D%3D_001096623-FS_FILES-51dfe52b-817a-47eb-9c26-687c94930924%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-06-05T171303.227.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>06\/06\/2023<\/td><td>05\/06\/2023<\/td><td>2023-UNVACLE-0009675<\/td><td>Provvedimento del Direttore generale - Affidamento diretto alla ditta FERRARI GIOVANNI COMPUTERS s.r.l. di Modena, P. Iva 02138390360, della fornitura di filamenti (ad uso stampante 3D), specifici per lo svolgimento delle attivit\u00e0 inerenti il progetto \u201cMEDIA (Museo Emozionale DIgitale multimediale Avanzato)\u201d, in risposta al Bando \u201cAggregazioni R&S\u201d, promosso dall\u2019Assessorato Sviluppo economico, formazione e lavoro della Regione Autonoma Valle d\u2019Aosta, CUP B19J22001510007. CIG Z593B49418.<\/td><td><ul><li><a href=\"\/download-titulus?id=O7vzrHdKIXQgEX%2Bg%2BvGaqQ%3D%3D_001096625-FS_FILES-a35ecd5b-6320-4f14-bbb1-769be1f472a3%5B1%5D.pdf\" target=\"_blank\">PD_FERRARI.pdf<a><\/li><li><a href=\"\/download-titulus?id=yQOgHFhWMoUbhihRQuBowg%3D%3D_001096603-FS_FILES-ac54cd64-35b1-4c61-936c-533cc676d7e3%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7284954 - Omissis.pdf<a><\/li><li><a href=\"\/download-titulus?id=5%2BwmGW77N7q5vCwtWH53pQ%3D%3D_001096604-FS_FILES-3723f8e9-5d2f-4f87-952c-3ac4f3e75583%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-06-05T162915.215.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>16\/06\/2023<\/td><td>15\/06\/2023<\/td><td>2023-UNVACLE-0010233<\/td><td>Provvedimento del Direttore generale -Affidamento diretto alla ditta MORPHICA di Monopoli (BA) - P. Iva 07949220722, della fornitura di filamenti (ad uso stampante 3D), specifici per lo svolgimento delle attivit\u00e0 inerenti il progetto \u201cMEDIA (Museo Emozionale DIgitale multimediale Avanzato)\u201d, in risposta al Bando \u201cAggregazioni R&S\u201d, promosso dall\u2019Assessorato Sviluppo economico, formazione e lavoro della Regione Autonoma Valle d\u2019Aosta, CUP B19J22001510007. CIG ZFA3B8DB88.<\/td><td><ul><li><a href=\"\/download-titulus?id=n5qFKruSzGSIcBw0Fiushg%3D%3D_001098797-FS_FILES-23bd6f4a-5f21-4c67-a855-e226bfdc4f87%5B1%5D.pdf\" target=\"_blank\">PD_MORPHICA.pdf<a><\/li><li><a href=\"\/download-titulus?id=C7FpwWrhDbcuvg18GBdNaw%3D%3D_001098795-FS_FILES-58a6786e-a8af-4f06-8a41-481c60cf15a0%5B1%5D.pdf\" target=\"_blank\">Ordinativo n. 7306137 (Morphica S.r.l.) - omissis.pdf<a><\/li><li><a href=\"\/download-titulus?id=SL8%2FxWo%2Bt%2BOnU8DzH4Gl1w%3D%3D_001098796-FS_FILES-7a736528-516f-44f6-8d92-a18e6852ae19%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - 2023-06-15T180018.563.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>26\/06\/2023<\/td><td>23\/06\/2023<\/td><td>2023-UNVACLE-0010793<\/td><td>Provvedimento del Direttore generale - Affidamento all\u2019Associazione Italiana Biblioteche (AIB), P. IVA 01132481001, della fornitura dell\u2019abbonamento alla WebDewey Italiana\u00ae per il periodo 01\/07\/2023-30\/06\/2024 - CIG Z823B59348.<\/td><td><ul><li><a href=\"\/download-titulus?id=AuEXwsTIo6q6%2B3z5un7MBQ%3D%3D_001100798-FS_FILES-19474e01-143f-4ae5-8139-19535b6fcf96%5B1%5D.pdf\" target=\"_blank\">Provv_WebDewey_2023-24.pdf<a><\/li><li><a href=\"\/download-titulus?id=IrxomquTKTSAPT7a6h9CBA%3D%3D_001100586-FS_FILES-8f3253ec-2f2d-4c9b-9ef9-213d7eca26fe%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/06\/2023<\/td><td>26\/06\/2023<\/td><td>2023-UNVACLE-0010836<\/td><td>Provvedimento del Direttore generale - Affidamento alla ditta CAMPUS EDITORI s.r.l., P.IVA 09406120155, per la locazione di spazi e per la fornitura di servizi connessi alla partecipazione alle manifestazioni di orientamento \u201cCampus Orienta\u201d per l\u2019anno 2023 mediante Trattativa Diretta nell\u2019ambito del Mercato Elettronico della Pubblica Amministrazione \u2013 CIG Z203A694CE.<\/td><td><ul><li><a href=\"\/download-titulus?id=JLX6Jmhoi1u8w0JZJ9yUZg%3D%3D_001100958-FS_FILES-36a6711a-6880-4876-a6dc-121c777f433b%5B1%5D.pdf\" target=\"_blank\">PD Campus orienta.pdf<a><\/li><li><a href=\"\/download-titulus?id=I%2FUQVpZ7P0AtxWsPLyqvpA%3D%3D_001100895-FS_FILES-7f776c99-db59-4d91-a47e-92f8fd6a2f79%5B1%5D.pdf\" target=\"_blank\">OE_NG3602512_L0_NP701716 _1_.pdf<a><\/li><li><a href=\"\/download-titulus?id=3sUYm88kOAnZo4uGNagvCA%3D%3D_001100898-FS_FILES-41f2b7c0-e10f-41d6-ada2-82088d35b19a%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/06\/2023<\/td><td>26\/06\/2023<\/td><td>2023-UNVACLE-0010837<\/td><td>Affidamento alla ditta Mediamond S.p.A., P.IVA 06703540960, della campagna di promozione istituzionale e orientamento universitario per l\u2019anno accademico 2023\/2024 su Skuola.net \u2013 CIG Z1C3B0DB4E. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=mG6YFlj5KtvmZA%2Bp5CpZIw%3D%3D_001100959-FS_FILES-57b626d9-a93b-45a7-b5f7-72624175efc0%5B1%5D.pdf\" target=\"_blank\">00_PD promozione istituzionale 2023 - Mediamond.pdf<a><\/li><li><a href=\"\/download-titulus?id=TX%2F%2BC4FvEFntfSCBcBy6Mg%3D%3D_001100884-FS_FILES-80439f35-52e6-413f-b7f1-61238feb4df4%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>27\/06\/2023<\/td><td>26\/06\/2023<\/td><td>2023-UNVACLE-0010838<\/td><td>Provvedimento del Direttore generale - Affidamento alla Ditta Tipografia Litografia Bolognino Davide & C. s.n.c., via Dora Baltea 4, Ivrea (TO), P. IVA 02067490017, del servizio di stampa di materiale informativo dell\u2019Ateneo, mediante Trattativa Diretta (TD) nell\u2019ambito del Mercato Elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 CIG ZCA3B9D84D.<\/td><td><ul><li><a href=\"\/download-titulus?id=zIHmvGVz7IVH0L%2FREor8Sw%3D%3D_001100961-FS_FILES-78dfa7d5-3679-4ec8-a379-d9c5765b7265%5B1%5D.pdf\" target=\"_blank\">PD Servizi Stampa.pdf<a><\/li><li><a href=\"\/download-titulus?id=yR%2FKnhMYDGGOKlZlanZXtg%3D%3D_001100802-FS_FILES-661ee065-1e63-4381-9e31-5863a19a026c%5B1%5D.pdf\" target=\"_blank\">10679.2023 LETTERA trattativa diretta - TIPOGRAFIA (2).pdf<a><\/li><li><a href=\"\/download-titulus?id=ir6Ucc%2BO0PHlAIJHKfgmNQ%3D%3D_001100791-FS_FILES-0424b034-2e4a-4911-94d6-0560dce55cb9%5B2%5D.pdf.p7m\" target=\"_blank\">All. 02_OE_NG3629503_L0_NP734436.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=xdJwo%2F1MgR33ydaZSSVUiA%3D%3D_001100793-FS_FILES-305d7eb1-3129-469f-ada0-4ffc15004f9d%5B2%5D.pdf\" target=\"_blank\">All. 03_ Dettaglio servizi  Off1548-signed.pdf<a><\/li><li><a href=\"\/download-titulus?id=n4wm08OAExp6NpSTdrwB%2Fw%3D%3D_001100880-FS_FILES-6b2b6fbf-b9c7-4af0-9395-8ceecec2f72b%5B1%5D.pdf\" target=\"_blank\">All. 04_Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>29\/06\/2023<\/td><td>28\/06\/2023<\/td><td>2023-UNVACLE-0010997<\/td><td>Affidamento alla ditta Publi(iN) Srl, P.IVA 01842780064, della campagna di promozione istituzionale e orientamento universitario per l\u2019anno accademico 2023\/2024 per pubblicazioni su testate giornalistiche locali \u2013 CIG ZDC3B0D826. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=sxFaabyZSj60iDSIPWJPsA%3D%3D_001101567-FS_FILES-f6e204e2-78fd-4fe2-8ac4-665b91747fbb%5B1%5D.pdf\" target=\"_blank\">PD promozione istituzionale 20223 - Publi(iN).pdf<a><\/li><li><a href=\"\/download-titulus?id=ZGMEQeDqwUJ%2FNJGtFcDBDg%3D%3D_001101142-FS_FILES-14257294-ac33-4432-a8b0-337df07708b6%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>29\/06\/2023<\/td><td>28\/06\/2023<\/td><td>2023-UNVACLE-0011033<\/td><td>Affidamento diretto ai sensi dell\u2019art. 1, comma 2, lettera a) della Legge n. 120\/2020 e ss.mm.ii. (Conversione in legge, con modificazioni, del Decreto-legge 16 luglio 2020, n. 76, recante \u00abMisure urgenti per la semplificazione e l\u2019innovazione digitale\u00bb), dei servizi di comunicazione per la Direzione Generale di Ateneo \u2013 CIG: ZC93B7A152. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=iEY2gW7c0LAKkhZd%2FaxSzQ%3D%3D_001101677-FS_FILES-bafaa43f-5f1f-4955-9cbf-baa77395e53f%5B1%5D.pdf\" target=\"_blank\">Provvedimento affidamento Servizi comunicazione.pdf<a><\/li><li><a href=\"\/download-titulus?id=cT7CWBwLl%2FGwNrP5Zdflbg%3D%3D_001101673-FS_FILES-064ace84-b844-470c-83b3-056d0ab47541%5B1%5D.pdf\" target=\"_blank\">All. 01 - Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=l4GBAPnREm3ZE3vLpQ6TEg%3D%3D_001101856-FS_FILES-f6031b10-3ab5-4b2c-b25e-f3537493deba%5B1%5D.pdf\" target=\"_blank\">All. 02 - Disciplinare di incarico def. Digitouch 2023 - omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>26\/07\/2023<\/td><td>25\/07\/2023<\/td><td>2023-UNVACLE-0012461<\/td><td>Provvedimento del Direttore Generale - Affidamento alla ditta LED \u2013 Edizioni Universitarie di Lettere Economia Diritto S.r.l., P.IVA 10295540156, della pubblicazione del volume \u201cNatura e paesaggio nello Zibaldone di Leopardi. Un\u2019analisi semantica\u201d, della dottoressa Veronica Medda - progetto FAR 3 \u2013 Formazione alla ricerca 3 (PAC.01104.20AC.0.0001.PCE) finanziato dal Fondo Sociale Europeo, nell\u2019ambito del piano giovani \u2013 avviso 20AC (codice SISPOR 2020\/02), CUP B69C20000380006. CIG Z1B3BE488F.<\/td><td><ul><li><a href=\"\/download-titulus?id=AJjJWdheYtrVBggEDUiQ3g%3D%3D_001107398-FS_FILES-0be3f571-e68d-4239-8551-64747407becd%5B1%5D.pdf\" target=\"_blank\">PD - Pubblicazione Led.pdf<a><\/li><li><a href=\"\/download-titulus?id=huXpbmTP7t2mpT1iBnfgOA%3D%3D_001107267-FS_FILES-187910e1-fb70-4763-9048-b28a2427ac34%5B1%5D.pdf\" target=\"_blank\">Scrittura Contabile.pdf<a><\/li><li><a href=\"\/download-titulus?id=P3mRq6rxXdY9eYYiWEiCxQ%3D%3D_001107271-FS_FILES-7aaf3132-fc23-4f35-aeaf-c6ed2307ad5b%5B1%5D.pdf\" target=\"_blank\">Preventivo_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>03\/08\/2023<\/td><td>02\/08\/2023<\/td><td>2023-UNVACLE-0012792<\/td><td>Provvedimento del Direttore generale - Affidamento diretto alla ditta ITA S.r.l., P. Iva 01593590605, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, dell\u2019erogazione di un corso di formazione dal titolo \u201cLa nuova disciplina in materia di incarichi, cumulo di impieghi e incompatibilit\u00e0 dei docenti universitari: la responsabilit\u00e0 di fronte alla Corte dei conti\u201d, erogato in modalit\u00e0 telematica, rivolto ad una dirigente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Ordinativo di Esecuzione Immediata nell\u2019ambito del mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 CIG ZFA3BFB983.<\/td><td><ul><li><a href=\"\/download-titulus?id=My6Z3q%2FWMR07Gf3MrA2K0A%3D%3D_001108986-FS_FILES-114d1ac0-3922-4145-b27c-bfc42c8b95d4%5B1%5D.pdf\" target=\"_blank\">PD Corso Dott.ssa De Luca.pdf<a><\/li><li><a href=\"\/download-titulus?id=5XoV5LD6uSHveHXYkzCU1Q%3D%3D_001108787-FS_FILES-603f8a3d-3aec-45a6-bef3-17881194b55f%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=a1Q3p%2FABdRKv3nb8sY1b9g%3D%3D_001108775-FS_FILES-47f73a43-9b29-4010-a9ac-6509f9510a11%5B1%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7362786_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>18\/08\/2023<\/td><td>17\/08\/2023<\/td><td>2023-UNVACLE-0013487<\/td><td>Provvedimento del Direttore generale - Affidamento diretto alla ditta Tipografia Pesando Snc di Pesando-Gamacchio & Macr\u00ec, P. Iva 00466260072, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, della fornitura di agende e calendari con il logo dell\u2019Universit\u00e0 della Valle d\u2019Aosta, per l\u2019anno 2024, a seguito di Richiesta di Offerta nell\u2019ambito della piattaforma telematica PlaCe-Vda di In.Va. S.p.A. \u2013 CIG Z023BE5182<\/td><td><ul><li><a href=\"\/download-titulus?id=KcOZlkGj7tWWmprKtutuVQ%3D%3D_001111358-FS_FILES-b9a221eb-2034-4974-a6e6-32dc801c1ad6%5B1%5D.pdf\" target=\"_blank\">PD_Agende 2024.pdf<a><\/li><li><a href=\"\/download-titulus?id=ZnJrSACD8k7rPoELNOVHMg%3D%3D_001110970-FS_FILES-c98011ac-39e3-4278-90e0-dccc50935f95%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>22\/08\/2023<\/td><td>21\/08\/2023<\/td><td>2023-UNVACLE-0013630<\/td><td>Affidamento diretto ai sensi dell\u2019art. 1, comma 2, lettera a) della Legge n. 120\/2020 e ss.mm.ii. (Conversione in legge, con modificazioni, del Decreto-legge 16 luglio 2020, n. 76, recante \u00abMisure urgenti per la semplificazione e l\u2019innovazione digitale\u00bb), dei servizi legali a supporto della Direzione Generale di Ateneo \u2013 Integrazione - CIG Z853865216<\/td><td><ul><li><a href=\"\/download-titulus?id=jAxV88%2B31iRvhg8EB3M74Q%3D%3D_001111765-FS_FILES-fa477c88-a767-4696-bafb-3ddca7921839%5B1%5D.pdf\" target=\"_blank\">PD Integrazione cassa  Servizi Legali.pdf<a><\/li><li><a href=\"\/download-titulus?id=p0LxWmYkQXGRyAl019kqgA%3D%3D_001111396-FS_FILES-92470467-c62e-4b8b-8d05-169bc4bc5a12%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN Integrativa.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>22\/08\/2023<\/td><td>21\/08\/2023<\/td><td>2023-UNVACLE-0013633<\/td><td>Affidamento diretto, tramite Trattativa diretta nell\u2019ambito del Mercato Elettronico della Pubblica Amministrazione, alla ditta Day Ristoservice s.p.a., P.IVA 03543000370, per la fornitura del servizio sostitutivo mensa mediante n. 6.300 buoni pasto elettronici, per il personale tecnico-amministrativo dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, nelle more dell\u2019attivazione della Convenzione Consip \u201cBuoni Pasto ed. 10\u201d \u2013 CIG Z5A3C20DA7.<\/td><td><ul><li><a href=\"\/download-titulus?id=%2FN7c2YiRVUudf8PsMwipCw%3D%3D_001111768-FS_FILES-67da2a06-6314-41ab-9741-a8f162f916fd%5B1%5D.pdf\" target=\"_blank\">PD Buoni pasto.pdf<a><\/li><li><a href=\"\/download-titulus?id=vHqrESaZwGxmhK%2ByjL06aQ%3D%3D_001111569-FS_FILES-04e3aee5-b33b-418d-b069-bf3750dee01b%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=wYhOZ0CDAUnmmESRZx451w%3D%3D_001110506-FS_FILES-3a4f04fc-364f-41d6-ab71-131f8c505314%5B2%5D.pdf.p7m\" target=\"_blank\">OE_NG3692499_L0_NP815902.pdf.p7m<a><\/li><\/ul><\/td><\/tr><tr><td>28\/08\/2023<\/td><td>25\/08\/2023<\/td><td>2023-UNVACLE-0013909<\/td><td>Provvedimento del Direttore Generale - Affidamento diretto alla ditta GA Service s.r.l. - P. Iva 07252620963 \u2013 della fornitura di due tablet e un Ipad con accessori, specifici per lo svolgimento delle attivit\u00e0 inerenti il progetto \u201cNODES \u2013 Nord Ovest Digitale e Sostenibile\u201d, in risposta all\u2019avviso pubblico per la presentazione di Proposte di intervento per la creazione e il rafforzamento di \u201cecosistemi dell\u2019innovazione\u201d, costruzione di \u201cleader territoriali di R&S\u201d \u2013 Ecosistemi dell\u2019Innovazione \u2013 relativo al Piano Nazionale di Ripresa e Resilienza (PNRR), Missione 4 Istruzione e ricerca \u2013 Componente 2 Dalla ricerca all\u2019impresa \u2013 Investimento 1.5, finanziato dall\u2019Unione europea \u2013 NextGenerationEU \u2013 CUP B63B22000010001. CIG ZE03C3E323.<\/td><td><ul><li><a href=\"\/download-titulus?id=MR7eSUFsdOhxh1S1H8VKfw%3D%3D_001112906-FS_FILES-3b440954-e676-40d3-976d-8cf8741f44bb%5B1%5D.pdf\" target=\"_blank\">PD_Tablet Nodes.pdf<a><\/li><li><a href=\"\/download-titulus?id=Iw6FrPOR8pG%2FqTMvhabs5w%3D%3D_001112899-FS_FILES-0793befa-3777-41ca-adb7-dd87c6cbc643%5B1%5D.pdf\" target=\"_blank\">Ordinativo n. 7383396 - omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>28\/08\/2023<\/td><td>25\/08\/2023<\/td><td>2023-UNVACLE-0013914<\/td><td>Affidamento alla ditta FCS FERRARA S.R.L. di Ferrara (FE), P. Iva 01737930386, della fornitura di attrezzatura tecnica, finalizzata allo svolgimento delle attivit\u00e0 inerenti al progetto \u201cMEDIA (Museo Emozionale DIgitale multimediale Avanzato)\u201d, in risposta al Bando \u201cAggregazioni R&S\u201d, promosso dall\u2019Assessorato Sviluppo economico, formazione e lavoro della Regione Autonoma Valle d\u2019Aosta, CUP B19J22001510007. CIG Z0C3BF446B.<\/td><td><ul><li><a href=\"\/download-titulus?id=22RKwxwxN%2Bj0xz5t8UDbGw%3D%3D_001112944-FS_FILES-f3f65dcb-39d4-404f-9261-f1a8518c1655%5B1%5D.pdf\" target=\"_blank\">PD Visore.pdf<a><\/li><li><a href=\"\/download-titulus?id=oFOVzMm7aQDd6%2FdHNdOgYA%3D%3D_001112934-FS_FILES-c7eaa9b3-731f-4b01-87b5-4343b8aa23d8%5B2%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7368773_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>13\/09\/2023<\/td><td>12\/09\/2023<\/td><td>2023-UNVACLE-0014792<\/td><td>Provvedimento del Direttore generale - Affidamento diretto alla ditta I.T.A. S.r.l., P.IVA 01593590605, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, dell\u2019erogazione di un corso di formazione dal titolo \u201cAutotutela e ritiro degli atti amministrativi: rischi di responsabilit\u00e0 di fronte alla Corte dei conti\u201d, erogato in modalit\u00e0 telematica, rivolto ad una dirigente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG Z993C48D3B. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=oKNcO0ikxVQUOHb%2B82yOOQ%3D%3D_001116157-FS_FILES-b07025f3-b7b0-4986-b669-0b4bcc5b0b1f%5B1%5D.pdf\" target=\"_blank\">PD_Corso Dott.ssa Luboz.pdf<a><\/li><li><a href=\"\/download-titulus?id=NG7ve3NjB6opgGkLi0aBDQ%3D%3D_001115869-FS_FILES-3ce245eb-3788-49bd-a31d-5c5167bf3843%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=J4TxwYUl8GpLaZOZZlfZIw%3D%3D_001115870-FS_FILES-21ee749a-f4ab-4eee-b2dc-68eb04ed62f3%5B1%5D.pdf\" target=\"_blank\">Programma corso.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>13\/09\/2023<\/td><td>12\/09\/2023<\/td><td>2023-UNVACLE-0014793<\/td><td>Provvedimento del Direttore Generale - Affidamento alla ditta CANON ITALIA SPA, P. Iva 11723840150, mediante adesione alla convenzione Consip \u201cApparecchiature multifunzione in noleggio 2\u201d \u2013 Lotto 2 - Multifunzione A3 monocromatiche per gruppi di medie dimensioni, della fornitura a noleggio, per un periodo di 48 mesi, di un apparecchio multifunzione da destinare alla sede di Loc. Le Grand Chemin 181 in Saint Christophe (AO) presso l\u2019Ufficio Segreterie studenti e Diritto allo Studio \u2013 CIG Z3C3C2C4C2.<\/td><td><ul><li><a href=\"\/download-titulus?id=J9e1DRbd3yD2BxURs8YpSA%3D%3D_001116158-FS_FILES-1c202cce-7c26-49c2-8870-d959e2051e93%5B1%5D.pdf\" target=\"_blank\">PD Canon.pdf<a><\/li><li><a href=\"\/download-titulus?id=iCbky7UlYcYYsDFyr65lpw%3D%3D_001115858-FS_FILES-aee057b5-bfd4-492f-96c8-cfa3ea540c54%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - Anticipata.pdf<a><\/li><li><a href=\"\/download-titulus?id=gsUFQG8sjVdb59q05%2BCJJA%3D%3D_001115536-FS_FILES-fe1038d0-06c0-4f5c-98a6-eef23720e0ee%5B1%5D.pdf\" target=\"_blank\">ID 2508 MF 2 Corrispettivi LOTTO 2.pdf<a><\/li><li><a href=\"\/download-titulus?id=AKSiUSCm3oFI7LvNYfy7oQ%3D%3D_001115538-FS_FILES-1cf352ea-78a7-4c1f-a56a-840d603f9118%5B1%5D.pdf\" target=\"_blank\">ORDINE_7375721 - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>29\/09\/2023<\/td><td>28\/09\/2023<\/td><td>2023-UNVACLE-0015705<\/td><td>Adesione dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste alla Convenzione Consip Facility Management 4 \u2013 Lotto 2 \u2013 Convenzione per i servizi di pulizia e igiene ambientale, manutenzione impianti, altri servizi operativi e servizi gestionali presso gli immobili adibiti prevalentemente ad uso ufficio delle Pubbliche Amministrazioni e negli immobili delle Istituzioni Universitarie Pubbliche e degli Enti ed Istituti di Ricerca. CIG 56512853E9 \u2013 CIG derivato A015B8BE00<\/td><td><ul><li><a href=\"\/download-titulus?id=SmQzBJhabrJSMWIbMuGgXA%3D%3D_001120133-FS_FILES-2be0b183-e44d-4310-80d2-5f87a99e8b5b%5B1%5D.pdf\" target=\"_blank\">PD facility FM4 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=Z%2FNk%2F0dREi%2BpRWJO33eLPg%3D%3D_001120131-FS_FILES-f1d1d2c0-8e64-4639-81d4-271478aac577%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN FM4 - anno 2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>05\/10\/2023<\/td><td>04\/10\/2023<\/td><td>2023-UNVACLE-0016018<\/td><td>Provvedimento del Direttore Generale - Affidamento al Consorzio Interuniversitario Cineca, P.IVA 00502591209, dell\u2019erogazione di un corso di formazione denominato \u201cCSA Economico Base Completo\u201d, erogato in modalit\u00e0 e-learning blended, rivolto a due dipendenti dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, ai sensi dell\u2019art. 7 del D.lgs. n. 36\/2023. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=17j17qeRF1dhQ8LtKHo9CA%3D%3D_001121666-FS_FILES-c37c7202-f080-4be6-af25-82aac220c9f7%5B1%5D.pdf\" target=\"_blank\">Provvedimento corso CSA Economico Base completo.pdf<a><\/li><li><a href=\"\/download-titulus?id=baX5Kzyai1jc32F%2FTD%2BBVg%3D%3D_001121632-FS_FILES-72f9b0a9-9b68-4c77-bb7f-fadebe0cdaaa%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=7%2FKva8t2vpz0bVrd%2BXGBoQ%3D%3D_001121548-FS_FILES-fb4b4dd5-a19c-443b-a78d-95744bd77673%5B1%5D.pdf\" target=\"_blank\">Programma corso.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>05\/10\/2023<\/td><td>04\/10\/2023<\/td><td>2023-UNVACLE-0016019<\/td><td>Provvedimento del Direttore Generale - Affidamento alla ditta CANON ITALIA SPA, P. Iva 11723840150, mediante adesione alla convenzione Consip \u201cApparecchiature multifunzione in noleggio 2\u201d \u2013 Lotto 2 - Multifunzione A3 monocromatiche per gruppi di medie dimensioni, della fornitura a noleggio, per un periodo di 48 mesi, di un apparecchio multifunzione da destinare alla sede di Loc. Le Grand Chemin 181 in Saint Christophe (AO) \u2013 CIG Z5F3C54793.<\/td><td><ul><li><a href=\"\/download-titulus?id=TihkHsVZ6xyIJcN8UWnxtw%3D%3D_001121667-FS_FILES-751b4a3c-d1d5-4196-adbc-c5e673737b99%5B1%5D.pdf\" target=\"_blank\">PD Convenzione stampante.pdf<a><\/li><li><a href=\"\/download-titulus?id=7hxAnyaJriBafYtAajaJsQ%3D%3D_001121550-FS_FILES-5562d618-95d1-4cda-a138-f7232b091b72%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=2J9e2IVVLbgZWE7%2BBKjI%2BA%3D%3D_001120729-FS_FILES-36475e14-53f9-48ef-a8e5-dfa7a966b341%5B1%5D.pdf\" target=\"_blank\">ID 2508 MF 2 Corrispettivi LOTTO 2-1.pdf<a><\/li><li><a href=\"\/download-titulus?id=VT6dgIorbbWJUFqHhLhxyQ%3D%3D_001120727-FS_FILES-8849749c-c178-45bd-987b-054659b8e3ce%5B1%5D.pdf\" target=\"_blank\">Ordine omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>05\/10\/2023<\/td><td>04\/10\/2023<\/td><td>2023-UNVACLE-0016020<\/td><td>Provvedimento del Direttore Generale - Affidamento diretto alla ditta Tekn\u00e8 \u2013 Sicurezza e Formazione S.r.l., P. Iva 05683131006, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, del servizio di erogazione di un corso di aggiornamento di informazione e formazione in materia di salute e sicurezza sui luoghi di lavoro, ai sensi dell\u2019art. 37 del D.lgs. n. 81\/2008 e del punto 9 dell\u2019Accordo Stato-Regioni n. 221\/csr del 21 dicembre 2011, rivolto al personale tecnico\u2013amministrativo dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Trattativa Diretta (TD) nell\u2019ambito del Mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A \u2013 CIG Z233C9DEAC<\/td><td><ul><li><a href=\"\/download-titulus?id=ym0BO3nQCapfjG8zC2l4mQ%3D%3D_001121668-FS_FILES-fc5593bb-17ee-4b3e-b3e7-9f2c5bcefa51%5B1%5D.pdf\" target=\"_blank\">PD_Corso aggiornamento ASR.pdf<a><\/li><li><a href=\"\/download-titulus?id=bUrtlOueSDAVpO81eSlrBQ%3D%3D_001121540-FS_FILES-89015f59-15d5-4c1c-8a79-3fb06dfd2420%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=w6sYq80xYXZtY5ETHUGExw%3D%3D_001121414-FS_FILES-550b8ce8-1a76-4428-9435-afab4a5a93ed%5B1%5D.pdf\" target=\"_blank\">Bozza documento di stipula n. 3766133 - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>05\/10\/2023<\/td><td>04\/10\/2023<\/td><td>2023-UNVACLE-0016082<\/td><td>Provvedimento del Direttore Generale - Affidamento al Consorzio Interuniversitario Cineca, P.IVA 00502591209, dell\u2019erogazione di un seminario di formazione denominato \u201cSeminario: Il Modello 770 2023\u201d, erogato in modalit\u00e0 telematica, rivolto ad una dipendente dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, ai sensi dell\u2019art. 7 del D.lgs. n. 36\/2023. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=yOdIF34a14PPqsrUQJnmEA%3D%3D_001121892-FS_FILES-78101c09-684b-46ab-a0e9-31b340e83c2b%5B1%5D.pdf\" target=\"_blank\">PD Seminario 770.pdf<a><\/li><li><a href=\"\/download-titulus?id=q%2BDclTEpQ5gmo460KyB2EA%3D%3D_001121692-FS_FILES-38644bc4-01bb-4f21-8998-495bcf7f4c9a%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=3zVT7yRAgkk23z1u%2FlxPeA%3D%3D_001121671-FS_FILES-55cb2823-82f6-474e-8fb8-45eea293def1%5B1%5D.pdf\" target=\"_blank\">Programma.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>05\/10\/2023<\/td><td>04\/10\/2023<\/td><td>2023-UNVACLE-0016083<\/td><td>Provvedimento del Direttore Generale - Affidamento diretto alla ditta C2 S.r.l., P. Iva 01121130197, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, della fornitura di notebook, borse per trasporto notebook, monitor, tastiere e webcam ad integrazione della dotazione tecnico-informatica dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, a seguito di confronto di preventivi nell\u2019ambito del mercato elettronico della Pubblica Amministrazione (MePA) di Consip S.p.A.\u2013 CIG Z273C31852<\/td><td><ul><li><a href=\"\/download-titulus?id=GfGDe6eAIkhyhb0cZcNnIA%3D%3D_001121893-FS_FILES-7986b6f5-158f-43f5-a90d-0c130644d173%5B1%5D.pdf\" target=\"_blank\">PD_Dot. informatiche.pdf<a><\/li><li><a href=\"\/download-titulus?id=Zdyh6%2FjVVBJzyr9zMzpFtg%3D%3D_001121635-FS_FILES-69d29872-2e38-4d9f-bf21-879fd51b9685%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=om0UhAWMFmSQ%2FQ80Lbvgiw%3D%3D_001121621-FS_FILES-64b18f8d-1cb4-4a08-a260-5524ff71a8f6%5B1%5D.pdf\" target=\"_blank\">Offerta economica C2 Srl.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>12\/10\/2023<\/td><td>11\/10\/2023<\/td><td>2023-UNVACLE-0016421<\/td><td>Fornitura \u201cchiavi in mano\u201d delle dotazioni tecnologico\/informatiche necessarie per l\u2019entrata in funzione del Nuovo Polo Universitario ex Testafochi: contributo di gara ANAC. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=Gukh4N2VBVH%2FyN01idiDcw%3D%3D_001123328-FS_FILES-be3d4b58-2c48-48fa-8a97-cfc453394ed7%5B1%5D.pdf\" target=\"_blank\">PD Autorizzazione contributo ANAC.pdf<a><\/li><li><a href=\"\/download-titulus?id=hCmca7Oeaa7OEcP8%2FT0bSw%3D%3D_001122939-FS_FILES-5495c397-6bca-4e02-8180-6eca0064b1f5%5B1%5D.pdf\" target=\"_blank\">COAN contributo ANAC.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>13\/10\/2023<\/td><td>12\/10\/2023<\/td><td>2023-UNVACLE-0016498<\/td><td>Provvedimento del Direttore Generale - Affidamento al Consorzio Interuniversitario CINECA dei servizi di help desk, consulenza specialistica e sviluppo requisiti ad integrazione dell\u2019ammontare annuale 2023 previsto in convenzione 2022, 2023 e 2024, ai sensi dell\u2019art. 7 del D.lgs. n. 36\/2023. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=k9lX18mCHLTbXrfICY6Pcw%3D%3D_001123648-FS_FILES-3a23554f-3af4-4bc3-b3aa-d34dc288ac56%5B1%5D.pdf\" target=\"_blank\">Provv.to di affidamento servizi integrativi help desk e consulenza specialistica - CINECA.pdf<a><\/li><li><a href=\"\/download-titulus?id=AHgGACI81f31Q6qaf8Az%2Fw%3D%3D_001123172-FS_FILES-7f748fde-bf75-4bc3-b01f-e6e549c614a4%5B3%5D.pdf\" target=\"_blank\">UNIVDA - 23079001 - Ricarica Borsellino 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=jRM%2BfG3U7t4Uuxhn4%2BYkhg%3D%3D_001123647-FS_FILES-5fe8a210-a03a-412b-9104-6b81dc2f939c%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - Anticipata ricarica borsellino CINECA.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>16\/10\/2023<\/td><td>13\/10\/2023<\/td><td>2023-UNVACLE-0016550<\/td><td>Provvedimento del Direttore Generale - Affidamento diretto alla ditta Tekn\u00e8 \u2013 Sicurezza e Formazione S.r.l., P.Iva 05683131006, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, del servizio di erogazione di un corso di aggiornamento di informazione e formazione in materia di salute e sicurezza sui luoghi di lavoro, ai sensi dell\u2019art. 37 del D.lgs. n. 81\/2008 e del punto 9 dell\u2019Accordo Stato-Regioni n. 221\/csr del 21 dicembre 2011, rivolto al personale tecnico-amministrativo dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Trattativa Diretta (TD) nell\u2019ambito del Mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 Integrazione - CIG Z233C9DEAC<\/td><td><ul><li><a href=\"\/download-titulus?id=DaIfwdD1AJgAwmEnfcN2%2Fg%3D%3D_001123827-FS_FILES-290d3470-6ce6-4b1d-ad09-0dd926928995%5B1%5D.pdf\" target=\"_blank\">PD Integrazione IVA Corso aggiornamento.pdf<a><\/li><li><a href=\"\/download-titulus?id=fFjurNbyp8NpBE1XIFKSog%3D%3D_001123817-FS_FILES-aa3c8886-9950-4caf-ba6f-567d6b10397e%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>18\/10\/2023<\/td><td>17\/10\/2023<\/td><td>2023-UNVACLE-0016747<\/td><td>Provvedimento del Direttore Generale - Affidamento diretto al Consorzio Interuniversitario sulla Formazione (Co.In.Fo.), P.IVA 06764560014, ai sensi dell\u2019art. 50 del D.lgs. n. 36\/2023, della fornitura del servizio per la partecipazione di due dipendenti dell\u2019Ufficio Ricerca dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, in modalit\u00e0 telematica, al Seminario Autunnale del progetto ISOIVA-COINFO \u2013 CIG Z273CD33C7<\/td><td><ul><li><a href=\"\/download-titulus?id=qLNEb1HoaLzT7MXVb%2Bm1HQ%3D%3D_001124722-FS_FILES-7e06c568-4e64-4390-9b47-62348e19dc1b%5B1%5D.pdf\" target=\"_blank\">PD_Corso ISOIVA.pdf<a><\/li><li><a href=\"\/download-titulus?id=fjYzDyzCxbCKLdepKbufVg%3D%3D_001124290-FS_FILES-d7865e55-832c-4065-9253-9be47b0dfcdc%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=CnSN7lwlCfN4ZUY8mzLrTw%3D%3D_001124291-FS_FILES-f6b6a340-1e0f-42d7-b04a-774ec71ccf27%5B1%5D.pdf\" target=\"_blank\">Programma Seminario COINFO.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>01\/11\/2023<\/td><td>31\/10\/2023<\/td><td>2023-UNVACLE-0017593<\/td><td>Provvedimento del Direttore Generale - Affidamento alla ditta DM Cultura Srl di Roma dei servizi di hosting, manutenzione ed assistenza ordinaria per la fruizione in modalit\u00e0 SaaS dei servizi della suite Sebina (SebinaNEXT, SebinaYOU, ReteINDACO), per la gestione informatizzata dei servizi della Biblioteca di Ateneo, per il triennio 2024-2026. CIG: Z293C65E2E.<\/td><td><ul><li><a href=\"\/download-titulus?id=adW8Co89aVIIQCSsG7P1AQ%3D%3D_001127815-FS_FILES-5940a3f6-6a3c-4605-9976-535dce6c2f56%5B1%5D.pdf\" target=\"_blank\">PD DM Cultura.pdf<a><\/li><li><a href=\"\/download-titulus?id=2Tidlhy3p4Gqc6zKlxgfqQ%3D%3D_001127816-FS_FILES-19fde040-05bb-446b-9b72-747bfcc3fe66%5B1%5D.pdf.p7m.p7m\" target=\"_blank\">OE_NG3740111_L0_NP875878.pdf.p7m.p7m<a><\/li><\/ul><\/td><\/tr><tr><td>13\/11\/2023<\/td><td>10\/11\/2023<\/td><td>2023-UNVACLE-0018216<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Digital Point di Gasparini Alberto, P.IVA 02170360412, della fornitura di materiale tecnico di consumo, ad integrazione della dotazione tecnico-informatica dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Ordinativo di Esecuzione Immediata nell\u2019ambito del mercato elettronico della Pubblica Amministrazione (Me.Pa) di Consip S.p.A. \u2013 CIG Z683D212CE. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=5PwEx25QfnVQQQD0eYSvTQ%3D%3D_001130312-FS_FILES-ef73a841-6ea7-48a5-a5d6-b3731326ad61%5B1%5D.pdf\" target=\"_blank\">Provvedimento - Digital Point.pdf<a><\/li><li><a href=\"\/download-titulus?id=ANvU1DGE8pXocWZhCr2fPA%3D%3D_001130108-FS_FILES-fcf284e6-51fc-42db-a088-fc7c972a6a81%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=ft1k1SO2i3NsdUxv%2Fk5GCA%3D%3D_001130045-FS_FILES-27535a6f-0c75-4f2e-9728-e0d5e1f057c2%5B2%5D.pdf\" target=\"_blank\">RIEPILOGO FASE_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>16\/11\/2023<\/td><td>15\/11\/2023<\/td><td>2023-UNVACLE-0018516<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Formel S.r.l., P. IVA 01784630814, di un servizio per l\u2019erogazione di un corso di formazione dal titolo \u201cPromuovere le pari opportunit\u00e0: il GEP tra contenuti, struttura e monitoraggio\u201d, destinato a due componenti del Comitato Unico di Garanzia dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG Z783D31123 \u2013 Codice progetto CUG2023<\/td><td><ul><li><a href=\"\/download-titulus?id=OHNMRVk9z6Ma4XrYzhcSHA%3D%3D_001131547-FS_FILES-e4cf5455-b02f-4d69-899f-4cde5230839e%5B1%5D.pdf\" target=\"_blank\">PD Corso CUG.pdf<a><\/li><li><a href=\"\/download-titulus?id=k47Di%2BHdvWs5dlH0r3%2Fs5g%3D%3D_001131124-FS_FILES-fbbcdaac-0786-4d2a-b870-a9e856eb5ed3%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=XvPwFuLZiRz8TOLHKIsnCw%3D%3D_001131125-FS_FILES-d978a590-d089-4550-a792-1a4734453abf%5B1%5D.pdf\" target=\"_blank\">Programma corso 17.11.2023.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>21\/11\/2023<\/td><td>20\/11\/2023<\/td><td>2023-UNVACLE-0018780<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, del servizio di stipula dell\u2019atto integrativo per la partecipazione al Raggruppamento Temporaneo di Imprese nell\u2019ambito del progetto denominato \u201cMontagna Fiorentina Montagna del Benessere\u201d di cui l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u00e8 soggetto partner, in risposta al Bando emanato dalla Regione Toscana, indetto all\u2019interno del Programma di sviluppo Rurale (PSR 2014\/2022) \u00abDiversificazione delle attivit\u00e0 agricole in attivit\u00e0 riguardanti l\u2019assistenza sanitaria, l\u2019integrazione sociale, l\u2019agricoltura sostenuta dalla comunit\u00e0 e l\u2019educazione ambientale e alimentare\u00bb - soggetto proponente: \u00abSociet\u00e0 agricola Torre di Bavecchia SS\u00bb - CUP MASTER D77F23000080007. CUP DERIVATO B77F23000010009 \u2013 CIG Z513D068F7. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=JKFH6ud44mKuF2g2hQRWXQ%3D%3D_001132875-FS_FILES-bcfab605-6223-45bc-b20e-4846ab64af42%5B1%5D.pdf\" target=\"_blank\">Provvedimento Notaio.pdf<a><\/li><li><a href=\"\/download-titulus?id=isRhe%2Bn%2BKmpn6zWTVJ4SZg%3D%3D_001132874-FS_FILES-676e3a0b-aee0-44f9-9ccc-10a7e78713a6%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>22\/11\/2023<\/td><td>21\/11\/2023<\/td><td>2023-UNVACLE-0018882<\/td><td>Provvedimento del Direttore generale - Rinnovo dell\u2019affidamento diretto al raggruppamento temporaneo di imprese tra lo Studio Legale Finocchiaro Formentin Saracco e Associati, P. IVA 06088110017 e lo Studio Legale Balducci-Sommo & Associati P.IVA 01101380077, dei servizi legali a supporto della Direzione Generale di Ateneo, per ulteriori 24 mesi \u2013 CIG Z853865216. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=r%2Fviim%2Fv08wyP11EUgPAPg%3D%3D_001133389-FS_FILES-0ca2e6a6-1715-479a-b60e-42174a68add7%5B1%5D.pdf\" target=\"_blank\">Provvedimento rinnovo servizi legali.pdf<a><\/li><li><a href=\"\/download-titulus?id=TwPIe7Erw%2FXoExJw5gVd8A%3D%3D_001133192-FS_FILES-4bb40d13-e6e9-470d-b1ec-8235621f0021%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>23\/11\/2023<\/td><td>22\/11\/2023<\/td><td>2023-UNVACLE-0018949<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Rekordata S.r.l., P. IVA 05185750014, della fornitura di n. 1 MacBook Air 13\u201d per la nuova Rettrice dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Ordinativo di Esecuzione Immediata nell\u2019ambito del mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 CIG Z8C3D21896.<\/td><td><ul><li><a href=\"\/download-titulus?id=TRoEjVaXxIoX4rpgcCieNA%3D%3D_001130251-FS_FILES-3a3a9fc9-31f4-433c-9807-9230a09e6c7c%5B1%5D.pdf\" target=\"_blank\">Offerta Presentata Rekordata.pdf<a><\/li><li><a href=\"\/download-titulus?id=wR2Oo42us15AHKzIh%2F%2FOtA%3D%3D_001133881-FS_FILES-7029f310-3b00-45db-8585-503ca16453bb%5B1%5D.pdf\" target=\"_blank\">Provvedimento Notebook.pdf<a><\/li><li><a href=\"\/download-titulus?id=ngb8ar9m8%2FVhzN3AzRxCWg%3D%3D_001133649-FS_FILES-da16bca1-f9b7-47b9-9f7f-c29085963da7%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=OkW%2B8gZqQ9Smg9G8z0lxqw%3D%3D_001130250-FS_FILES-cb97f407-29e5-4409-9f9a-35d91de2e1ee%5B2%5D.pdf\" target=\"_blank\">Riepilogo fase_omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>29\/11\/2023<\/td><td>28\/11\/2023<\/td><td>2023-UNVACLE-0019309<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli\n17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta CHIRA TECNOLOGY S.R.L., P.IVA 03461810925, della fornitura di attrezzatura tecnica, finalizzata allo svolgimento delle attivit\u00e0 inerenti il progetto \u201cMEDIA (Museo Emozionale DIgitale multimediale Avanzato)\u201d, in risposta al Bando \u201cAggregazioni R&S\u201d, promosso dall\u2019Assessorato Sviluppo economico, formazione e lavoro  della Regione Autonoma Valle d\u2019Aosta, CUP B19J22001510007 - CIG Z803D1D4A4. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=gRYbJuCeZU0zXChtf5WiBg%3D%3D_001135660-FS_FILES-7b324694-a545-4b11-ba48-b1ff7a0f14dc%5B1%5D.pdf\" target=\"_blank\">Provvedimento - Prof. Pioletti.pdf<a><\/li><li><a href=\"\/download-titulus?id=v2Llb8zKIs9QpTnFlWLQow%3D%3D_001135617-FS_FILES-420da2c0-ca51-4fe8-bb3a-fc9d719e8d38%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=6vN%2BG4629Kv5gs9N1QK1zw%3D%3D_001133654-FS_FILES-481f31a8-d399-41c7-9c2f-d4b484d61303%5B3%5D.pdf\" target=\"_blank\">Riepilogo Fase _omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>01\/12\/2023<\/td><td>30\/11\/2023<\/td><td>2023-UNVACLE-0019469<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Il Mulino S.p.A., P. IVA 00311580377, della fornitura del servizio di abbonamento alla banca dati online \u201cRivisteweb\u201d con la formula \u201cCampus\u201d per l\u2019anno 2024 \u2013 CIG ZAE3D3ACE1. Autorizzazione alla spesa<\/td><td><ul><li><a href=\"\/download-titulus?id=v%2B6SZqZ2lXSVG6uPa7AJTQ%3D%3D_001136243-FS_FILES-3b391f8c-946e-424b-aef2-0351bb717e2e%5B1%5D.pdf\" target=\"_blank\">PD_Il Mulino.pdf<a><\/li><li><a href=\"\/download-titulus?id=s4mRSToSfuP2a5SDEWLN6g%3D%3D_001136048-FS_FILES-f8ac83bd-07bb-408a-b88b-1c271606cfe3%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=JkM%2Fi7fGg6YmirKUUiBEtA%3D%3D_001136030-FS_FILES-b8c0150c-20bc-4478-a045-689078e291e7%5B1%5D.pdf.p7m\" target=\"_blank\">OE_NG3866303_L0_NP1007660.pdf.p7m<a><\/li><\/ul><\/td><\/tr><tr><td>01\/12\/2023<\/td><td>30\/11\/2023<\/td><td>2023-UNVACLE-0019470<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Infobit S.n.c. di Namia B. e Mamoli T., P. Iva 12435450155, della fornitura di n. 1 Monitor, finalizzato allo svolgimento delle attivit\u00e0 inerenti al progetto di ricerca di Ateneo \u201cL\u2019accessibilit\u00e0 dei testi normativi come dispositivo di inclusione: studio di caso e strumenti applicativi in Valle d\u2019Aosta. Prima parte\u201d \u2013 CIG Z293D4BFD7 - CUP B69J21022010007 (codice progetto: MASREV21CRT)<\/td><td><ul><li><a href=\"\/download-titulus?id=fFSC%2FV%2Fu%2B03a8DU22HgEvw%3D%3D_001136244-FS_FILES-5bfb6a7f-eb86-4c80-bbf4-2c8c326e9e52%5B1%5D.pdf\" target=\"_blank\">PD Monitor.pdf<a><\/li><li><a href=\"\/download-titulus?id=8wTKxqfIqH9HXb3CC%2B5SKA%3D%3D_001135715-FS_FILES-52a314b4-6ff0-4542-ba3a-a0917730f77c%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=n1m3FuQahgHmt531xW%2FzTw%3D%3D_001134453-FS_FILES-b3734da6-d5ea-4a7f-93cb-ea1814cb7e3c%5B3%5D.pdf\" target=\"_blank\">Ordinativo n. 7498667 - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>04\/12\/2023<\/td><td>01\/12\/2023<\/td><td>2023-UNVACLE-0019659<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Ebsco Information Services SRL, P.IVA 11164410018, della fornitura del servizio di abbonamento alle banche dati online PsycINFO e PBSC per l\u2019anno 2024 \u2013 CIG Z4B3D18A8C. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=%2FwH55ITz2VqLPeDt3zmsGg%3D%3D_001136988-FS_FILES-1443b9e6-aa56-4210-9c53-3b8588439fa3%5B1%5D.pdf\" target=\"_blank\">Provvedimento Ebsco.pdf<a><\/li><li><a href=\"\/download-titulus?id=bHuYN1FC5Jf3fri0ERQoyw%3D%3D_001136441-FS_FILES-97bb7764-f503-4e34-ae09-5b506f5432d6%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>06\/12\/2023<\/td><td>05\/12\/2023<\/td><td>2023-UNVACLE-0019794<\/td><td>Provvedimento del Direttore Generale - Convenzione Consip Facility Management 4 \u2013 Lotto 2 \u2013 Convenzione per i servizi di pulizia e igiene ambientale, manutenzione impianti, altri servizi operativi e servizi gestionali presso gli immobili adibiti prevalentemente ad uso ufficio delle Pubbliche Amministrazioni e negli immobili delle Istituzioni Universitarie Pubbliche e degli Enti ed Istituti di Ricerca. \nOrdine di attivit\u00e0 cod. FM4L020050-000001 del 28.11.2023. Servizio di manutenzione dell\u2019impianto di riscaldamento ed in particolare delle unit\u00e0 Robur, presso la sede di Saint-Christophe. CIG 56512853E9 \u2013 CIG derivato A015B8BE00.<\/td><td><ul><li><a href=\"\/download-titulus?id=%2FuNGzFd%2FySMzZY6bHX%2BuqQ%3D%3D_001137702-FS_FILES-5b50b619-1db0-4a5e-b906-fda02e3a4eb9%5B1%5D.pdf\" target=\"_blank\">PD facility FM4 2023.pdf<a><\/li><li><a href=\"\/download-titulus?id=Z3t4wtWdI3aNJghjw6RrAw%3D%3D_001137688-FS_FILES-655070a3-5839-431a-9494-06a61472dfae%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>07\/12\/2023<\/td><td>06\/12\/2023<\/td><td>2023-UNVACLE-0019904<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b), del D.lgs. n. 36\/2023, alla ditta Onairz S.r.l.s., P.IVA 01283680070, dei servizi video dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG ZC73D35B60. Autorizzazione alla spesa<\/td><td><ul><li><a href=\"\/download-titulus?id=simWC6IaILlwWl451hZTog%3D%3D_001138224-FS_FILES-7bc90b3e-a0c2-4714-ac86-9b7e8d17dff6%5B1%5D.pdf\" target=\"_blank\">PD_Video 23-24.pdf<a><\/li><li><a href=\"\/download-titulus?id=25vv3AW8bj7MjWuOLD46Tw%3D%3D_001138139-FS_FILES-61b51050-4505-40ce-aa48-d2afd3cfa253%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=VgHQtwGh2eF64vicvJcbfw%3D%3D_001138521-FS_FILES-018a0419-c966-41c1-b8e5-dad02bfd5f9b%5B1%5D.pdf\" target=\"_blank\">Disciplinare videomaker (2)..pdf<a><\/li><\/ul><\/td><\/tr><tr><td>07\/12\/2023<\/td><td>06\/12\/2023<\/td><td>2023-UNVACLE-0019906<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla Ditta Ithaka Harbors Inc. della fornitura del servizio di abbonamento alla banca dati online denominata \u201cJSTOR\u201d ad uso della Biblioteca di Ateneo per l\u2019anno 2024. CIG: Z983CFC1D0. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=eFseugeVofHAPB%2F71u3D2g%3D%3D_001138227-FS_FILES-45ef4550-8732-406c-9fec-aa055d54c5d4%5B1%5D.pdf\" target=\"_blank\">Provvedimento JSTOR.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2BECEkMh3El8zxjNr58cvgg%3D%3D_001137840-FS_FILES-b9f34ee7-297e-4d51-ba9c-21681da73602%5B1%5D.pdf\" target=\"_blank\">Scrittura contabile.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/12\/2023<\/td><td>13\/12\/2023<\/td><td>2023-UNVACLE-0020287<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto alla ditta Perlego Ltd - 138 Holborn, Londra EC1N 2SW, Londra, Regno Unito, P. IVA 246681777, della fornitura di un abbonamento per l\u2019accesso a volumi pubblicati dai principali editori internazionali, a supporto dell\u2019attivit\u00e0 didattica e di ricerca inerente al progetto \u201cNODES \u2013 Nord Ovest Digitale e Sostenibile\u201d, in risposta all\u2019avviso pubblico per la presentazione di Proposte di intervento per la creazione e il rafforzamento di \u201cecosistemi dell\u2019innovazione\u201d, costruzione di \u201cleader territoriali di R&S\u201d \u2013 Ecosistemi dell\u2019Innovazione \u2013 relativo al Piano Nazionale di Ripresa e Resilienza (PNRR), Missione 4 Istruzione e ricerca \u2013 Componente 2 Dalla ricerca all\u2019impresa \u2013 Investimento 1.5, finanziato dall\u2019Unione europea \u2013 NextGenerationEU \u2013 CUP B63B22000010001 \u2013 CIG Z4F3D512A3. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=muuSrqqaCw9XluQbnNwlqA%3D%3D_001139870-FS_FILES-ad842b64-2fd7-4762-97e3-01395487522a%5B1%5D.pdf\" target=\"_blank\">PD_NODES Perlego.pdf<a><\/li><li><a href=\"\/download-titulus?id=J6uTeyHyXmx1Eb03MIBt1Q%3D%3D_001139452-FS_FILES-2da43e0b-0fa9-4bcb-9b32-0e2c3594bfd2%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN - Anticipata.pdf<a><\/li><li><a href=\"\/download-titulus?id=ldNLyFR9oyNbqTkmfP6www%3D%3D_001139451-FS_FILES-a316960b-913f-45cf-a56a-7555a3bed4a8%5B2%5D.pdf\" target=\"_blank\">Bozza contratto Perlego - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/12\/2023<\/td><td>13\/12\/2023<\/td><td>2023-UNVACLE-0020289<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e affidamento diretto, ai sensi degli articolo 17, comma 1, e 50, comma 1, lettera b), del D.lgs. n.36\/2023, alla Ditta CELDES S.r.l., P.IVA 01137991004, e alla Ditta EBSCO Information Services S.r.l., P.Iva 11164410018, rispettivamente della fornitura degli abbonamenti a periodici italiani (Lotto 1) e stranieri (Lotto 2) per la Biblioteca di Ateneo per il periodo 01\/01\/2024 \u2013 31\/12\/2025, rinnovabile per un ulteriore biennio e quindi per il periodo 01\/01\/2026 \u2013 31\/12\/2027, a seguito di RDO nell\u2019ambito del Mercato elettronico della Consip SpA n. 3863658. CIG N. ZB53D67E6E (LOTTO 1 \u2013 Periodici pubblicati da editori italiani) - CIG N. Z5C3D67EF4 (LOTTO 2 - Periodici pubblicati da editori stranieri).<\/td><td><ul><li><a href=\"\/download-titulus?id=NNH5AgLMldoVyTP4FpuVRQ%3D%3D_001139874-FS_FILES-53f10511-a2c2-4e88-a302-b6a50eff34fa%5B1%5D.pdf\" target=\"_blank\">Provvedimento.pdf<a><\/li><li><a href=\"\/download-titulus?id=fFdRSC2OH8CiXRx7kEnImQ%3D%3D_001137845-FS_FILES-f189bba6-82aa-4cee-a748-063e778fb536%5B3%5D.pdf.p7m\" target=\"_blank\">OE_NG3863658_L1_NP1004434_Celdes.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=ivbQOiCy%2BtS9PU8vhZ%2BH0g%3D%3D_001137850-FS_FILES-8a29959d-3e43-4362-8b41-66587569cc51%5B3%5D.pdf\" target=\"_blank\">OE_NG3863658_L2_NP1011371_Ebsco (1).pdf<a><\/li><li><a href=\"\/download-titulus?id=s4MkxeVX%2BQD%2FvVxYHD%2FaTA%3D%3D_001137844-FS_FILES-70cd501c-f59c-42a0-9792-0d293660684d%5B3%5D.p7m\" target=\"_blank\">Dichiarazione_Sostitutiva_Di_Partecipazione_CELDES_S.R.L._T1004434.pdf (1).p7m<a><\/li><li><a href=\"\/download-titulus?id=KMmyQVwFAPz4xuvgZATgfw%3D%3D_001137848-FS_FILES-182db02e-726c-4b7e-8747-27a0384e477e%5B3%5D.pdf\" target=\"_blank\">Dichiarazione sostitutiva di partecipazione_Ebsco.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/12\/2023<\/td><td>13\/12\/2023<\/td><td>2023-UNVACLE-0020290<\/td><td>Provvedimento del Direttore Generale - Sottoscrizione dell\u2019accordo CRUI \u2013 Conferenza dei Rettori delle Universit\u00e0 Italiane e l\u2019Universit\u00e0 della Valle d\u2019Aosta per l\u2019adesione alle trattative di acquisto di beni e servizi informatici per il triennio 2024 \u2013 2026. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=GqDRiPrzf3XBnwyVu32%2BAQ%3D%3D_001139875-FS_FILES-c1c18792-265f-4cd7-8ad8-e5902dbec517%5B1%5D.pdf\" target=\"_blank\">PD CRUI.pdf<a><\/li><li><a href=\"\/download-titulus?id=HCwlCBmgD0okEI4ZHV3Z4A%3D%3D_001132961-FS_FILES-cfe10fc8-6b5c-4967-b704-7d8101662b60%5B2%5D.pdf\" target=\"_blank\">Allegato 1 Relazione sul riparto delle quote di adesione.pdf<a><\/li><li><a href=\"\/download-titulus?id=zcKsEOyouS9ZRZP32Au89w%3D%3D_001132962-FS_FILES-d6f9e0eb-4041-47f6-bacb-ba563252a0dd%5B2%5D.pdf\" target=\"_blank\">Allegato 2 Piano dei fabbisogni 2023-2024vg.pdf<a><\/li><li><a href=\"\/download-titulus?id=aYDfkyNgtbt8FupGrrVILQ%3D%3D_001132963-FS_FILES-1485604b-328f-431e-931d-a2a0db5a4de9%5B2%5D.pdf\" target=\"_blank\">Allegato 3 - Classifica Censis delle Universita Italiane 2023-2024_0.pdf<a><\/li><li><a href=\"\/download-titulus?id=Eci8L1rHLIRnpnelbPQogA%3D%3D_001132960-FS_FILES-86162aad-8b34-450b-bfa4-10d53967c8af%5B3%5D.pdf\" target=\"_blank\">ACCORDO_PER_L'ADESIONE_ALLE_TRATTATIVE_2024_2026 .pdf<a><\/li><\/ul><\/td><\/tr><tr><td>14\/12\/2023<\/td><td>13\/12\/2023<\/td><td>2023-UNVACLE-0020314<\/td><td>Provvedimento del Direttore generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b), del D.lgs. n. 36\/2023, a Infocert S.p.A., P. Iva 07945211006, dei servizi di Certificazione Digitale mediante Trattativa Diretta nell\u2019ambito del Mercato Elettronico della Pubblica Amministrazione \u2013 CIG ZBD3D5BD79. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=dNKmqcJiFUsq5aPvUQdwrA%3D%3D_001139972-FS_FILES-077c1807-4712-4830-a0f4-1d731d7171d2%5B1%5D.pdf\" target=\"_blank\">Provvedimento.pdf<a><\/li><li><a href=\"\/download-titulus?id=7hlKqYxBBZRTVOlW3w4J2w%3D%3D_001135132-FS_FILES-5e09180d-3aca-41a9-91ad-30f92a0d8aba%5B2%5D.pdf.p7m\" target=\"_blank\">OE_NG3857218_L0_NP995870.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=5%2BvEdKKlQUb48r1ws9KgCw%3D%3D_001135133-FS_FILES-fb0ca2ac-1d6d-47ce-af32-3899677c7c7c%5B2%5D.pdf.p7m\" target=\"_blank\">Offerta rinnovo Certificati Firma Remota 2023BIS .pdf.p7m<a><\/li><\/ul><\/td><\/tr><tr><td>14\/12\/2023<\/td><td>13\/12\/2023<\/td><td>2023-UNVACLE-0020315<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b), del D.lgs. n. 36\/2023, alla ditta Noi e gli Altri S.c.s., P.IVA 00442210076, del servizio di ascolto, sostegno e counseling psicologico a supporto della comunit\u00e0 accademica dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste \u2013 CIG Z1B3D2826A. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=E6PQ0OdKPnx6bCYTcrIL3Q%3D%3D_001139976-FS_FILES-3907371f-16ed-4802-a143-62071e29af95%5B1%5D.pdf\" target=\"_blank\">PD_Psicologo.pdf<a><\/li><li><a href=\"\/download-titulus?id=rySKzjOM8O%2FzWvPTtHy3zg%3D%3D_001138671-FS_FILES-034a7c0a-3343-4644-957a-49876040bfd9%5B1%5D.pdf\" target=\"_blank\">Disciplinare counseling psicologico.pdf<a><\/li><li><a href=\"\/download-titulus?id=%2F7N33MDwQbec58Gj4yLCtQ%3D%3D_001138706-FS_FILES-0c7b7f59-1d67-4093-aa08-f2bc1f1cfc30%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>18\/12\/2023<\/td><td>15\/12\/2023<\/td><td>2023-UNVACLE-0020510<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Migaraur S.R.L., P.IVA 16967301009, della fornitura di un notebook inerente al progetto \u201cMONTUR - Monitoraggio realtime e previsione dei flussi Turistici in Valle d\u2019Aosta attraverso sensori distribuiti e strumenti di machine learning e big data\u201d, presentato da KRIA S.r.l., in risposta al bando \u201cAggregazioni R&S\u201d, promosso dall\u2019Assessorato sviluppo economico, formazione e lavoro della Regione Autonoma Valle d\u2019Aosta - CUP B79J22002140007 e un notebook inerente al progetto di ricerca di Ateneo \u201cInterventi e sospensioni della circolazione al Traforo del Monte Bianco: le ricadute sulla Valle d\u2019Aosta\u201d codice progetto ALD23PRA.TMB.SEP. CIG Z6A3D90103. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=BDIpxN4nCxSPOg2gfATXkw%3D%3D_001140757-FS_FILES-519cd15c-2b95-41ef-8c22-2c513be5a4f5%5B1%5D.pdf\" target=\"_blank\">Provvedimento notebook.pdf<a><\/li><li><a href=\"\/download-titulus?id=kG3hhKeVlC%2BZhAYOn8Gdjw%3D%3D_001140563-FS_FILES-0ae4c961-e4fa-4897-a2ad-86c7ed34c742%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN_MONTUR.pdf<a><\/li><li><a href=\"\/download-titulus?id=Fps0iWTYdt8g%2Fg%2BrOcoRyg%3D%3D_001140564-FS_FILES-e86ff546-9c93-44ff-984a-0c1a396ec7fb%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN_TMB.pdf<a><\/li><li><a href=\"\/download-titulus?id=KN34Ti2sWdJZ6Kch1%2BLjJg%3D%3D_001140566-FS_FILES-b9fd6321-9933-426c-91b0-8096e8f2a67d%5B2%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7535567_omissispdf.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>19\/12\/2023<\/td><td>18\/12\/2023<\/td><td>2023-UNVACLE-0020640<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Consis \u2013 Consulenze Sistemistiche S.r.l., P. IVA 00984681007, C.F. 01304330580, della fornitura di n. 1 Workstation e n. 1 Notebook specifici per lo svolgimento delle attivit\u00e0 inerenti il progetto \u201cNODES \u2013 Nord Ovest Digitale e Sostenibile\u201d, in risposta all\u2019avviso pubblico per la presentazione di Proposte di intervento per la creazione e il rafforzamento di \u201cecosistemi dell\u2019innovazione\u201d, costruzione di \u201cleader territoriali di R&S\u201d \u2013 Ecosistemi dell\u2019Innovazione \u2013 relativo al Piano Nazionale di Ripresa e Resilienza (PNRR), Missione 4 Istruzione e ricerca \u2013 Componente 2 Dalla ricerca all\u2019impresa \u2013 Investimento 1.5, finanziato dall\u2019Unione europea \u2013 NextGenerationEU \u2013 CUP B63B22000010001 \u2013 CIG ZD73D878B1<\/td><td><ul><li><a href=\"\/download-titulus?id=vHZUmqotSf%2BKHl7%2BN9POdQ%3D%3D_001141203-FS_FILES-774ec76e-6066-4f9f-b416-160801eac01f%5B1%5D.pdf\" target=\"_blank\">PD_Workstation e PC_PNRR.pdf<a><\/li><li><a href=\"\/download-titulus?id=7YhQJOi1Mqzu4fcUhAYU1A%3D%3D_001140921-FS_FILES-d509e563-a91e-4fd7-84ba-31745a341dd0%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><li><a href=\"\/download-titulus?id=PBbnWcm7UpECBW6RD3fjpw%3D%3D_001140917-FS_FILES-3fbeb063-5ab7-4092-8761-edd7e41963ad%5B2%5D.pdf\" target=\"_blank\">RIEPILOGO_FASE_7549268 - Omissis.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>21\/12\/2023<\/td><td>20\/12\/2023<\/td><td>2023-UNVACLE-0020820<\/td><td>Provvedimento del Direttore Generale - Decisione di contrarre e contestuale affidamento diretto, ai sensi degli articoli 17, comma 1, e 50, comma 1, lettera b, del D.lgs. n. 36\/2023, alla ditta Layup Factory S.n.c., P. Iva 11021620015, della fornitura di gadget personalizzati per l\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante Trattativa Diretta (TD) nell\u2019ambito del Mercato elettronico della Pubblica Amministrazione (Me.Pa.) di Consip S.p.A. \u2013 CIG Z3B3D6E2E4. Autorizzazione alla spesa.<\/td><td><ul><li><a href=\"\/download-titulus?id=VW%2BE5QCkpkl8RdUktL7Mog%3D%3D_001141855-FS_FILES-9614b12a-2ed7-4373-9d9a-93edc36c0b5f%5B1%5D.pdf\" target=\"_blank\">PD_Gadget.pdf<a><\/li><li><a href=\"\/download-titulus?id=ggKTLnVM0sAaPZ0yheLHhQ%3D%3D_001141664-FS_FILES-d26bc29b-7fe7-4922-bdff-ea6521ccdfe4%5B1%5D.pdf.p7m\" target=\"_blank\">OE_NG3891229_L0_NP1036907.pdf.p7m<a><\/li><li><a href=\"\/download-titulus?id=NJqx34qQ1xeVrTz8jL7O0w%3D%3D_001141665-FS_FILES-72d822c9-56e7-4238-957b-c82b8755964b%5B1%5D.pdf\" target=\"_blank\">Preventivo 704 Universit della Valle d Aosta.pdf<a><\/li><li><a href=\"\/download-titulus?id=KMw9Rs%2F6UJG5UJ13HFa1mA%3D%3D_001141765-FS_FILES-f535a2e9-205b-476c-ba87-f49406c4fb60%5B1%5D.pdf\" target=\"_blank\">Scrittura COAN.pdf<a><\/li><\/ul><\/td><\/tr><tr><td>25\/12\/2023<\/td><td>22\/12\/2023<\/td><td>2023-UNVACLE-0021088<\/td><td>Adesione alla Convenzione della Centrale Unica di Committenza di IN.VA. s.p.a. denominata \u201cServizi di Portierato\/Custodia ed altre attivit\u00e0 accessorie rivolti alla Regione Autonoma Valle d\u2019Aosta, agli Enti Locali e tutti gli Enti aderenti alla Centrale Unica di Committenza per servizi e forniture, ad eccezione dell\u2019Azienda USL della Valle d\u2019Aosta - Edizione 1 \u2013 LOTTO 2\u201d per il, per il periodo 1\u00b0 gennaio 2024 \u2013 31 dicembre 2027. CIG master 9906608789 - CIG derivato n. A04285F999<\/td><td><ul><li><a href=\"\/download-titulus?id=B8IupQaATxcENuRv54pEcg%3D%3D_001142803-FS_FILES-b4ace512-9d6b-4500-9cc3-32c4b6da3101%5B1%5D.pdf\" target=\"_blank\">PD_convenzione portierato PlaCe.pdf<a><\/li><li><a href=\"\/download-titulus?id=armvYlHRHcWJP4cC2oL6hQ%3D%3D_001142225-FS_FILES-3b366975-2afc-43f8-a97f-0219eca50d4c%5B2%5D.pdf\" target=\"_blank\">Ordinativo omissis.pdf<a><\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"parent":0,"template":"","tipologie":[530],"class_list":["post-101825","amm-trasparente","type-amm-trasparente","status-publish","hentry","tipologie-2-provvedimenti-di-affidamento"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.univda.it\/en\/wp-json\/wp\/v2\/amm-trasparente\/101825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univda.it\/en\/wp-json\/wp\/v2\/amm-trasparente"}],"about":[{"href":"https:\/\/www.univda.it\/en\/wp-json\/wp\/v2\/types\/amm-trasparente"}],"author":[{"embeddable":true,"href":"https:\/\/www.univda.it\/en\/wp-json\/wp\/v2\/users\/14"}],"version-history":[{"count":1,"href":"https:\/\/www.univda.it\/en\/wp-json\/wp\/v2\/amm-trasparente\/101825\/revisions"}],"predecessor-version":[{"id":101826,"href":"https:\/\/www.univda.it\/en\/wp-json\/wp\/v2\/amm-trasparente\/101825\/revisions\/101826"}],"wp:attachment":[{"href":"https:\/\/www.univda.it\/en\/wp-json\/wp\/v2\/media?parent=101825"}],"wp:term":[{"taxonomy":"tipologie","embeddable":true,"href":"https:\/\/www.univda.it\/en\/wp-json\/wp\/v2\/tipologie?post=101825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}