{"id":99301,"date":"2026-06-24T15:53:41","date_gmt":"2026-06-24T13:53:41","guid":{"rendered":"https:\/\/www.univda.it\/?post_type=amm-trasparente&#038;p=99301"},"modified":"2026-09-01T09:35:31","modified_gmt":"2026-09-01T07:35:31","slug":"1-provvedimenti-a-contrarre","status":"publish","type":"amm-trasparente","link":"https:\/\/www.univda.it\/fr\/amm-trasparente\/1-provvedimenti-a-contrarre\/","title":{"rendered":"1. Provvedimenti a contrarre"},"content":{"rendered":"<h3><strong>Anno 2019<\/strong><\/h3>\n<table id=\"tablePreview\" class=\"table table-bordered\">\n<thead>\n<tr>\n<th>Data pubblicazione<\/th>\n<th>Data protocollo<\/th>\n<th>Repertorio numero<\/th>\n<th>Oggetto<\/th>\n<th>File allegati<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>17\/07\/2019<\/td>\n<td>16\/07\/2019<\/td>\n<td>2019-UNVACLE-0010262<\/td>\n<td>Provvedimento Dirigente Area Finanza e Risorse umane \u2013 Approvazione della procedura di acquisizione, mediante richiesta di formulazione di offerta sulla piattaforma telematica del MePA di Consip S.p.A., del servizio di reception\/portierato e di accoglienza da effettuarsi presso gli edifici in uso all\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, ai sensi dell\u2019articolo 36, comma 2, lettera b), del D.lgs. 18 aprile 2016, n. 50 \u2013 CIG: 7965776E4B<\/td>\n<td>\n<ul>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=%2BncO0Q5jrjGfHPFF4%2Bkr2g%3D%3D_000775315-FS_FILES-0f4fc7fe-a672-4867-98ab-dac543feef96%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Provv reception 2019-2021.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=lzsE7KCOfBKNtqHKZywl0Q%3D%3D_000775316-FS_FILES-05d3e20f-a1f4-441c-9230-2face829375a%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. A \u2013 Modello dichiarazioni.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=T50ZLO7xiDre1z7hLH3WsA%3D%3D_000775317-FS_FILES-7f268b6c-60bf-4e39-8c01-568c3676246c%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. B \u2013 Capitolato tecnico+DUVRI.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=YedywIEgcFvMA4DhsuYqpQ%3D%3D_000775318-FS_FILES-aaec723f-57f0-4a57-a21b-d480ba5a15c1%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. C \u2013 Modello-offerta-tecnica.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=U9LdbsyJ7AKXbyfihcEbZA%3D%3D_000775319-FS_FILES-7a92b333-0026-4cb7-a730-f67ce8b5e7bb%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. D \u2013 Modello offerta economica.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=1QleAuRfiyilaD68lwfQiQ%3D%3D_000775320-FS_FILES-de0b6f89-f3cc-4898-ba86-5c391625d6b8%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. E \u2013 Schema-DGUE.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=M2MJDY9ldAKZjsf2lYcXag%3D%3D_000775321-FS_FILES-e76f9b59-e480-4fc5-8f6e-36980297fc45%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. F \u2013 Modello-attestazione-lodevole.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=diC1GJWB6jZNj3gO40NcEA%3D%3D_000775322-FS_FILES-f58352b6-dbba-4410-a7ea-5b995ae04662%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. G \u2013 Regolamento Studentato Univda.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=teLx8KqCowL5LaiYhWzDdQ%3D%3D_000775323-FS_FILES-3e1e2722-8910-4234-a58b-de4993920a22%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Lettera di invito.pdf<\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>06\/08\/2019<\/td>\n<td>05\/08\/2019<\/td>\n<td>2019-UNVACLE-0011422<\/td>\n<td>Provvedimento Dirigente Area Finanza e Risorse umane \u2013 Approvazione della procedura di acquisizione, previa indagine di mercato, dei servizi di pulizia e disinfezione degli edifici in uso all\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, mediante richiesta di formulazione di offerta sulla piattaforma telematica del MePA di Consip S.p.A ai sensi dell\u2019articolo 36, comma 2, lettera b), del D.lgs. 18 aprile 2016, n. 50 \u2013 CIG: 7997274746<\/td>\n<td>\n<ul>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=ZQ%2F8tSEGWVteAdVOQxg6sw%3D%3D_000779905-FS_FILES-ef49614b-ee14-4ce9-87fa-525332ae1b2c%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">PD indizione gara pulizie 2019-2021.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=5CZ4o2Cv4D3UEzSbd9%2BWDA%3D%3D_000779906-FS_FILES-606def2e-0742-4e7f-be3a-789fc95c262a%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Avviso_Manif. interesse_Pulizie.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=xFL5RV5VKRmzvCSmck6Ftg%3D%3D_000779907-FS_FILES-642fd2f0-97f1-4f28-82b3-cf42e88eb258%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. 1_Modulo Manif. interesse.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=FckZGXbawFmGvNZrWglUiA%3D%3D_000779908-FS_FILES-5d53527f-be56-4033-8ba7-ae542d5c3c87%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Lettera di invito.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=7ORhZPPa2lqdD502VUjMPQ%3D%3D_000779909-FS_FILES-6201471d-75b0-4e82-8fae-d9a03651276f%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Capitolato tecnico.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=aENSQhFk1cl3lqQPdg72KA%3D%3D_000779910-FS_FILES-3d072120-fa67-4a86-8462-b64633fb3165%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. A \u2013 Schema-DGUE.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=0DgA3iuLxwMg4fg7JD0Wyg%3D%3D_000779911-FS_FILES-f4d3f961-d403-4854-b439-604d2fb54aaa%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. B \u2013 Modello offerta tecnico-qualit..pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=RfUHCS7u0EGNkxGubY1Xzg%3D%3D_000779912-FS_FILES-a2d18b49-920b-4fd2-bf93-2b647c703762%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. C- Modello-attestazione-lodevole.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=K0%2Bvsfuhn%2Be%2BTul2Joie4Q%3D%3D_000779913-FS_FILES-6f0cee8a-1b9f-42d2-b4e7-317d379fbc12%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. D \u2013 Costo manodopera.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=sGVUeeuFzrgVjVV4tUVFCw%3D%3D_000779914-FS_FILES-0f6fed74-b940-49af-b7a4-5734372ac3d7%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. E \u2013 Dichiarazione CAM.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=mrVUOtSy5S8W0OMfCcFrAw%3D%3D_000779915-FS_FILES-01d5ebf8-ca2d-4367-a544-2c94ead262fe%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Dich. avvenuto sopralluogo.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=qcK9fix6Rf72A7t8Jry63A%3D%3D_000779916-FS_FILES-7fe2f401-2ea6-4a55-9406-2d27cd8851d6%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">DUVRI.pdf<\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>16\/10\/2019<\/td>\n<td>15\/10\/2019<\/td>\n<td>2019-UNVACLE-0015052<\/td>\n<td>Provvedimento Dirigente Area Finanza e Risorse umane \u2013 Approvazione dell\u2019acquisizione del servizio di Cassa dell\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste. Periodo 01 gennaio 2020 \u2013 31 dicembre 2024. Numero di gara: 7543527 CIG: 8039317E3F<\/td>\n<td>\n<ul>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=f1dgDHcHX8%2BURh0nSlbs%2BQ%3D%3D_000799518-FS_FILES-c799ed62-7e23-47c2-bc2d-45b8245160db%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Provvedimento a contrarre servizio cassa 2020_2024.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=bi8z%2BDo5u5PSxwXBOZE9Gw%3D%3D_000799519-FS_FILES-dd31a1a8-ed8d-4480-93cf-49d212049248%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Convenzione Servizio di Cassa 2020_2024def.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=fl1v613WFPcqa5hxiRwUBQ%3D%3D_000799520-FS_FILES-7249ea01-6ef3-44fe-800d-66c302b65c2b%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Disciplinare_Univda Servizio Cassa.pdf<\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>02\/04\/2019<\/td>\n<td>01\/04\/2019<\/td>\n<td>2019-UNVACLE-0004406<\/td>\n<td>Provvedimento del Dirigente Area Affari Generali \u2013 Acquisizione dell\u2019hardware e del software necessario alla realizzazione dell\u2019infrastruttura di backup da installare presso il Data Center Unico Regionale di INVA S.p.A. tramite indizione di RDO aperta nell\u2019ambito del Mercato Elettronico della Consip S.p.A. \u2013 CIG ZBF27AB8AE<\/td>\n<td>\n<ul>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=agEfDCCE7sNKfoNH55hq5A%3D%3D_000748519-FS_FILES-d0b4ac9d-0f04-4d08-865e-6f47bdc58448%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Determina-InfrastrutturaBackup.pdf <\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><strong>Anno 2020<\/strong><\/h3>\n<table id=\"tablePreview\" class=\"table table-bordered\">\n<thead>\n<tr>\n<th>Data pubblicazione<\/th>\n<th>Data protocollo<\/th>\n<th>Repertorio numero<\/th>\n<th>Oggetto<\/th>\n<th>File allegati<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>22\/09\/2020<\/td>\n<td>21\/09\/2020<\/td>\n<td>2020-UNVACLE-0012462<\/td>\n<td>Provvedimento Dirigente Area Finanza Ricerca e Patrimonio \u2013 Approvazione della procedura di acquisizione, mediante richiesta di formulazione di offerta sulla piattaforma telematica della Centrale Unica di Committenza della Valle d\u2019Aosta di IN.VA S.p.A., del servizio di reception\/portierato e di accoglienza da effettuarsi presso gli edifici in uso all\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste, ai sensi dell\u2019articolo 36, comma 2, lettera b), del D.lgs. 18 aprile 2016, n. 50 \u2013 CIG: 8444014CC7<\/td>\n<td>\n<ul>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=gNUNj4Io4NMGy4luo3%2Bn6w%3D%3D_000880729-FS_FILES-eab23cfe-64fd-4052-9e5f-ca5a9c6476a1%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Provvedimento approvazione procedura.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=RvtggjFcOQ4Jr6%2BnMOZkLA%3D%3D_000880730-FS_FILES-dced911b-58d6-4bfe-aa82-ded925ad48a7%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Avviso pubblico finalizzato all\u2019indagine di mercato .pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=0D5vZ1TGXjWm3mN4jcvtfQ%3D%3D_000880709-FS_FILES-611aa7f5-5134-4f62-9534-1aa88eca616c%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Allegato 1 \u2013 Modulo di manifestazione di interesse.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=AbGlxmqbigWk9eel35vgPA%3D%3D_000880731-FS_FILES-4546b2b7-5c13-46ad-8e10-fc24d1586253%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Lettera di invito.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=oMFZ7cp4ppr0y2sucWdx7w%3D%3D_000880711-FS_FILES-fcc31c71-0afa-4f0e-bb78-ad5b77321c60%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. A \u2013 Modello delle dichiarazioni.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=icHuL%2FnJOxdWMG8gTeTASQ%3D%3D_000880717-FS_FILES-bc2677a9-6907-4898-a725-169d1b8d4abd%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. B \u2013 Capitolato tecnico.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=GAp6Am66jf6nFLnjqji4%2Bg%3D%3D_000880713-FS_FILES-be9121bb-cc20-4de9-a65b-abcfe3bfe077%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. C \u2013 Modello di presentazione dell\u2019offerta tecnico-qualitativa.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=uN69SZFXeehEMUzV%2BuO%2BwA%3D%3D_000880714-FS_FILES-eca00088-89ac-4870-8304-efcb992b898f%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. D \u2013 Modello di presentazione dell\u2019offerta economica.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=N%2FxWyDSvMnRetPrw2SUX7w%3D%3D_000880715-FS_FILES-7b314748-3b31-4d0d-8b94-c6336ade6761%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. E \u2013 Modello di attestazione di lodevole esercizio.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=AZgyJ62GeQd%2Bf61%2BkrTnqA%3D%3D_000775288-FS_FILES-aefc2e44-e2ed-4629-9272-e6cf5fe848f7%5B2%5D.pdf\" target=\"_blank\" rel=\"noopener\">All. F \u2013 Regolamento Studentato Univda.pdf<\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>03\/03\/2020<\/td>\n<td>02\/03\/2020<\/td>\n<td>2020-UNVACLE-0003155<\/td>\n<td>Provvedimento del Direttore generale \u2013 Approvazione della procedura di acquisizione dei servizi di Responsabile della protezione dati (RPD\/DPO) e di supporto all\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste all\u2019adeguamento alla normativa europea sulla protezione dei dati personali mediante richiesta di formulazione di offerta sulla piattaforma telematica del MePA di Consip SpA ai sensi dell\u2019articolo 36 comma 2 lettera a) del decreto legislativo 18 aprile 2016 numero 50 \u2013 CIG Z602961022<\/td>\n<td>\n<ul>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=lb%2Fzx0SKhFHOzLMX98XM%2Fw%3D%3D_000846885-FS_FILES-444a4839-3033-47b4-8f18-c0bee86ed7f6%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Provvedimento<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=9l0nygtW6ZzaLniR1QE%2Fwg%3D%3D_000845972-FS_FILES-a5a40f6f-53c2-4468-b5ce-003fe3812c5a%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Lettera di invito<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=4DeCVHq1XrnwduqoBZu%2F2g%3D%3D_000845967-FS_FILES-499549fe-d9f2-4b75-af30-4cce9c94506b%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Allegato A \u2013 Capitolato tecnico<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=tMwWS2d%2FD6rks3gym52nGQ%3D%3D_000845968-FS_FILES-3cc4ab56-995f-4f6b-a8cc-f631335b4c8d%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Allegato B \u2013 Modello delle dichiarazioni<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=IMLIMBznxhflx9P5GLROEw%3D%3D_000845969-FS_FILES-47a0f24a-169e-44d8-bb01-5d3e7b610de5%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Allegato C \u2013 DGUE<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=8IvNYLk9Atwcq0xMbRiwiw%3D%3D_000845970-FS_FILES-9bff65e3-025c-4d4f-b10a-3e3b3470887f%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Allegato D \u2013 Modello Relazione tecnico-qualitativa<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=QQc0OvwLpwgqPvhh3xvUIA%3D%3D_000845971-FS_FILES-3cf1b466-83c2-4a53-977a-813bf5f32c02%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Allegato E \u2013 Modello Offerta economica<\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><strong>Anno 2021<\/strong><\/h3>\n<table id=\"tablePreview\" class=\"table table-bordered\">\n<thead>\n<tr>\n<th>Data pubblicazione<\/th>\n<th>Data protocollo<\/th>\n<th>Repertorio numero<\/th>\n<th>Oggetto<\/th>\n<th>File allegati<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>23\/02\/2021<\/td>\n<td>22\/02\/2021<\/td>\n<td>2021-UNVACLE-0002716<\/td>\n<td>Provvedimento Dirigente Area Finanza e Patrimonio \u2013 Approvazione della procedura di acquisizione dei servizi di pulizia, disinfezione e sanificazione degli edifici in uso all\u2019Universit\u00e0 della Valle d\u2019Aosta \u2013 Universit\u00e9 de la Vall\u00e9e d\u2019Aoste per anni due, mediante richiesta di formulazione di offerta sulla piattaforma e-procurement della Centrale Unica di Committenza della Regione Autonoma Valle d\u2019Aosta, ai sensi dell\u2019art. 1 co. 2 della Legge n. 120\/2020 \u2013 CIG: 8639569DDE<\/td>\n<td>\n<ul>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=TdsiFvWKJEjUvKdkJ0SaHw%3D%3D_000913711-FS_FILES-a7a615ce-d5dd-4202-9418-7ee43d51d55a%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Provvedimento indizione gara pulizie 2021-2023<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=HzmZZIQ6efQPN7IifO6IWA%3D%3D_000913712-FS_FILES-a5e54583-0290-4fe7-93e9-05d87660451c%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Lettera di invito e informativa privacy per procedure di gara<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=9a%2FuBUUFNFPBE9HFddlQmw%3D%3D_000913693-FS_FILES-21de34ad-97bc-4bb6-bb53-10dd5acee46f%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Capitolato tecnico e planimetrie<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=XYY05BnPfo8N7OZbtSaRqQ%3D%3D_000913694-FS_FILES-508e49cf-9e10-4480-b3bd-fd20ca51216d%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Modello delle dichiarazioni<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=iqyY3yUMX51tJeIm0UWT8g%3D%3D_000913695-FS_FILES-4636e2ba-7a60-4e05-a805-60a84aaa0bb2%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Modello offerta tecnica.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=U2O6FnJwOtKM9s9pM5WlyQ%3D%3D_000913696-FS_FILES-83203bff-bd03-4c57-b8ff-c5f52b5ef25f%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Modello dichiarazione CAM.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=PztHKSTOBLi6OI%2F9NbnaoQ%3D%3D_000913697-FS_FILES-b586b716-1061-432b-8e5e-ce70816ddb1b%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Modello Costo manodopera.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=xRmkXRa2lW7rLDv3GqpFDA%3D%3D_000913698-FS_FILES-e9e3d1df-5f43-4efa-823a-5647fac0f835%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">DUVRI.pdf<\/a><\/li>\n<li><a href=\"https:\/\/www.univda.it\/download-titulus?id=0sTcpZ0qnLxmSyyCJ4Oorg%3D%3D_000913699-FS_FILES-49f382f0-092c-43e3-a311-409c85c04769%5B1%5D.pdf\" target=\"_blank\" rel=\"noopener\">Scrittura contabile_Anac<\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><strong>Anno 2022<\/strong><\/h3>\n<p>Per l\u2019anno 2022 non risultano informazioni da pubblicare.<\/p>\n<h3><strong>Anno 2023<\/strong><\/h3>\n<p>Per l\u2019anno 2023 non risultano informazioni da pubblicare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anno 2019 Data pubblicazione Data protocollo Repertorio numero Oggetto File allegati 17\/07\/2019 16\/07\/2019 2019-UNVACLE-0010262 Provvedimento Dirigente Area Finanza e Risorse umane \u2013 Approvazione della procedura di acquisizione, mediante richiesta di formulazione di offerta sulla piattaforma telematica del MePA di Consip S.p.A., del servizio di reception\/portierato e di accoglienza da effettuarsi presso gli edifici in uso [&hellip;]<\/p>\n","protected":false},"author":1,"parent":0,"template":"","tipologie":[526],"class_list":["post-99301","amm-trasparente","type-amm-trasparente","status-publish","hentry","tipologie-3-delibere-a-contrarre"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.univda.it\/fr\/wp-json\/wp\/v2\/amm-trasparente\/99301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univda.it\/fr\/wp-json\/wp\/v2\/amm-trasparente"}],"about":[{"href":"https:\/\/www.univda.it\/fr\/wp-json\/wp\/v2\/types\/amm-trasparente"}],"author":[{"embeddable":true,"href":"https:\/\/www.univda.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":5,"href":"https:\/\/www.univda.it\/fr\/wp-json\/wp\/v2\/amm-trasparente\/99301\/revisions"}],"predecessor-version":[{"id":101822,"href":"https:\/\/www.univda.it\/fr\/wp-json\/wp\/v2\/amm-trasparente\/99301\/revisions\/101822"}],"wp:attachment":[{"href":"https:\/\/www.univda.it\/fr\/wp-json\/wp\/v2\/media?parent=99301"}],"wp:term":[{"taxonomy":"tipologie","embeddable":true,"href":"https:\/\/www.univda.it\/fr\/wp-json\/wp\/v2\/tipologie?post=99301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}